{"id":11177,"date":"2026-01-08T12:48:07","date_gmt":"2026-01-08T12:48:07","guid":{"rendered":"https:\/\/www.europesays.com\/africa\/11177\/"},"modified":"2026-01-08T12:48:07","modified_gmt":"2026-01-08T12:48:07","slug":"can-2025-lessentiel-de-la-conf-de-david-pagou-avant-maroc-cameroun","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/africa\/11177\/","title":{"rendered":"CAN 2025: l\u2019essentiel de la conf\u2019 de David Pagou avant Maroc-Cameroun"},"content":{"rendered":"<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">David Pagou, s\u00e9lectionneur du Cameroun, \u00e9tait pr\u00e9sent en conf\u00e9rence de presse, ce jeudi 8 janvier \u00e0 la Salle couverte du Complexe Moulay Abdellah de Rabat, \u00e0 la veille du quart de finale de la CAN 2025 entre les Lions indomptables et les Lions de l\u2019Atlas.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abNous sommes fiers d\u2019\u00eatre l\u00e0. Nous sommes focalis\u00e9s. Le Maroc est au top, c\u2019est une immense \u00e9quipe. Le challenge ne sera pas facile, mais nous sommes pr\u00eats \u00e0 le relever. Mes joueurs sont jeunes et veulent inscrire leurs noms dans les pages du football. Soyons patients avec eux\u00bb, a d\u2019abord d\u00e9clar\u00e9 le technicien.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abDans une comp\u00e9tition comme celle-ci, l\u2019infirmerie est toujours visit\u00e9e. Mais il y a des bobos avec lesquels les joueurs peuvent jouer. Nous essayons aussi de les manager sur le c\u00f4t\u00e9 psychologique\u00bb, a affirm\u00e9 le technicien au sujet des bless\u00e9s.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abNous ne sommes pas toujours satisfaits. Nous avons toujours le souci d\u2019atteindre la perfection. Mais il y a beaucoup de segments \u00e0 travailler sur les plans offensif et d\u00e9fensif. Nous avons des joueurs matures qui ont fait ce qu\u2019il fallait pour nous rassurer\u00bb, a-t-il ajout\u00e9 au sujet de la profondeur de banc du Cameroun.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abC\u2019est un quart de finale face au pays organisateur, qui a des individualit\u00e9s tr\u00e8s fortes et un collectif performant. Le Maroc n\u2019a pas perdu depuis tr\u00e8s longtemps \u00e0 domicile. C\u2019est une motivation suppl\u00e9mentaire. Ce sera au mental\u00bb, a poursuivi le technicien au sujet des Lions de l\u2019Atlas.<\/p>\n<p lang=\"fr\" dir=\"ltr\">\ud83c\udde8\ud83c\uddf2\ud83d\udcac David Pagou : \u00ab On joue le pays organisateur, une grosse \u00e9quipe [\u2026] Je ne suis pas historien, mais \u00e7a fait tr\u00e8s longtemps que le Maroc \ud83c\uddf2\ud83c\udde6 n\u2019a pas perdu \u00e0 domicile. Ce sera une motivation suppl\u00e9mentaire. \u00bb <a href=\"https:\/\/t.co\/rZUwklnyCh\" rel=\"nofollow\">pic.twitter.com\/rZUwklnyCh<\/a><\/p>\n<p>\u2014 Le360 (@Le360fr) <a href=\"https:\/\/twitter.com\/Le360fr\/status\/2009215265117020556?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">January 8, 2026<\/a><\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abMbeumo est le genre de joueur qui a besoin d\u2019\u00eatre bouscul\u00e9 de temps en temps pour qu\u2019il s\u2019exprime, surtout dans le vestiaire. Je voulais qu\u2019il soit une locomotive dans ce groupe et il prend bien ce r\u00f4le. Il a un r\u00f4le pr\u00e9pond\u00e9rant dans l\u2019effectif\u00bb, a-t-il affirm\u00e9 au sujet du joueur de Manchester United, vedette des Lions indomptables.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abLe pass\u00e9 ne garantit pas l\u2019avenir. Surtout en football. Vous pouvez \u00eatre tr\u00e8s performant hier et \u00eatre un flop aujourd\u2019hui. Les confrontations entre les deux nations font partie du pass\u00e9. Le Maroc, ce pays ami et fr\u00e8re, est le favori naturel. Demi-finaliste d\u2019une Coupe du Monde. Ce sera un match tr\u00e8s difficile contre une tr\u00e8s bonne \u00e9quipe. On va essayer de les challenger\u00bb, a-t-il ajout\u00e9. Avant de poursuivre: \u00abce qui caract\u00e9rise le Camerounais, c\u2019est son courage. M\u00eame s\u2019il y a une montagne en face. C\u2019est le mental qui fait la diff\u00e9rence\u00bb.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abLe Maroc va mieux se pr\u00e9parer pour nous damer le pion. Nous sommes dans notre bulle et tous nos joueurs sont jeunes. Il n\u2019\u00e9tait pas n\u00e9s en 1988. Le Maroc a de tr\u00e8s grands footballeurs, le Ballon d\u2019Or 2025 est Achraf Hakimi. Le stade sera plein, mais nous entendrons plus les cris des Camerounais (rires)\u00bb, ajoute-t-il.<\/p>\n<p lang=\"fr\" dir=\"ltr\">\ud83c\udde8\ud83c\uddf2\ud83d\udcac David Pagou : \u00ab Le Maroc est le favori naturel \ud83c\uddf2\ud83c\udde6, demi-finaliste de la Coupe du monde. On ne dira jamais ici que le Cameroun est favori. Ce sera un match difficile. \u00bb <a href=\"https:\/\/t.co\/7GteCA1Xxt\" rel=\"nofollow\">pic.twitter.com\/7GteCA1Xxt<\/a><\/p>\n<p>\u2014 Le360 (@Le360fr) <a href=\"https:\/\/twitter.com\/Le360fr\/status\/2009217219406807502?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">January 8, 2026<\/a><\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abNous sommes l\u00e0 pour manager nos joueurs sur le terrain, l\u2019arbitre est l\u00e0 pour diriger la partie\u00bb, affirme-t-il au sujet de l\u2019arbitrage.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">\u00abJe ne peux pas me comparer \u00e0 Walid Regragui. Je commence et il a fait une demi-finale de Coupe du Monde et rend fiers les entra\u00eeneurs africains\u00bb, a ajout\u00e9 le technicien.<\/p>\n<p class=\"default__StyledText-sc-10mj2vp-0 CxBBS body-paragraph\">Christian Kofane \u00e9tait pr\u00e9sent \u00e0 ses c\u00f4t\u00e9s: \u00abc\u2019est une des plus belle comp\u00e9tition d\u2018Afrique. J\u2019essaye de profiter du moment. C\u2019est un r\u00eave qui devient r\u00e9alit\u00e9. Nous nous sommes bien pr\u00e9par\u00e9s. Nous savons que ce sera un match difficile\u00bb.<\/p>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"David Pagou, s\u00e9lectionneur du Cameroun, \u00e9tait pr\u00e9sent en conf\u00e9rence de presse, ce jeudi 8 janvier \u00e0 la Salle&hellip;\n","protected":false},"author":2,"featured_media":11178,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[381,179,2490,158],"class_list":{"0":"post-11177","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-maroc","8":"tag-cameroun","9":"tag-can-2025","10":"tag-coupe-d-afrique-des-nations","11":"tag-maroc"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/11177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/comments?post=11177"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/11177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media\/11178"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media?parent=11177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/categories?post=11177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/tags?post=11177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}