{"id":15292,"date":"2026-01-10T13:46:08","date_gmt":"2026-01-10T13:46:08","guid":{"rendered":"https:\/\/www.europesays.com\/africa\/15292\/"},"modified":"2026-01-10T13:46:08","modified_gmt":"2026-01-10T13:46:08","slug":"trois-hommes-en-garde-a-vue-apres-avoir-tire-des-fusees-apres-la-victoire-du-maroc-contre-le-cameroun","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/africa\/15292\/","title":{"rendered":"Trois hommes en garde \u00e0 vue apr\u00e8s avoir tir\u00e9 des fus\u00e9es apr\u00e8s la victoire du Maroc contre le Cameroun"},"content":{"rendered":"<p>\n                                                                Trois individus sont suspect\u00e9s d\u2019avoir tir\u00e9 des mortiers en direction de policiers vendredi soir \u00e0 Pissevin. Les CRS sont intervenus.\n                            <\/p>\n<p>En marge de la victoire du Maroc contre le Cameroun (2-0) dans le cadre du match de football de la coupe d\u2019Afrique des Nations (CAN), des jeunes gens de Pissevin ont lanc\u00e9 des fus\u00e9es pour c\u00e9l\u00e9brer l\u2019issue du match. Des policiers sont intervenus sur place et notamment des CRS qui ont \u00e9t\u00e9 d\u00e9p\u00each\u00e9s pour contenir les d\u00e9bordements des supporters de l\u2019\u00e9quipe marocaine.<\/p>\n<p>Suspect\u00e9s de violences sur des policiers<\/p>\n<p>Trois individus suspect\u00e9s d\u2019avoir tir\u00e9 des fus\u00e9es en direction des policiers ont \u00e9t\u00e9 interpell\u00e9s pour ce comportement dangereux. Ils ont \u00e9t\u00e9 plac\u00e9s en garde \u00e0 vue pour violences sur personne d\u00e9positaire de l\u2019autorit\u00e9 publique.<\/p>\n","protected":false},"excerpt":{"rendered":"Trois individus sont suspect\u00e9s d\u2019avoir tir\u00e9 des mortiers en direction de policiers vendredi soir \u00e0 Pissevin. Les CRS&hellip;\n","protected":false},"author":2,"featured_media":15293,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[1601,10046,158,10047],"class_list":{"0":"post-15292","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-maroc","8":"tag-faits-divers","9":"tag-gard","10":"tag-maroc","11":"tag-nimes"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/15292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/comments?post=15292"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/15292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media\/15293"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media?parent=15292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/categories?post=15292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/tags?post=15292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}