{"id":17051,"date":"2026-01-11T12:52:06","date_gmt":"2026-01-11T12:52:06","guid":{"rendered":"https:\/\/www.europesays.com\/africa\/17051\/"},"modified":"2026-01-11T12:52:06","modified_gmt":"2026-01-11T12:52:06","slug":"a-quelle-heure-et-sur-quelle-chaine-regarder-les-demi-finales-de-la-coupe-dafrique-des-nations","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/africa\/17051\/","title":{"rendered":"\u00e0 quelle heure et sur quelle cha\u00eene regarder les demi-finales de la Coupe d&#8217;Afrique des Nations\u00a0?"},"content":{"rendered":"<p>                    Par<\/p>\n<p>            <a href=\"https:\/\/actu.fr\/auteur\/anne-laure-petit-henon\" title=\"Consulter tous les articles de Anne-Laure Petit-H\u00e9non\" rel=\"nofollow noopener\" target=\"_blank\">Anne-Laure Petit-H\u00e9non<\/a><\/p>\n<p>        Publi\u00e9 le<\/p>\n<p>            11 janv. 2026 \u00e0 13h26        <\/p>\n<p>Alors que la<a href=\"https:\/\/actu.fr\/sports\/football\/karim-benzema-se-verrait-bien-au-mondial-2026-son-retour-en-equipe-de-france-est-il-possible_63568241.html\" rel=\"nofollow noopener\" target=\"_blank\"> Coupe du monde<\/a> de football d\u00e9butera dans quelques mois, en juin\u00a02026, la <a href=\"https:\/\/actu.fr\/sports\/football\/can-2026-sur-quelle-chaine-regarder-l-integralite-de-la-coupe-d-afrique-des-nations-qui-debute-ce-dimanche_63588237.html\" rel=\"nofollow noopener\" target=\"_blank\">Coupe d\u2019Afrique des Nations<\/a> offre un avant-go\u00fbt avant la comp\u00e9tition ultime qui se d\u00e9roulera entre les \u00c9tats-Unis, le Mexique et le Canada.<\/p>\n<p class=\" wall-content\">D\u00e9but\u00e9e en d\u00e9cembre\u00a02025, la CAN touche \u00e0 sa fin en ce d\u00e9but d\u2019ann\u00e9e. Samedi 10\u00a0janvier 2026, les derniers quarts de finale ont \u00e9t\u00e9 jou\u00e9s et maintenant, on connait les \u00e9quipes qui forment le carr\u00e9 final.<\/p>\n<p>L\u2019Alg\u00e9rie, grande absente<\/p>\n<p class=\" wall-content\">On aurait pu croire \u00e0 un choc Alg\u00e9rie-Maroc en demi, mais il n\u2019aura pas lieu. Les Fennecs se sont fait lourdement \u00e9liminer par le Nigeria, 2-0.<\/p>\n<p class=\" wall-content\">Qui donc retrouvera le Maroc, pays h\u00f4te de la CAN et vainqueur en quart face au Cameroun, 2-0 \u00e9galement.<\/p>\n<p class=\" wall-content\">La deuxi\u00e8me affiche verra s\u2019opposer le S\u00e9n\u00e9gal \u00e0 l\u2019\u00c9gypte, qui a \u00e9limin\u00e9 les tenants du titre, les \u00c9l\u00e9phants de C\u00f4te d\u2019Ivoire (3-2).<\/p>\n<p>Deux matchs le m\u00eame jour<\/p>\n<p class=\" wall-content\">Il faudra \u00eatre un tout petit peu patient avant de pouvoir suivre ces deux rencontres, car elles auront lieu mercredi 14\u00a0janvier 2026.<\/p>\n<p>Votre r\u00e9gion, votre actu !<\/p>\n<p>Recevez chaque jour les infos qui comptent pour vous.<\/p>\n<p>\t<a href=\"https:\/\/actu.fr\/newsletter\" class=\"ac-btn ac-btn--corner ac-btn--medium ac-btn--blue800\" rel=\"nofollow noopener\" target=\"_blank\">S&#8217;incrire<\/a><\/p>\n<p class=\" wall-content\">La premi\u00e8re, S\u00e9n\u00e9gal-\u00c9gypte, aura lieu \u00e0 18\u00a0heures. Nigeria-Maroc se jouera \u00e0 partir de 21\u00a0heures.<\/p>\n<p class=\" wall-content\">Parmi ces quatre \u00e9quipes se trouve le futur vainqueur de la CAN 2026. Mais pour savoir cela, il faudra patienter jusqu\u2019\u00e0 la finale, dimanche 18\u00a0janvier 2026.<\/p>\n<p>Pas de diffusion en clair<\/p>\n<p class=\" wall-content\">En revanche, si vous voulez suivre la fin de la comp\u00e9tition, il va falloir passer par la case paiement. En effet, la CAN n\u2019est pas diffus\u00e9e en clair en France.<\/p>\n<p class=\" wall-content\">C\u2019est la cha\u00eene beIN, sp\u00e9cialis\u00e9e dans le sport, qui a r\u00e9cup\u00e9r\u00e9 les droits. Il vous faudra prendre un a<a href=\"https:\/\/boutique.canalplus.com\/sport\/coupe-afrique-des-nations-2025\" rel=\"nofollow noopener\" target=\"_blank\">bonnement via Canal +<\/a>\u00a0pour regarder les matchs du dernier carr\u00e9.<\/p>\n<p class=\" wall-content\">Personnalisez votre actualit\u00e9 en ajoutant vos villes et m\u00e9dias en favori avec <a href=\"https:\/\/moncompte.actu.fr\" title=\"D\u00e9couvez Mon Actu\" rel=\"nofollow noopener\" data-trk=\"{&quot;cta&quot;:{&quot;action&quot;:&quot;https:\\\/\\\/moncompte.actu.fr&quot;,&quot;category&quot;:&quot;mon compte&quot;,&quot;from&quot;:&quot;article footer&quot;,&quot;name&quot;:&quot;Mon actu&quot;,&quot;type&quot;:&quot;cta&quot;}}\" target=\"_blank\">Mon Actu<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Par Anne-Laure Petit-H\u00e9non Publi\u00e9 le 11 janv. 2026 \u00e0 13h26 Alors que la Coupe du monde de football&hellip;\n","protected":false},"author":2,"featured_media":17052,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[64,311,264],"class_list":{"0":"post-17051","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-afrique","9":"tag-football","10":"tag-sports"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/17051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/comments?post=17051"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/posts\/17051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media\/17052"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/media?parent=17051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/categories?post=17051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/africa\/wp-json\/wp\/v2\/tags?post=17051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}