{"id":1698,"date":"2026-04-18T18:32:26","date_gmt":"2026-04-18T18:32:26","guid":{"rendered":"https:\/\/www.europesays.com\/afrika\/1698\/"},"modified":"2026-04-18T18:32:26","modified_gmt":"2026-04-18T18:32:26","slug":"irw-news-global-li-ion-graphite-madagaskar-hebt-16-jaehrige-aussetzung-der-erteilung-von-bergbaugenehmigungen-auf-ein-bedeutender-fortschritt-fuer-das-graphitprojekt-ambato-arana-von-lion","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrika\/1698\/","title":{"rendered":"IRW-News: Global Li-Ion Graphite: Madagaskar hebt 16-j\u00e4hrige Aussetzung der Erteilung von Bergbaugenehmigungen auf: Ein bedeutender Fortschritt f\u00fcr das Graphitprojekt Ambato Arana von LION"},"content":{"rendered":"<p>                        IRW-PRESS: <a href=\"https:\/\/www.boerse.de\/aktien\/GLOBAL-LI-ION-GRAPH-Aktie\/CA37956H1082\" rel=\"nofollow noopener\" target=\"_blank\">Global Li-Ion<\/a> Graphite: Madagaskar hebt 16-j\u00e4hrige Aussetzung der Erteilung von Bergbaugenehmigungen auf: Ein bedeutender Fortschritt f\u00fcr das Graphitprojekt Ambato Arana von LION<\/p>\n<p>Vancouver, British Columbia, Kanada (12. Februar 2026) \/ IRW-Press \/ Global Li-Ion Graphite Corp. (<a href=\"https:\/\/www.boerse.de\/aktien\/GLOBAL-LI-ION-GRAPH-Aktie\/CA37956H1082\" rel=\"nofollow noopener\" target=\"_blank\">Global Li-Ion<\/a> oder das Unternehmen) (CSE: LION) m\u00f6chte diese Gelegenheit nutzen, um seine Aktion\u00e4re und interessierten Parteien \u00fcber den aktuellen Stand zu informieren. Das Unternehmen begr\u00fc\u00dft die Ank\u00fcndigung von Carl Andriamparany, Minister f\u00fcr Bergbau und strategische Ressourcen von Madagaskar, dass Madagaskar seine 16-j\u00e4hrige Aussetzung der Erteilung von Bergbaugenehmigungen (mit Ausnahme von Goldabbau-Genehmigungen) aufgehoben hat.<\/p>\n<p><a href=\"https:\/\/www.boerse.de\/boersennewsletter\/?linknr=85331\" rel=\"nofollow noopener\" target=\"_blank\">boerse.de-Aktien-Ausblick:<br \/>Wie es an den B\u00f6rsen jetzt weitergeht!<br \/>Hier gratis anfordern &#8230;<\/a> <\/p>\n<p>Laut lokalen Medien basiert das neue System f\u00fcr die Erteilung von Genehmigungen auf mehreren Mechanismen, darunter: Lizenzgenehmigungen f\u00fcr kleine Betreiber, Ausschreibungen f\u00fcr Industrieprojekte und die Einbeziehung der Bergbaubrigade (Regulierungs-\/Polizeieinheit, die den Bergbau \u00fcberwacht und die Gesetze in diesem Sektor durchsetzt) bei der Pr\u00fcfung von Antr\u00e4gen.<\/p>\n<p>Madagaskar verf\u00fcgt \u00fcber bedeutende Bodensch\u00e4tze, insbesondere Nickel, Kobalt und Graphit, die im Zusammenhang mit der globalen Energiewende als strategische Mineralien gelten. Laut dem letzten Bericht, der Ende 2025 im Rahmen der Extractive Industries Transparency Initiative ver\u00f6ffentlicht wurde, standen im Jahr 2023 die Genehmigungen f\u00fcr 1.650 Bergbauantr\u00e4ge noch aus.<\/p>\n<p>Der Chairman Jason Walsh kommentierte: Dies ist ein wichtiger Schritt nach vorne f\u00fcr die Bergbauindustrie in Madagaskar, da es ausl\u00e4ndischem Kapital erm\u00f6glicht, mit Zuversicht in Bergbauprojekte wie die Graphitmine Ambato Arana von <a href=\"https:\/\/www.boerse.de\/aktien\/GLOBAL-LI-ION-GRAPH-Aktie\/CA37956H1082\" rel=\"nofollow noopener\" target=\"_blank\">Global Li-Ion<\/a> zu investieren.<\/p>\n<p>\u00dcber die Graphitmine Ambato-Arana in Madagaskar <\/p>\n<p>Die 3 vierzig Jahre geltenden Bergbaulizenzen des Projekts umfassen insgesamt 4.375 Hektar (10.811 Acres) und liegen in der N\u00e4he von Andasibe in der Provinz Toamasina in Madagaskar, 20 km s\u00fcdwestlich von Sheritts gro\u00dffl\u00e4chigem Nickel\/Kobalt\/Laterit-Tagebau auf Ambatovy und 15 km nord\u00f6stlich der Stadt Moramanga. Von dort aus besteht \u00fcber den nationalen Highway RN2 eine Verbindung zur Hauptstadt Antananarivo (114 km) und zu Madagaskars Haupthafen Toamasina (Tamatave) (240 km). Auf den Lizenzen wurde ab 1910 etwa ein Jahrhundert lang Graphit in bescheidenem Umfang produziert, was auf die auf den Lizenzgebieten angewandte Technologie zur\u00fcckzuf\u00fchren ist. Die Produktion wurde von den vorherigen Eigent\u00fcmern aufgrund des damaligen Einbruchs der globalen Graphitm\u00e4rkte und der nur teilweise abgebauten Lagerst\u00e4tten eingestellt. Die Lagerst\u00e4tten wurden teilweise abgebaut und stehen nun f\u00fcr den Abbau in gr\u00f6\u00dferem Stil mit modernen Produktionstechniken zur Verf\u00fcgung. Sie liegen in den Graphithorizonten der \u00e4u\u00dferst aussichtsreichen Manampotsy-Formation und werden mit topographischen Erhebungen assoziiert, die \u00fcber free-digging von Lateriterz und im Tagebau abgebaut werden k\u00f6nnen, was kosteneffektiver ist und keine Sprengungen erfordert. Die Graphitmineralisierung auf dem Projektgebiet scheint in gut definierten Nord-S\u00fcd-G\u00fcrteln mit eingebetteten graphitreichen, br\u00fcchigen Schichten zu liegen. Die geologischen Schichten, die von Interesse sind, sind \u00fcber mehrere Kilometer kontinuierlich und weisen einen geringen Neigungswinkel auf. Die Probendaten deuten auf einen guten Gehalt (bis zu 10 % Kohlenstoffgehalt bei einigen Proben bis zu fast 14 %) und gro\u00dfe Flocken (Jumbo-Gr\u00f6\u00dfe) hin, die mit anderen nahegelegenen Minen \u00fcbereinstimmen, z. B. Gallois (Elate Graphite), Sahamamy &amp; Vatomina (Tirupati Graphite) und DNI Metals Vohitsara (DNI Metals).<\/p>\n<p>Weitere Informationen zu <a href=\"https:\/\/www.boerse.de\/aktien\/GLOBAL-LI-ION-GRAPH-Aktie\/CA37956H1082\" rel=\"nofollow noopener\" target=\"_blank\">Global Li-Ion<\/a> finden Sie unter dem Firmenprofil auf der SEDAR-Webseite (www.sedar.com), auf der Webseite der CSE (www.thecse.com) und auf der Firmenwebseite (www.globalli-iongraphite.com). <\/p>\n<p>Weitere Informationen zum Unternehmen erhalten Sie \u00fcber:<\/p>\n<p>Jason Walsh<\/p>\n<p>Global Li-Ion Graphite Corp.<\/p>\n<p>Tel: 604.608.6314<\/p>\n<p>E-Mail: <a href=\"https:\/\/www.boerse.de\/cdn-cgi\/l\/email-protection\" class=\"__cf_email__\" data-cfemail=\"422b2c242d022e2b2d2c253023322a2b36276c212d2f\" rel=\"nofollow noopener\" target=\"_blank\">[email\u00a0protected]<\/a> <\/p>\n<p>Die Canadian Securities Exchange und ihre Regulierungsorgane haben die Angemessenheit bzw. Genauigkeit dieser Meldung nicht gepr\u00fcft und \u00fcbernehmen diesbez\u00fcglich keine Verantwortung.<\/p>\n<p>Zukunftsgerichtete Informationen:<\/p>\n<p>Diese Pressemitteilung enth\u00e4lt zukunftsgerichtete Aussagen. Mit der Verwendung von Ausdr\u00fccken wie prognostizieren, fortsetzen, sch\u00e4tzen, erwarten, k\u00f6nnen, werden, planen, beabsichtigen, glauben und \u00e4hnlichen Ausdr\u00fccken soll auf zukunftsgerichtete Aussagen hingewiesen werden. Obwohl das Unternehmen der Ansicht ist, dass die Erwartungen und Annahmen, auf denen solche zukunftsgerichteten Aussagen beruhen, angemessen sind, sollten solche zukunftsgerichteten Aussagen nicht \u00fcberbewertet werden, da das Unternehmen nicht garantieren kann, dass sich diese als richtig erweisen werden. Da sich zukunftsgerichtete Aussagen auf zuk\u00fcnftige Ereignisse und Umst\u00e4nde beziehen, sind sie typischerweise Risiken und Unsicherheiten unterworfen. Diese Aussagen wurden unter Bezugnahme auf den Zeitpunkt der Erstellung dieser Pressemitteilung get\u00e4tigt. Aufgrund verschiedener Faktoren und Risiken, die im Lagebericht des Unternehmens (Managements Discussion &amp; Analysis) beschrieben sind und unter dem Unternehmensprofil auf www.sedar.com ver\u00f6ffentlicht wurden, k\u00f6nnen sich die tats\u00e4chlichen Ergebnisse erheblich von den derzeit erwarteten Ergebnissen unterscheiden. Auch wenn das Unternehmen dies beschlie\u00dfen k\u00f6nnte, ist zu keinem Zeitpunkt eine Aktualisierung dieser Informationen vorgesehen.<\/p>\n<p>Diese Pressemitteilung stellt weder ein Angebot zum Verkauf noch eine Aufforderung zum Kauf von Wertpapieren in den Vereinigten Staaten dar. Die Wertpapiere wurden und werden nicht gem\u00e4\u00df dem United States Securities Act von 1933 in der jeweils g\u00fcltigen Fassung (der U.S. Securities Act) oder den Wertpapiergesetzen der einzelnen Bundesstaaten registriert und d\u00fcrfen in den Vereinigten Staaten weder angeboten noch verkauft werden, es sei denn, sie sind gem\u00e4\u00df dem U.S. Securities Act und den anwendbaren Wertpapiergesetzen der einzelnen Bundesstaaten registriert oder es liegt eine Ausnahme von dieser Registrierung vor.<\/p>\n<p>Hinweis\/Disclaimer zur \u00dcbersetzung (inkl. KI-Unterst\u00fctzung): Die Originalmeldung in der Ausgangssprache (in der Regel Englisch) ist die einzige ma\u00dfgebliche, autorisierte und rechtsverbindliche Fassung. Diese deutschsprachige \u00dcbersetzung\/Zusammenfassung dient ausschlie\u00dflich der leichteren Verst\u00e4ndlichkeit und kann gek\u00fcrzt oder redaktionell verdichtet sein. Die \u00dcbersetzung kann ganz oder teilweise mithilfe maschineller \u00dcbersetzung bzw. generativer KI (Large Language Models) erfolgt sein und wurde redaktionell gepr\u00fcft; trotzdem k\u00f6nnen Fehler, Auslassungen oder Sinnverschiebungen auftreten. Es wird keine Gew\u00e4hr f\u00fcr Richtigkeit, Vollst\u00e4ndigkeit, Aktualit\u00e4t oder Angemessenheit \u00fcbernommen; Haftungsanspr\u00fcche sind ausgeschlossen (auch bei Fahrl\u00e4ssigkeit), ma\u00dfgeblich ist stets die Originalfassung. Diese Mitteilung stellt weder eine Kauf- noch eine Verkaufsempfehlung dar und ersetzt keine rechtliche, steuerliche oder finanzielle Beratung. Bitte beachten Sie die englische Originalmeldung bzw. die offiziellen Unterlagen auf www.sedarplus.ca, www.sec.gov, www.asx.com.au oder auf der Website des Emittenten; bei Abweichungen gilt ausschlie\u00dflich das Original.<\/p>\n<p>Die englische Originalmeldung finden Sie unter folgendem Link: <\/p>\n<p>https:\/\/www.irw-press.at\/press_html.aspx?messageID=82985<\/p>\n<p>Die \u00fcbersetzte Meldung finden Sie unter folgendem Link: <\/p>\n<p>https:\/\/www.irw-press.at\/press_html.aspx?messageID=82985&#038;tr=1<\/p>\n<p>NEWSLETTER REGISTRIERUNG: <\/p>\n<p>Aktuelle Pressemeldungen dieses Unternehmens direkt in Ihr Postfach: <\/p>\n<p>http:\/\/www.irw-press.com\/alert_subscription.php?lang=de&#038;isin=CA37956H1082<\/p>\n<p>Mitteilung \u00fcbermittelt durch IRW-Press.com. F\u00fcr den Inhalt ist der Aussender verantwortlich.<\/p>\n<p>Kostenloser Abdruck mit Quellenangabe erlaubt.<\/p>\n<p>Quelle: dpa-AFX<\/p>\n","protected":false},"excerpt":{"rendered":"IRW-PRESS: Global Li-Ion Graphite: Madagaskar hebt 16-j\u00e4hrige Aussetzung der Erteilung von Bergbaugenehmigungen auf: Ein bedeutender Fortschritt f\u00fcr das&hellip;\n","protected":false},"author":2,"featured_media":1699,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[245],"tags":[380,379],"class_list":{"0":"post-1698","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-madagaskar","8":"tag-madagascar","9":"tag-madagaskar"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/1698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/comments?post=1698"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/1698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media\/1699"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media?parent=1698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/categories?post=1698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/tags?post=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}