{"id":1769,"date":"2026-04-18T19:16:56","date_gmt":"2026-04-18T19:16:56","guid":{"rendered":"https:\/\/www.europesays.com\/afrika\/1769\/"},"modified":"2026-04-18T19:16:56","modified_gmt":"2026-04-18T19:16:56","slug":"im-sueden-der-rieseninsel-madagaskar-zerbricht-alle-gesellschaftliche-ordnung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrika\/1769\/","title":{"rendered":"Im Sueden der Rieseninsel Madagaskar zerbricht alle gesellschaftliche Ordnung"},"content":{"rendered":"<p><a href=\"https:\/\/www.fr.de\/\" class=\"id-Breadcrumb-link\" data-id-ec=\"{\" shn=\"\" textlink=\"\" data-k5a-pos=\"1_startseite\" rel=\"nofollow noopener\" target=\"_blank\">Startseite<\/a><a href=\"https:\/\/www.fr.de\/politik\/\" class=\"id-Breadcrumb-link\" data-id-ec=\"{\" shn=\"\" textlink=\"\" data-k5a-pos=\"2_politik\" rel=\"nofollow noopener\" target=\"_blank\">Politik<\/a><\/p>\n<p class=\"id-Story-timestamp id-Story-timestamp--default\">Stand: 06.01.2026, 09:46 Uhr<\/p>\n<p class=\"id-Story-authors id-Story-authors--default\">Von: <a class=\"id-Story-authors-link lp_west_author\" href=\"https:\/\/www.fr.de\/autor\/sereina-donatsch-6t3k905be.html\" title=\"Zur Autorenseite von Sereina Donatsch\" data-id-ec=\"{\" shn=\"\" author-link=\"\" donatsch=\"\" data-k5a-pos=\"west_author\" rel=\"nofollow noopener\" target=\"_blank\">Sereina Donatsch<\/a><\/p>\n<p class=\"id-Story-interactionBar id-Story-interactionBar--default\">DruckenTeilen<\/p>\n<p><a href=\"https:\/\/profile.google.com\/cp\/CgkvbS8wNHk5cHYaAA\" class=\"id-Story-googleFollowButton id-Story-googleFollowButton--default\" target=\"_blank\" data-id-ec=\"{\" shn=\"\" google-follow=\"\" auf=\"\" google=\"\" folgen=\"\" rel=\"nofollow noopener\">Uns auf Google folgen<\/a><img decoding=\"async\" class=\"id-RatioPlaceholder-element wv_story_el_image\" src=\"https:\/\/www.europesays.com\/afrika\/wp-content\/uploads\/2026\/04\/40945397-baeume-im-suedwesten-madagaskars-deren-wurzeln-durch-erosion-freigelegt-wurden-2IMR8MjiPe7a.jpeg\" loading=\"eager\" fetchpriority=\"high\"   height=\"792\" width=\"1408\" alt=\"B&#xE4;ume im S&#xFC;dwesten Madagaskars, deren Wurzeln durch Erosion freigelegt wurden.\"\/>B\u00e4ume im S\u00fcdwesten Madagaskars, deren Wurzeln durch Erosion freigelegt wurden.  \u00a9\u00a0Karel Prinsloo\/AFP<\/p>\n<p class=\"id-StoryElement-leadText\">Im S\u00fcden der Rieseninsel zerbricht alle gesellschaftliche Ordnung.<\/p>\n<p class=\"id-StoryElement-paragraph\">Damisoa hat seine Heimat nicht verlassen, weil er wollte, sondern weil er musste.<\/p>\n<p class=\"id-StoryElement-paragraph\">Im S\u00fcden Madagaskars \u2013 in der Region Androy \u2013 bricht infolge von D\u00fcrre und Hunger die Lebensgrundlage vieler Familien weg. Mehrere aufeinanderfolgende Regenausf\u00e4lle lassen Ernten verdorren, Vieh verenden und Brunnen versiegen. Damisoa und seine Angeh\u00f6rigen machen sich auf, vier Monate lang und \u00fcber 1500 Kilometer, Richtung Nordwesten in die Region Boeny. Sie suchen Wasser, Arbeit und Ackerland \u2013 und landen stattdessen in einem Umsiedlungsort nahe dem Ankarafantsika-Nationalpark.<\/p>\n<p class=\"id-StoryElement-paragraph\">Sie leben dort in einer winzigen H\u00fctte, auf unfruchtbarem Boden, ohne Zugang zu sauberem Wasser und ohne medizinische Versorgung. Lebensmittelhilfen erreichen die Siedlung nur unregelm\u00e4\u00dfig, Verdienstm\u00f6glichkeiten gibt es kaum. Anfang des Jahres stirbt Damisoas neugeborene Nichte, weil ihre Mutter nicht genug Muttermilch hat.<\/p>\n<p class=\"id-StoryElement-paragraph\">Die Lage der Siedlung versch\u00e4rft die ohnehin prek\u00e4ren Lebensbedingungen noch. In der Regenzeit tritt der nahe Kamoro-Fluss \u00fcber die Ufer und schneidet den Ort zeitweise von M\u00e4rkten, Apotheken, Krankenh\u00e4usern und Schulen ab. 2023 kommt dabei ein Mann durch einen Krokodilangriff ums Leben, ein weiterer ertrinkt beim Versuch, den Fluss zu \u00fcberqueren.<\/p>\n<p class=\"id-StoryElement-paragraph\">\u201eDie madagassischen Beh\u00f6rden haben es vers\u00e4umt, Tausende von Antandroy zu sch\u00fctzen und zu unterst\u00fctzen\u201c, kritisiert Amnesty International in einem Bericht. Zwischen 2018 und 2024 mussten rund 90\u2009000 Menschen \u2013 \u00fcberwiegend aus der Gemeinschaft der Antandroy, einer Bev\u00f6lkerungsgruppe aus dem extrem trockenen S\u00fcden Madagaskars \u2013 fliehen. Die meisten von ihnen innerhalb des eigenen Landes, ohne rechtlichen Schutzstatus oder beh\u00f6rdliche Unterst\u00fctzung.<\/p>\n<p>Die soziale Not versch\u00e4rft sich radikal<\/p>\n<p class=\"id-StoryElement-paragraph\">\u201eViele verkaufen alles, was sie haben, verschulden sich oder suchen unterwegs Gelegenheitsarbeit und sind dabei hohen Risiken wie Ausbeutung und unsicheren Arbeitsbedingungen ausgesetzt\u201c, erkl\u00e4rt Claudia Kolarski, Sprecherin der Amnesty-Koordinationsgruppe S\u00fcdliches Afrika, der Frankfurter Rundschau.<\/p>\n<p class=\"id-StoryElement-paragraph\">Die Flucht ist f\u00fcr viele schon finanziell kaum zu bew\u00e4ltigen. Die Reisekosten von rund 30 bis 60 US-Dollar entsprechen f\u00fcr zahlreiche Antandroy, die \u00fcberwiegend von kleinb\u00e4uerlicher Landwirtschaft und Viehhaltung leben, etwa einem Monatsverdienst. Wer so viel Geld nicht aufbringen kann, macht sich zu Fu\u00df auf den Weg \u2013 \u00fcber Hunderte Kilometer, mit Zwischenstopps entlang der Route, oft ohne feste Unterkunft oder Versorgung.<\/p>\n<p class=\"id-StoryElement-paragraph\">\u201eIch habe mit dem Fahrer verhandelt\u201c, erz\u00e4hlt der 48-j\u00e4hrige Masoandro Amnesty. Um die Schulden begleichen zu k\u00f6nnen, habe sein Sohn ein Jahr lang als Hirte arbeiten m\u00fcssen \u2013 denn falls das Geld nicht zur\u00fcckgezahlt w\u00fcrde, drohte der Fahrer mit Gef\u00e4ngnis. Solche Erfahrungen sind keine Einzelf\u00e4lle, betont Amnesty, sondern Ausdruck struktureller Schutzlosigkeit entlang der Fluchtrouten.<\/p>\n<p class=\"id-StoryElement-paragraph\">Die Ursachen der jetzigen Krise reichen weit zur\u00fcck: Anfang des 20. Jahrhunderts lie\u00dfen die franz\u00f6sischen Kolonialbeh\u00f6rden gezielt Cochenille-Parasiten aussetzen, um gro\u00dffl\u00e4chig die Opuntia-Kakteen zu vernichten \u2013 robuste Pflanzen, die im S\u00fcden Madagaskars als nat\u00fcrliche Nahrungs- und Wasserreserve dienen. Die Kakteen helfen Menschen und Vieh, l\u00e4ngere Trockenperioden zu \u00fcberstehen und auf ihrem Land zu bleiben.<\/p>\n<p class=\"id-StoryElement-paragraph\">Auch der Weltklimarat verweist darauf, dass historische Machtverh\u00e4ltnisse die Klimakrise in Madagaskar bis heute pr\u00e4gen. Kolonialistische Politik zerst\u00f6rt in vielen Regionen Land und \u00d6kosysteme und macht sie dadurch anf\u00e4lliger f\u00fcr D\u00fcrren und Extremwetter \u2013 eine Hypothek, die sich mit der Erderhitzung versch\u00e4rft.<\/p>\n<p class=\"id-StoryElement-paragraph\">Staaten, die \u00fcber Jahrzehnte von fossilem Wachstum profitierten, tragen daher besondere Verantwortung: Sie m\u00fcssen ihre Emissionen deutlich senken, \u00e4rmere L\u00e4nder bei der Anpassung an den Klimawandel finanziell unterst\u00fctzen und f\u00fcr Sch\u00e4den aufkommen, die durch D\u00fcrren, \u00dcberschwemmungen oder den Verlust von Lebensgrundlagen bereits entstanden sind. Andernfalls, warnt Amnesty International, droht die Klimakrise, bestehende globale Ungleichheiten weiter zu verfestigen.<\/p>\n<p class=\"id-StoryElement-paragraph\">Nicht nur Amnesty, sondern auch Hilfsorganisationen vor Ort wie Action Against Hunger und Caritas Madagascar sprechen von einer humanit\u00e4ren Katastrophe. Im S\u00fcden des Landes sind nach UN-Angaben zeitweise \u00fcber eine Million Menschen von akuter Ern\u00e4hrungsunsicherheit betroffen.<\/p>\n<p class=\"id-StoryElement-paragraph\">Das Problem ist, dass Menschen, die infolge von D\u00fcrre, Hunger oder Umweltzerst\u00f6rung fliehen, nach geltendem V\u00f6lkerrecht in der Regel nicht unter die Statuten der Genfer Fl\u00fcchtlingskonvention fallen. Ohne einen derart gekl\u00e4rten Rechtsstatus fehlt ihnen dann h\u00e4ufig der Anspruch auf umfassenden Schutz, Unterst\u00fctzung und langfristige Perspektiven. <\/p>\n<p class=\"id-StoryElement-paragraph\">Amnesty International fordert deshalb, klimabedingte Vertreibung ausdr\u00fccklich anzuerkennen und bestehende Schutzl\u00fccken zu schlie\u00dfen. Langfristig, so die Menschenrechtsorganisation, sei eine Weiterentwicklung des internationalen Fl\u00fcchtlingsrechts unvermeidlich.<\/p>\n<p class=\"id-StoryElement-paragraph\">Was diese rechtliche Schutzl\u00fccke in der Praxis bedeutet, l\u00e4sst sich in L\u00e4ndern wie Madagaskar besonders deutlich beobachten. Nach Angaben von Unicef steigen die Temperaturen auf der Rieseninsel schneller als im globalen Durchschnitt \u2013 um rund 0,35 Grad pro Jahrzehnt. Trockenperioden werden h\u00e4ufiger und intensiver, besonders im S\u00fcden. Die Klimakrise verst\u00e4rkt die dortige Armut. Besonders gravierend sind die Folgen f\u00fcr Kinder. Wenn D\u00fcrre den Alltag bestimmt und Wasserquellen versiegen, bleibt vielen Familien keine Wahl: Kinder werden aus der Schule genommen, um mitzuarbeiten, M\u00e4dchen legen weite und gef\u00e4hrliche Wege zur\u00fcck, um Wasser zu holen. Unicef warnt, dass sich damit Bildungsabbr\u00fcche, Gesundheitsrisiken und Gewaltspiralen verfestigen.<\/p>\n<p class=\"id-StoryElement-paragraph\">Was in Androy passiert, ist Teil eines globalen Musters: Binnenvertreibung durch Katastrophen erreicht Rekordh\u00f6hen. Der Global Report on Internal Displacement (GRID) des Forschungsinstituts IDMC weist f\u00fcr 2024 weltweit 45,8 Millionen neue Vertriebene infolge von Naturkatastrophen aus \u2013 so viele wie nie zuvor. Ende 2024 leben demnach 83,4 Millionen Menschen als Binnenvertriebene; die meisten wegen Konflikt und Gewalt, aber auch Millionen infolge von Naturkatastrophen. D\u00fcrre geh\u00f6rt inzwischen zu den zentralen Treibern.<\/p>\n<p>Gefahren rund um<br \/>\nden Indischen Ozean<\/p>\n<p class=\"id-StoryElement-paragraph\">Auch f\u00fcr Menschen, die bereits vor Krieg oder Verfolgung geflohen sind, versch\u00e4rft die Klimakrise deren Lage. Der UNHCR warnt, dass fast alle gro\u00dfen Fl\u00fcchtlingslager weltweit mit stark steigender, gef\u00e4hrlicher Hitzebelastung rechnen m\u00fcssen \u2013 etwa in Bangladesch, Kenia und im Sudan. <\/p>\n<p class=\"id-StoryElement-paragraph\">In den Lagern von Cox\u2019s Bazar, wo Hunderttausende burmesische Rohingya leben, oder in Dadaab und Kakuma im Norden Kenias steigen die Temperaturen schon heute regelm\u00e4\u00dfig auf \u00fcber 40 Grad. Bis 2050 k\u00f6nnten die 15 am st\u00e4rksten betroffenen Camps an nahezu 200 Tagen im Jahr gef\u00e4hrlichen Hitzestress erleben. <\/p>\n<p class=\"id-StoryElement-paragraph\">Ohne wirksame Klimaanpassung und verbindliche Schutzregelungen droht klimabedingte Vertreibung zur neuen Normalit\u00e4t zu werden.<\/p>\n<p>Klimaflucht<\/p>\n<p class=\"id-StoryElement-factBox-paragraph\">Allein 2024 werden weltweit 45,8 Millionen Menschen infolge von D\u00fcrren, \u00dcberschwemmungen, St\u00fcrmen und anderen Extremereignissen innerhalb ihrer L\u00e4nder vertrieben. Ende 2024 leben laut dem Internal Displacement Monitoring Centre (IDMC) 83,4 Millionen Menschen als Binnenvertriebene \u2013 so viele wie nie zuvor.<\/p>\n<p class=\"id-StoryElement-factBox-paragraph\">Zwar bleiben Konflikte und Gewalt die h\u00e4ufigste Ursache von Vertreibung, doch klimabedingte Katastrophen gewinnen deutlich an Bedeutung. D\u00fcrre z\u00e4hlt inzwischen zu den zentralen Treibern, insbesondere in Regionen mit hoher Armut und schwacher Infrastruktur.<\/p>\n<p class=\"id-StoryElement-factBox-paragraph\">\u00dcber die vergangenen zehn Jahre hinweg werden weltweit rund 250 Millionen Menschen zumindest zeitweise durch klimatische Extremereignisse aus ihrer Heimat verdr\u00e4ngt. sd<\/p>\n","protected":false},"excerpt":{"rendered":"StartseitePolitik Stand: 06.01.2026, 09:46 Uhr Von: Sereina Donatsch DruckenTeilen Uns auf Google folgenB\u00e4ume im S\u00fcdwesten Madagaskars, deren Wurzeln&hellip;\n","protected":false},"author":2,"featured_media":1770,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[245],"tags":[380,379],"class_list":{"0":"post-1769","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-madagaskar","8":"tag-madagascar","9":"tag-madagaskar"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/1769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/comments?post=1769"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/1769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media\/1770"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media?parent=1769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/categories?post=1769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/tags?post=1769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}