{"id":480,"date":"2026-04-18T06:14:21","date_gmt":"2026-04-18T06:14:21","guid":{"rendered":"https:\/\/www.europesays.com\/afrika\/480\/"},"modified":"2026-04-18T06:14:21","modified_gmt":"2026-04-18T06:14:21","slug":"golf-profi-marcel-siem-darum-lebt-er-auf-trauminsel-mauritius","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrika\/480\/","title":{"rendered":"Golf-Profi Marcel Siem: Darum lebt er auf Trauminsel Mauritius"},"content":{"rendered":"<p><a href=\"https:\/\/www.sportsillustrated.de\/tags\/marcel-siem\" rel=\"nofollow noopener\" target=\"_blank\">Marcel Siem<\/a> f\u00fchrt uns durch\u00a0Wahlheimat <a href=\"https:\/\/www.sportsillustrated.de\/tags\/mauritius\" rel=\"nofollow noopener\" target=\"_blank\">Mauritius<\/a>\u00a0<br \/>\n\t<a href=\"https:\/\/www.sportsillustrated.de\/tags\/golf\" rel=\"nofollow noopener\" target=\"_blank\">Golf:<\/a> Seit 2018 lebt Marcel Siem auf Mauritius<br \/>\n\tMauritius: T\u00fcrkisblaues Meer und Golf-Paradies\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Follow us on:<\/p>\n<p>Wie ich nach Mauritius \u2013 ein Inselstaat \u00f6stlich von Afrika \u2013 kam, das ist keine dieser typischen Auswanderer-Geschichten. 1998 war ich das erste Mal hier, damals noch als Amateur bei einem Turnier. Schon da hatte ich das Gef\u00fchl, dass dieser Ort etwas mit mir macht.<\/p>\n<p>2018 verlor ich dann meine Tourkarte, also die Berechtigung, bei den gr\u00f6\u00dften Turnieren der Welt antreten zu d\u00fcrfen, kurz darauf wurde meine Frau schwer krank. Es waren harte Monate. Als das \u00fcberstanden war, flogen wir noch einmal nach Mauritius \u2013 und merkten, wie gut uns das Leben hier tut. Also packten wir in einer Nacht-und-Nebel-Aktion unsere Sachen und zogen von Deutschland hierher.\u00a0<\/p>\n<p>Was Mauritius f\u00fcr mich besonders macht, sind die Menschen. Die Locals sind unglaublich freundlich und entspannt. Alles l\u00e4uft etwas langsamer, ohne tr\u00e4ge zu sein. Wir leben im S\u00fcden der Insel, im Heritage Resort, in einer Villa oberhalb des Golfplatzes.<\/p>\n<p>Marcel Siem lebt seit 2018 auf Trauminsel Mauritius<\/p>\n<p>Morgens fr\u00fchst\u00fccke ich mit meinen Kindern, die hier eine internationale Schule besuchen, steige in den Buggy, fahre zwei Minuten zum Gym und gehe dann auf den Platz. F\u00fcr mich als Golfprofi ist das ideal. Der Heritage Golf Club, der zum Resort geh\u00f6rt, ist mein Mittelpunkt.\u00a0<\/p>\n<p>Vor allem der Ch\u00e2teau Course bedeutet mir viel, weil er mich sportlich wieder auf Spur gebracht hat. Ich sitze unglaublich gern auf der Terrasse, schaue auf das Gr\u00fcn, w\u00e4hrend Hunde und Katzen \u00fcber den Platz laufen. F\u00fcr mich ist dieser Ort weit mehr als ein Golfplatz. Wenn ich nicht trainiere, zieht es mich aufs Wasser.\u00a0<\/p>\n<p>Von Macond\u00e9, einem Aussichtspunkt an der K\u00fcstenstra\u00dfe, geht es mit dem Boot raus durchs Riff Richtung Crystal Rock. Je nach Wellengang sucht man sich einen Punkt, wirft den Anker und steht knietief im Wasser, isst, redet, verbringt Zeit miteinander. Das ist f\u00fcr mich pure Entspannung. Auch im \u201eC Beach Club\u201c kann ich gut entspannen. Den ganzen Tag l\u00e4uft House-Music, man trinkt ein kaltes Getr\u00e4nk, schaut aufs Meer und trifft Leute, die hier leben.\u00a0<\/p>\n<p>Golf-Profi Marcel Siem: &#8222;Ich vermisse Deutschland&#8220;<\/p>\n<p>Wenn mir und den Kindern dann doch mal der Sinn nach Abwechslung steht, fahren wir mit dem Katamaran nach \u00cele aux Cerfs, in den Nordosten der Insel. F\u00fcr die Kinder ist es dort perfekt: ruhige Buchten zum Schwimmen auf der einen Seite, Action und Wassersport auf der anderen. Auch kulinarisch hat Mauritius einiges zu bieten. Mein Lieblingsrestaurant ist das \u201eMo Filaos\u201c, nur ein paar Meter vom Wasser entfernt, mitten im Gr\u00fcnen. Mein Tipp: Bestellt euch einen kleinen, brutzelnden Topf mit Fleisch, Fisch oder Meeresfr\u00fcchten, der mit Paprika, Zwiebeln, Knoblauch und Fried Rice serviert wird. Sehr simpel, aber unglaublich gut \u2013 wie so vieles auf Mauritius.\u00a0<\/p>\n<p>Ich vermisse Deutschland, meine Freunde, meine Familie, und ich sage nicht, dass ich nie zur\u00fcckkommen werde. Aber f\u00fcr diesen Abschnitt meines Lebens ist Mauritius genau richtig. Hier kann ich mich auf das konzentrieren, was mir wichtig ist.\u00a0<\/p>\n<p>Sports Illustrated-Chefredakteurs Newsletter<\/p>\n<p>Mit dem <a href=\"https:\/\/www.sportsillustrated.de\/newsletter\/?utm_source=si&amp;utm_medium=website&amp;utm_campaign=newsletter_button\" rel=\"nofollow noopener\" target=\"_blank\">Sports Illustrated-Chefredakteurs Newsletter<\/a> erhalten Sie aktuelle Sport-News, Hintergr\u00fcnde und Interviews aus der <a href=\"https:\/\/www.sportsillustrated.de\/football\/nfl\" rel=\"nofollow noopener\" target=\"_blank\">NFL<\/a>, der <a href=\"https:\/\/www.sportsillustrated.de\/basketball\/nba\" rel=\"nofollow noopener\" target=\"_blank\">NBA<\/a>, der <a href=\"https:\/\/www.sportsillustrated.de\/fussball\/1-bundesliga\" rel=\"nofollow noopener\" target=\"_blank\">Fu\u00dfball-Bundesliga<\/a>, der <a href=\"https:\/\/www.sportsillustrated.de\/formel-1\" rel=\"nofollow noopener\" target=\"_blank\">Formel 1<\/a> und <a href=\"https:\/\/www.sportsillustrated.de\/mehr-sport\" rel=\"nofollow noopener\" target=\"_blank\">vieles mehr.<\/a>\n<\/p>\n<p><a aria-label=\"Sports Illustrated-Chefredakteurs Newsletter abonnieren und keine Sport-News verpassen\" class=\"button\" href=\"https:\/\/www.sportsillustrated.de\/newsletter\/?utm_source=si&amp;utm_medium=website&amp;utm_campaign=newsletter_button\" rel=\"nofollow noopener\" target=\"_blank\">NEWSLETTER ABONNIEREN<\/a>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Marcel Siem f\u00fchrt uns durch\u00a0Wahlheimat Mauritius\u00a0 Golf: Seit 2018 lebt Marcel Siem auf Mauritius Mauritius: T\u00fcrkisblaues Meer und&hellip;\n","protected":false},"author":2,"featured_media":481,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[438,441,440,439,392],"class_list":{"0":"post-480","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mauritius","8":"tag-city-guide","9":"tag-golf","10":"tag-insel","11":"tag-marcel-siem","12":"tag-mauritius"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/comments?post=480"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts\/480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media\/481"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/media?parent=480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/categories?post=480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/tags?post=480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}