{"id":3061,"count":2,"description":"","link":"https:\/\/www.europesays.com\/afrika\/tag\/mv\/","name":"MV","slug":"mv","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/tags\/3061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/afrika\/wp-json\/wp\/v2\/posts?tags=3061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}