{"id":22781,"date":"2026-02-23T08:22:28","date_gmt":"2026-02-23T08:22:28","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/22781\/"},"modified":"2026-02-23T08:22:28","modified_gmt":"2026-02-23T08:22:28","slug":"enko-education-dalain-et-cyrille-nkontchou-leve-255-milliards-fcfa-pour-accelerer-lextension-de-ses-ecoles-en-afrique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/22781\/","title":{"rendered":"Enko Education d\u2019Alain et Cyrille Nkontchou l\u00e8ve 25,5 milliards FCFA pour acc\u00e9l\u00e9rer l\u2019extension de ses \u00e9coles en Afrique"},"content":{"rendered":"<p class=\"texte\" style=\"text-align: justify;\">(Investir au Cameroun) &#8211; Enko Education, la branche \u00e9ducation du gestionnaire d\u2019actifs Enko Capital \u2014 cofond\u00e9 par les financiers camerounais Alain et Cyrille Nkontchou \u2014 a annonc\u00e9, le 17 f\u00e9vrier 2026, le bouclage d\u2019une lev\u00e9e de fonds de 46 millions\u00a0$ (25,5 milliards FCFA au cours actuel du dollar am\u00e9ricain). L\u2019op\u00e9ration doit financer l\u2019expansion du r\u00e9seau d\u2019\u00e9coles internationales du groupe en Afrique subsaharienne, selon des informations communiqu\u00e9es officiellement.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Le financement inclut un pr\u00eat de 22 millions\u00a0$ (12,2 milliards FCFA) accord\u00e9 par Standard Bank, banque sud-africaine. Enko Education indique que ces ressources serviront \u00e0 acc\u00e9l\u00e9rer l\u2019extension du r\u00e9seau et \u00e0 soutenir une trajectoire de croissance ambitieuse.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">L\u2019objectif affich\u00e9 est de tripler le nombre d\u2019\u00e9l\u00e8ves pour atteindre 20\u00a0000 apprenants d\u2019ici 2029. \u00ab\u00a0Enko Education est le partenaire id\u00e9al pour les propri\u00e9taires d\u2019\u00e9coles qui souhaitent transmettre leur \u00e9tablissement \u00e0 un groupe qui respecte leur vision et leur h\u00e9ritage, tout en leur offrant les ressources n\u00e9cessaires pour se d\u00e9velopper et prosp\u00e9rer\u00a0\u00bb, commente Cyrille Nkontchou.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">\u00c0 ce jour, Enko Education revendique 16 \u00e9coles dans 10 pays d\u2019Afrique subsaharienne\u00a0: Cameroun, C\u00f4te d\u2019Ivoire, S\u00e9n\u00e9gal, Mali, Burkina Faso, Togo, Zambie, Botswana, Mozambique et Afrique du Sud. Au Cameroun, le r\u00e9seau cite notamment le complexe scolaire La Gait\u00e9 de Yaound\u00e9.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Le groupe met en avant un programme \u00ab\u00a0tr\u00e8s s\u00e9lect\u00a0\u00bb pr\u00e9parant au Baccalaur\u00e9at international. Selon ses promoteurs, le mod\u00e8le \u00e9ducatif, centr\u00e9 sur l\u2019excellence acad\u00e9mique, vise \u00e0 am\u00e9liorer la qualit\u00e9 de l\u2019\u00e9ducation en Afrique et \u00e0 faciliter l\u2019acc\u00e8s des \u00e9l\u00e8ves aux meilleures universit\u00e9s et grandes \u00e9coles dans le monde.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Enko Education indique qu\u2019\u00e0 ce jour, plus de 80\u00a0% des dipl\u00f4m\u00e9s de son r\u00e9seau ont int\u00e9gr\u00e9 plus de 600 universit\u00e9s \u00e0 travers le monde, parmi lesquelles Sciences Po, University of Toronto, University of Cape Town et Hong Kong Polytechnic University.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Brice R. Mbodiam<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Lire aussi:<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p><a href=\"https:\/\/www.investiraucameroun.com\/finance\/2504-7343-enko-education-investments-du-financier-camerounais-cyrille-nkontchou-prend-pied-en-cote-d-ivoire\" rel=\"nofollow noopener\" target=\"_blank\">25-04-2016\u2002-\u2002Enko Education\u2002Investments du financier camerounais Cyrille Nkontchou prend pied en C\u00f4te d\u2019Ivoire<\/a><\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p><a href=\"https:\/\/www.investiraucameroun.com\/finance\/0303-6134-le-financier-camerounais-cyrille-nkontchou-investit-dans-le-secteur-des-assurances-en-zambie\" rel=\"nofollow noopener\" target=\"_blank\">03-03-2015\u2002- Le financier camerounais Cyrille Nkontchou investit dans le secteur des assurances en<\/a>\u00a0Zambie<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"(Investir au Cameroun) &#8211; Enko Education, la branche \u00e9ducation du gestionnaire d\u2019actifs Enko Capital \u2014 cofond\u00e9 par les&hellip;\n","protected":false},"author":2,"featured_media":22782,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6,10216,90,2322,10215,418,7705,10217,1480],"class_list":{"0":"post-22781","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-afrique","9":"tag-cyrille","10":"tag-des","11":"tag-education","12":"tag-enko","13":"tag-groupe","14":"tag-leur","15":"tag-nkontchou","16":"tag-reseau"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116118981352178138","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/22781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=22781"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/22781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/22782"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=22781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=22781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=22781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}