{"id":31657,"date":"2026-03-03T15:31:24","date_gmt":"2026-03-03T15:31:24","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/31657\/"},"modified":"2026-03-03T15:31:24","modified_gmt":"2026-03-03T15:31:24","slug":"catherine-njeri-cartographie-et-analyse-les-terres-agricoles-dafrique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/31657\/","title":{"rendered":"Catherine Njeri cartographie et analyse les terres agricoles d\u2019Afrique"},"content":{"rendered":"<p style=\"text-align: justify;\">Elle met la donn\u00e9e au service des terres africaines. Son innovation permet aux acteurs agricoles et forestiers de comprendre, quantifier et valoriser leurs espaces comme jamais auparavant.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Catherine Njeri (photo) est une entrepreneure k\u00e9nyane sp\u00e9cialis\u00e9e dans les donn\u00e9es et les produits num\u00e9riques appliqu\u00e9s \u00e0 l\u2019agriculture et au climat. Elle est cofondatrice et directrice g\u00e9n\u00e9rale d\u2019Acre Insights, une entreprise qui aide les acteurs de l\u2019agriculture et de la foresterie en Afrique \u00e0 mieux conna\u00eetre, suivre et valoriser leurs terres.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Fond\u00e9e en 2023, Acre Insights ambitionne de contribuer \u00e0 une Afrique o\u00f9 chaque hectare, qu\u2019il s\u2019agisse de fermes ou de for\u00eats, peut \u00eatre mesur\u00e9, v\u00e9rifi\u00e9 et valoris\u00e9 de mani\u00e8re fiable. Elle fournit une base de donn\u00e9es claire et v\u00e9rifiable pour les projets de reforestation, d\u2019agriculture r\u00e9g\u00e9n\u00e9ratrice et de compensation carbone.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">L\u2019entreprise s\u2019appuie sur deux grands types d\u2019outils : d\u2019une part, l\u2019observation a\u00e9rienne et spatiale, et d\u2019autre part, l\u2019analyse de donn\u00e9es. Elle utilise des drones et des satellites pour capturer des images d\u00e9taill\u00e9es des terres agricoles et foresti\u00e8res. \u00c0 partir de ces images, ses algorithmes identifient les zones de couvert v\u00e9g\u00e9tal, la hauteur des arbres et d\u2019autres indicateurs essentiels \u00e0 l\u2019estimation de la biomasse et du carbone pr\u00e9sents sur un site.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Les r\u00e9sultats sont restitu\u00e9s sous forme de cartes interactives et de rapports d\u00e9taill\u00e9s. Les services d\u2019Acre Insights visent ainsi \u00e0 simplifier la complexit\u00e9 des syst\u00e8mes naturels pour permettre des d\u00e9cisions plus rapides, plus \u00e9clair\u00e9es et plus durables.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Catherine Njeri est dipl\u00f4m\u00e9e de l\u2019African Leadership University (ALU), o\u00f9 elle a obtenu en 2015 un bachelor en administration des affaires internationales. Elle est aussi titulaire d\u2019un dipl\u00f4me en technologies de l\u2019information commerciale obtenu la m\u00eame ann\u00e9e \u00e0 la Strathmore University.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Apr\u00e8s des stages en marketing et en d\u00e9veloppement commercial chez Cellulant, puis en gestion de projets et en analyse de donn\u00e9es chez ALX, elle rejoint l\u2019ALU en 2019 en tant qu\u2019analyste de donn\u00e9es. La m\u00eame ann\u00e9e, elle retourne chez Cellulant o\u00f9 elle occupe successivement les postes de coordinatrice des processus op\u00e9rationnels, de responsable des op\u00e9rations commerciales mondiales et de responsable grands comptes.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">En 2022, elle devient responsable des op\u00e9rations commerciales, des donn\u00e9es et des rapports chez Ramani, une entreprise sp\u00e9cialis\u00e9e dans la num\u00e9risation de la cha\u00eene d\u2019approvisionnement africaine. De 2024 \u00e0 2025, elle occupe le poste de responsable de la recherche au sein de Kenya Flying Labs, un centre d\u00e9di\u00e9 \u00e0 la robotique et \u00e0 l\u2019innovation technologique.<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Melchior Koba<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Edit\u00e9 par S\u00e8na D. B. de Sodji<\/p>\n<p class=\"texte\" style=\"text-align: justify;\">Lire aussi:<\/p>\n<p class=\"texte\" style=\"text-align: justify;\"><a href=\"https:\/\/www.wearetech.africa\/fr\/fils\/tech-stars\/lemonade-payments-mark-machiri-kihara-numerise-les-paiements-pour-les-entreprises\" rel=\"nofollow noopener\" target=\"_blank\">Lemonade Payments : Mark Machiri Kihara num\u00e9rise les paiements pour les entreprises<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Elle met la donn\u00e9e au service des terres africaines. Son innovation permet aux acteurs agricoles et forestiers de&hellip;\n","protected":false},"author":2,"featured_media":31658,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6,13347,90,1661,415,386,223,315,225],"class_list":{"0":"post-31657","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-afrique","9":"tag-chez","10":"tag-des","11":"tag-donnees","12":"tag-elle","13":"tag-est","14":"tag-les","15":"tag-pour","16":"tag-une"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116165966763057729","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/31657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=31657"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/31657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/31658"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=31657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=31657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=31657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}