{"id":34701,"date":"2026-03-06T10:12:14","date_gmt":"2026-03-06T10:12:14","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/34701\/"},"modified":"2026-03-06T10:12:14","modified_gmt":"2026-03-06T10:12:14","slug":"sanctions-contre-le-rwanda-massacre-au-soudan-du-sud-manifestation-au-senegal-lhebdo-afrique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/34701\/","title":{"rendered":"Sanctions contre le Rwanda, massacre au Soudan du Sud, manifestation au S\u00e9n\u00e9gal\u00a0: l\u2019hebdo Afrique"},"content":{"rendered":"<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/1770842114_652_inter-en-bref.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>          Les <a href=\"https:\/\/www.france24.com\/fr\/tag\/\u00e9tats-unis\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">\u00c9tats-Unis<\/a> ont annonc\u00e9 lundi <a href=\"https:\/\/www.france24.com\/fr\/vid\u00e9o\/20260304-rd-congo-washington-sanctionne-l-arm\u00e9e-rwandaise-pour-son-soutien-au-m23\" target=\"_self\" rel=\"nofollow noopener\">des sanctions contre l&rsquo;arm\u00e9e rwandaise pour son soutien aux forces de l&rsquo;AFC\/M23<\/a> dans l&rsquo;est de la R\u00e9publique d\u00e9mocratique du Congo. Kinshasa a salu\u00e9\u00a0ces sanctions am\u00e9ricaines,\u00a0r\u00e9clam\u00e9es\u00a0depuis longtemps, et exprim\u00e9 sa \u00ab\u00a0profonde reconnaissance\u00a0\u00bb. De son c\u00f4t\u00e9, le <a href=\"https:\/\/www.france24.com\/fr\/tag\/rwanda\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Rwanda<\/a> a d\u00e9clar\u00e9 qu&rsquo;elles \u00ab\u00a0visaient injustement une seule partie\u00a0\u00bb et affirm\u00e9 qu&rsquo;une telle mesure \u00ab\u00a0ne refl\u00e8te pas la r\u00e9alit\u00e9 et d\u00e9forme les faits du conflit\u00a0\u00bb.  <\/p>\n<p>Dans le nord du <a href=\"https:\/\/www.france24.com\/fr\/tag\/soudan-du-sud\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Soudan du Sud<\/a>, au moins 169\u00a0personnes ont \u00e9t\u00e9 tu\u00e9es dimanche par des attaquants arm\u00e9s dans le village d\u2019Abiemnhom.\u00a0Selon les autorit\u00e9s locales, un\u00a0groupe de jeunes venus de l&rsquo;\u00c9tat voisin d&rsquo;Unit\u00e9 est responsable de\u00a0ce massacre,\u00a0sur fond d&rsquo;intenses\u00a0violences\u00a0intercommunautaires entre\u00a0Dinka\u00a0et Nuer ces derni\u00e8res semaines.<\/p>\n<p>Au <a href=\"https:\/\/www.france24.com\/fr\/tag\/s\u00e9n\u00e9gal\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">S\u00e9n\u00e9gal<\/a>, <a href=\"https:\/\/www.france24.com\/fr\/vid\u00e9o\/20260302-s\u00e9n\u00e9gal-des-centaines-de-manifestants-\u00e0-dakar-contre-l-emprisonnement-de-supporters-s\u00e9n\u00e9galais\" target=\"_self\" rel=\"nofollow noopener\">des centaines de manifestants<\/a> ont r\u00e9clam\u00e9, samedi\u00a0dans les rues de la capitale, la lib\u00e9ration de <a href=\"https:\/\/www.france24.com\/fr\/\u00e9missions\/journal-de-l-afrique\/20260219-18-supporters-s\u00e9n\u00e9galais-condamn\u00e9s-entre-trois-mois-et-un-an-de-prison-au-maroc\" target=\"_self\" rel=\"nofollow noopener\">18 supporters s\u00e9n\u00e9galais emprisonn\u00e9s au Maroc<\/a>\u00a0apr\u00e8s les incidents survenus lors de la finale de\u00a0la Coupe d&rsquo;Afrique des nations. Les manifestants disent que ces sanctions sont injustes. Le Premier ministre s\u00e9n\u00e9galais,\u00a0<a href=\"https:\/\/www.france24.com\/fr\/tag\/ousmane-sonko\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Ousmane Sonko<\/a>, a affirm\u00e9 que toutes les voies\u00a0diplomatiques seraient explor\u00e9es pour leur lib\u00e9ration.<\/p>\n<p>Le pr\u00e9sident sud-africain a exprim\u00e9 jeudi sa \u00ab\u00a0vive pr\u00e9occupation\u00a0\u00bb face \u00e0 l&rsquo;escalade au Moyen-Orient. Il a condamn\u00e9 l&rsquo;op\u00e9ration am\u00e9ricaine \u00ab\u00a0contraire au\u00a0droit\u00a0international\u00a0\u00bb et appel\u00e9\u00a0toutes les parties au dialogue.\u00a0<a href=\"https:\/\/www.france24.com\/fr\/tag\/cyril-ramaphosa\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Cyril Ramaphosa<\/a> a d\u00e9clar\u00e9 que l&rsquo;<a href=\"https:\/\/www.france24.com\/fr\/tag\/afrique-du-sud\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Afrique du Sud<\/a> \u00e9tait pr\u00eate \u00e0 jouer le r\u00f4le de m\u00e9diateur.\u00a0L&rsquo;opinion publique est divis\u00e9e sur la question iranienne et\u00a0l&rsquo;opposition demande que Pretoria clarifie sa position.<\/p>\n<p>Les chefs d\u2019\u00e9tat-major\u00a0des arm\u00e9es des pays de la <a href=\"https:\/\/www.france24.com\/fr\/tag\/c\u00e9d\u00e9ao\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">C\u00e9d\u00e9ao<\/a> ont d\u00e9cid\u00e9 samedi de la mise en place d\u2019une force \u00ab\u00a0d\u2019attente\u00a0\u00bb de 2\u00a0000\u00a0hommes pour lutter\u00a0contre les groupes terroristes qui progressent dans la r\u00e9gion.\u00a0Lors des discussions organis\u00e9es \u00e0 Freetown, en <a href=\"https:\/\/www.france24.com\/fr\/tag\/sierra-leone\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Sierra Leone<\/a>, les chefs des arm\u00e9es ouest-africains ont \u00ab\u00a0dress\u00e9 un \u00e9tat des lieux pr\u00e9occupant du paysage s\u00e9curitaire r\u00e9gional\u00a0\u00bb, a affirm\u00e9 une source proche de la rencontre.<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/1771019172_283_inter-grand-angle.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/www.france24.com\/fr\/afrique\/20260228-pourquoi-guerre-entre-ethiopie-tigre-erythree\" target=\"_self\" rel=\"nofollow noopener\">L&rsquo;\u00c9thiopie et le Tigr\u00e9 sont-ils \u00e0 nouveau au bord de la guerre ?<\/a><\/p>\n<p>Plus de trois ans apr\u00e8s la fin d&rsquo;un conflit qui a fait 600\u00a0000\u00a0morts, l&rsquo;<a href=\"https:\/\/www.france24.com\/fr\/tag\/\u00e9thiopie\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">\u00c9thiopie<\/a> et la r\u00e9gion rebelle du <a href=\"https:\/\/www.france24.com\/fr\/tag\/tigr\u00e9\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Tigr\u00e9<\/a>, appuy\u00e9e par l&rsquo;<a href=\"https:\/\/www.france24.com\/fr\/tag\/\u00e9rythr\u00e9e\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">\u00c9rythr\u00e9e<\/a>, sont \u00e0 nouveau \u00e0 couteaux tir\u00e9s. Addis-Abeba a mass\u00e9 des troupes aux abords de sa province et les incidents se multiplient depuis un mois entre l&rsquo;arm\u00e9e f\u00e9d\u00e9rale et les Forces de d\u00e9fense du Tigr\u00e9 (TDF).<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/000-36KM964.jpg\"   alt=\"Les restes calcin\u00e9s d'un char T-72 sur la route reliant Shiraro \u00e0 Shire dans la r\u00e9gion du Tigr\u00e9, le 12 octobre 2024\" style=\"max-height:567px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>                Les restes calcin\u00e9s d&rsquo;un char T-72 sur la route reliant Shiraro \u00e0 Shire dans la r\u00e9gion du Tigr\u00e9, le 12 octobre 2024.                \u00a9 Michele Spatari, AFP            <\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/inter-jta.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/www.france24.com\/fr\/\u00e9missions\/journal-de-l-afrique\/20260305-crise-du-cacao-la-c\u00f4te-d-ivoire-r\u00e9duit-drastiquement-le-prix-d-achat-aux-planteurs\" target=\"_self\" rel=\"nofollow noopener\">Crise du cacao : la C\u00f4te d&rsquo;Ivoire r\u00e9duit drastiquement le prix d&rsquo;achat aux planteurs<\/a><\/p>\n<p>La <a href=\"https:\/\/www.france24.com\/fr\/tag\/c\u00f4te-d-ivoire\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">C\u00f4te d&rsquo;Ivoire<\/a>, premi\u00e8re productrice mondiale de cacao, a divis\u00e9 de plus de moiti\u00e9 le prix d&rsquo;achat de \u00ab\u00a0l&rsquo;or brun\u00a0\u00bb aux planteurs. Son nouveau prix, 1\u00a0200\u00a0francs\u00a0CFA (1,82\u00a0euros) est inf\u00e9rieur de pr\u00e8s de 60\u00a0% au montant record de 2\u00a0800\u00a0francs CFA (4,26\u00a0euros) en vigueur depuis octobre. Une d\u00e9cision n\u00e9cessaire pour enrayer la crise de m\u00e9vente travers\u00e9e par la fili\u00e8re, ont d\u00e9clar\u00e9 les autorit\u00e9s dans un contexte de chute des cours mondiaux et d&rsquo;une crise de surstockage.\u00a0La fili\u00e8re du cacao ivoirien repr\u00e9sente 14\u00a0% du <a href=\"https:\/\/www.france24.com\/fr\/tag\/pib\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">PIB<\/a> du pays et fait vivre environ 5\u00a0millions de personnes.<\/p>\n<p class=\"o-em-consent__content__text\">Pour afficher ce contenu YouTube, il est n\u00e9cessaire d&rsquo;autoriser les cookies de mesure d&rsquo;audience et de publicit\u00e9.<\/p>\n<p>            Accepter<\/p>\n<p>        G\u00e9rer mes choix<\/p>\n<p class=\"o-em-adblock__content__text\">Une extension de votre navigateur semble bloquer le chargement du lecteur vid\u00e9o. Pour pouvoir regarder ce contenu, vous devez la d\u00e9sactiver ou la d\u00e9sinstaller.<\/p>\n<p>            R\u00e9essayer<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/FRAN260304-2141-Live-01.jpg\"   width=\"1024\" height=\"576\" alt=\"\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>                                \u00a9 France 24            <\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/reportage_semaine.png\"   alt=\"\" style=\"max-height:123px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/www.france24.com\/fr\/\u00e9missions\/focus\/20260304-nestl\u00e9-rend-il-les-b\u00e9b\u00e9s-africains-accros-au-sucre\" target=\"_self\" rel=\"nofollow noopener\">Nestl\u00e9 rend-il les b\u00e9b\u00e9s africains accros au sucre ?<\/a><\/p>\n<p>L\u2019ONG suisse Public Eye a r\u00e9v\u00e9l\u00e9 que la marque de c\u00e9r\u00e9ales infantiles Cerelac, de Nestl\u00e9, vendait des produits contenant jusqu&rsquo;\u00e0 15\u00a0% de sucre ajout\u00e9 en Afrique, contre des produits sans sucre ajout\u00e9 en Europe. L&rsquo;<a href=\"https:\/\/www.france24.com\/fr\/tag\/oms\/\" target=\"_self\" rel=\"nofollow noopener\">Organisation mondiale de la sant\u00e9 (OMS)<\/a> appelle \u00e0 arr\u00eater le sucre pour les enfants de moins de 3\u00a0ans, ce que la loi ivoirienne n&rsquo;interdit pas. \u00c0 Abidjan, en C\u00f4te d&rsquo;Ivoire, les habitants se mobilisent pour que l&rsquo;\u00c9tat s&rsquo;aligne sur l&rsquo;OMS.<\/p>\n<p>\u00c0 voir aussi :<\/p>\n<p class=\"o-em-consent__content__text\">Pour afficher ce contenu YouTube, il est n\u00e9cessaire d&rsquo;autoriser les cookies de mesure d&rsquo;audience et de publicit\u00e9.<\/p>\n<p>            Accepter<\/p>\n<p>        G\u00e9rer mes choix<\/p>\n<p class=\"o-em-adblock__content__text\">Une extension de votre navigateur semble bloquer le chargement du lecteur vid\u00e9o. Pour pouvoir regarder ce contenu, vous devez la d\u00e9sactiver ou la d\u00e9sinstaller.<\/p>\n<p>            R\u00e9essayer<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/FR-NW-OOV-ECRAN-FREEZE-FOCUS-LAIT-BEBE-BAIN-Lauren-transfer.jpg\"   width=\"1024\" height=\"576\" alt=\"FOCUS\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>                Focus                \u00a9 France 24            <\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/inter-a-laffiche.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/www.france24.com\/fr\/\u00e9missions\/\u00e0-l-affiche\/20260305-thomas-ngijol-pr\u00eate-sa-voix-\u00e0-allah-n-est-pas-oblig\u00e9-film-d-animation-sur-les-enfants-soldats\" target=\"_self\" rel=\"nofollow noopener\">Thomas Ngijol pr\u00eate sa voix \u00e0 \u00ab\u00a0Allah n\u2019est pas oblig\u00e9\u00a0\u00bb, film d\u2019animation sur les enfants soldats<\/a><\/p>\n<p>Le com\u00e9dien Thomas Ngijol et le r\u00e9alisateur Zaven Najjar pr\u00e9sentent le film d\u2019animation \u00ab\u00a0Allah n\u2019est pas oblig\u00e9\u00a0\u00bb, adaptation du roman \u00e9ponyme d&rsquo;Ahmadou Kourouma qui avait re\u00e7u le prix Renaudot en 2000. L\u2019histoire raconte <a href=\"https:\/\/www.france24.com\/fr\/culture\/20250614-festival-d-annecy-allah-n-est-pas-oblig\u00e9-l-itin\u00e9raire-d-un-enfant-soldat-au-liberia\" target=\"_self\" rel=\"nofollow noopener\">la vie de Birahima, un enfant guin\u00e9en entra\u00een\u00e9 comme enfant soldat dans les guerres civiles<\/a> qui ont ravag\u00e9 le <a href=\"https:\/\/www.france24.com\/fr\/tag\/liberia\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Liberia<\/a> et la Sierra Leone dans les ann\u00e9es 1990.<\/p>\n<p class=\"o-em-consent__content__text\">Pour afficher ce contenu YouTube, il est n\u00e9cessaire d&rsquo;autoriser les cookies de mesure d&rsquo;audience et de publicit\u00e9.<\/p>\n<p>            Accepter<\/p>\n<p>        G\u00e9rer mes choix<\/p>\n<p class=\"o-em-adblock__content__text\">Une extension de votre navigateur semble bloquer le chargement du lecteur vid\u00e9o. Pour pouvoir regarder ce contenu, vous devez la d\u00e9sactiver ou la d\u00e9sinstaller.<\/p>\n<p>            R\u00e9essayer<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/capture-76374860569a97a52a1f309-08945892.jpg\"   width=\"1024\" height=\"576\" alt=\"affiche\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>                affiche                \u00a9 FRANCE 24            <\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/1772199730_172_inter-infomigrants.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/www.infomigrants.net\/fr\/post\/70113\/tunisie--plus-de-1-100-migrants-ont-beneficie-dun-retour-volontaire-depuis-le-debut-de-lannee\" target=\"_blank\" rel=\"nofollow noopener\">Tunisie : plus de 1 100 migrants ont b\u00e9n\u00e9fici\u00e9 d\u2019un \u00ab\u00a0retour volontaire\u00a0\u00bb depuis le d\u00e9but de l&rsquo;ann\u00e9e<\/a><\/p>\n<p>L&rsquo;Organisation internationale des migrations (OIM) a organis\u00e9 le \u00ab\u00a0retour volontaire\u00a0\u00bb de 309\u00a0migrants \u2013 164\u00a0Guin\u00e9ens et 145\u00a0Ivoiriens\u00a0\u2013 les 24 et 25 f\u00e9vrier avec deux vols charters. Au total, 1\u00a0182\u00a0exil\u00e9s ont b\u00e9n\u00e9fici\u00e9 d&rsquo;un \u00ab\u00a0retour volontaire\u00a0\u00bb au d\u00e9part de la <a href=\"https:\/\/www.france24.com\/fr\/tag\/tunisie\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Tunisie<\/a> depuis le d\u00e9but de l&rsquo;ann\u00e9e. De plus en plus de migrants subsahariens fuient le pays de <a href=\"https:\/\/www.france24.com\/fr\/tag\/ka\u00efs-sa\u00efed\/\" target=\"_self\" class=\"gtm-add-suggested-tag\" rel=\"nofollow noopener\">Ka\u00efs Sa\u00efed<\/a>, qui les pousse dans une pr\u00e9carit\u00e9 extr\u00eame.<\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/c33a7f8a5f39c7e938d31efdab797d49824ac6ea.jpg\"   alt=\"L'OIM a organis\u00e9 le &quot;retour volontaire&quot; de plus de 300\u00a0migrants les 24 et 25 f\u00e9vrier 2026.\" style=\"max-height:567px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p>                L&rsquo;OIM a organis\u00e9 le \u00ab\u00a0retour volontaire\u00a0\u00bb de plus de 300\u00a0migrants les 24 et 25 f\u00e9vrier 2026.                \u00a9 OIM Tunisie            <\/p>\n<p><img fetchpriority=\"low\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/02\/inter-post-de-la-semaine.png\"   alt=\"\" style=\"max-height:100px\" loading=\"lazy\" class=\"a-img \"\/><\/p>\n<p class=\"o-em-consent__content__text\">Pour afficher ce contenu Instagram, il est n\u00e9cessaire d&rsquo;autoriser les cookies de mesure d&rsquo;audience et de publicit\u00e9.<\/p>\n<p>            Accepter<\/p>\n<p>        G\u00e9rer mes choix<\/p>\n","protected":false},"excerpt":{"rendered":"Les \u00c9tats-Unis ont annonc\u00e9 lundi des sanctions contre l&rsquo;arm\u00e9e rwandaise pour son soutien aux forces de l&rsquo;AFC\/M23 dans&hellip;\n","protected":false},"author":2,"featured_media":34702,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6,140,999,216,262,2483,2480,3503,11,5809,124],"class_list":{"0":"post-34701","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-afrique","9":"tag-afrique-du-sud","10":"tag-cedeao","11":"tag-cote-divoire","12":"tag-ethiopie","13":"tag-liberia","14":"tag-rd-congo","15":"tag-recap","16":"tag-senegal","17":"tag-soudan-du-sud","18":"tag-tunisie"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116181699327055583","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/34701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=34701"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/34701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/34702"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=34701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=34701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=34701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}