{"id":36503,"date":"2026-03-08T09:07:29","date_gmt":"2026-03-08T09:07:29","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/36503\/"},"modified":"2026-03-08T09:07:29","modified_gmt":"2026-03-08T09:07:29","slug":"a-la-bad-sidi-ould-tah-sengage-a-batir-une-afrique-robuste-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/36503\/","title":{"rendered":"\u00c0 la BAD, Sidi Ould Tah s\u2019engage \u00e0 \u00ab b\u00e2tir une Afrique robuste \u00bb"},"content":{"rendered":"<p>La c\u00e9r\u00e9monie qui s&rsquo;est tenue ce lundi au Sofitel H\u00f4tel Ivoire d&rsquo;Abidjan, marque l&rsquo;ouverture d&rsquo;une nouvelle \u00e8re \u00e0 la Banque africaine de d\u00e9veloppement (BAD), sous le signe de \u00ab l&rsquo;urgence \u00bb et de \u00ab l&rsquo;action \u00bb, pour r\u00e9sumer les mots de Sidi Ould Tah. Le d\u00e9sormais pr\u00e9sident de la premi\u00e8re institution financi\u00e8re d&rsquo;Afrique a pr\u00eat\u00e9 serment devant un parterre de personnalit\u00e9s venues des quatre coins du globe, avec la pr\u00e9sence en force du gouvernement ivoirien men\u00e9 par le pr\u00e9sident Alassane Ouattara, mais aussi celle du pr\u00e9sident mauritanien Mohamed Ould Ghazouani ou de R\u00e9my Rioux, directeur g\u00e9n\u00e9ral de l&rsquo;Agence fran\u00e7aise de d\u00e9veloppement (AFD). \u00c9lu en mai dernier lors des assembl\u00e9es annuelles de la Banque, Sidi Ould Tah s&rsquo;engage \u00e0 \u00ab b\u00e2tir une Afrique robuste et prosp\u00e8re \u00bb, confiant que \u00ab le continent africain continuera \u00e0 faire preuve de r\u00e9silience \u00bb.<\/p>\n<p>L&rsquo;\u00e9conomiste et banquier mauritanien prend ainsi les commandes de la BAD dans un contexte international tendu, entre les incertitudes li\u00e9es aux bouleversements g\u00e9opolitiques, la remise en cause du multilat\u00e9ralisme, le recul de l&rsquo;aide publique au d\u00e9veloppement, le fardeau de la dette pour de nombreux pays du continent, l&rsquo;impact n\u00e9gatif des changements climatiques ou encore les retards enregistr\u00e9s dans l&rsquo;atteinte des objectifs de d\u00e9veloppement durable (ODD) dont l&rsquo;\u00e9ch\u00e9ance arrive d\u00e9sormais dans cinq ans. \u00ab Il est l&rsquo;homme de la situation \u00bb, estime Ludovic Ngats\u00e9, ministre du Budget, des Comptes Publics et du Portefeuille Public du Congo Brazzaville et pr\u00e9sident du Conseil des gouverneurs de la BAD, soulignant que le programme de Sidi Ould Tah \u00ab est le mieux \u00e0 m\u00eame d&rsquo;apporter des r\u00e9ponses concr\u00e8tes aux incertitudes de notre temps \u00bb du point de vue de tous les actionnaires de la Banque.<\/p>\n<p>Pour Sidi Ould Tah qui salu\u00e9 le travail de son pr\u00e9d\u00e9cesseur Akinwumi Adesina, les d\u00e9fis auxquels l&rsquo;Afrique est confront\u00e9e imposent \u00e0 la Banque de \u00ab r\u00e9viser en toute urgence le sch\u00e9ma d&rsquo;investissements \u00bb, en mettant l&rsquo;accent sur les secteurs dans lesquels l&rsquo;institution a le plus d&rsquo;impact, notamment la paix, \u00ab sans laquelle aucun d\u00e9veloppement n&rsquo;est possible \u00bb. Il entend en outre amplifier la collaboration avec les gouvernements, le secteur priv\u00e9 et les partenaires internationaux. D&rsquo;ailleurs, le pr\u00e9sident de la BAD &#8211; qui a pour ambition de favoriser la cr\u00e9ation d&rsquo;\u00ab un cadre financier qui serve l&rsquo;Afrique selon ses propres conditions \u00bb &#8211; n&rsquo;\u00e9carte pas l&rsquo;id\u00e9e d&rsquo;\u00e9largir le partenariat de la Banque \u00e0 de nouveaux acteurs tels que les fonds souverains et les fonds de pension.<\/p>\n<p>Le leader mauritanien h\u00e9rite d&rsquo;une institution vieille de 61 ans, mais qui a b\u00e9n\u00e9fici\u00e9 au cours de la derni\u00e8re d\u00e9cennie de deux augmentations de capital, lequel s&rsquo;\u00e9l\u00e8ve d\u00e9sormais \u00e0 318 milliards de dollars. L&rsquo;institution se f\u00e9licite \u00e9galement d&rsquo;avoir d\u00e9bloqu\u00e9 102 milliards des financements du d\u00e9veloppement sur la p\u00e9riode et d&rsquo;avoir r\u00e9ussi \u00e0 maintenir sa notation de cr\u00e9dit AAA. Soulignant les nombreux atouts du continent africain, dont ses ressources naturelles et sa jeunesse, Sidi Ould Tah a pr\u00e9sent\u00e9 ce qu&rsquo;il appelle \u00ab les quatre points cardinaux \u00bb de sa strat\u00e9gie au cours de ses 100 premiers jours de leadership \u00e0 savoir l&rsquo;\u00e9coute attentive de l&rsquo;ensemble des collaborateurs de la BAD, le lancement d&rsquo;un programme de r\u00e9formes acc\u00e9l\u00e9r\u00e9, l&rsquo;approfondissement des partenariats et l&rsquo;acc\u00e9l\u00e9ration des solutions concr\u00e8tes.<\/p>\n<p>Les r\u00e9sultats de Sidi Ould Tah \u00e0\u00a0la Banque arabe de d\u00e9veloppement \u00e9conomique en Afrique (BADEA) et son long parcours \u00e0 la fois gouvernemental et institutionnel ont \u00e9t\u00e9 d\u00e9terminants dans sa victoire \u00e0 l&rsquo;\u00e9lection du pr\u00e9sident de la BAD. Ce docteur en \u00e9conomie et polyglotte &#8211; parlant couramment le fran\u00e7ais, l&rsquo;anglais et l&rsquo;arabe tout en ma\u00eetrisant le portugais et l&rsquo;espagnol &#8211; s&rsquo;est arrach\u00e9 la r\u00e9putation d&rsquo;\u00ab un bon gestionnaire et d&rsquo;un leader pragmatique \u00bb, confiait \u00e0 La Tribune Afrique un investisseur tchadien. Dans un continent o\u00f9 la transformation des ressources naturelles et le d\u00e9veloppement des infrastructures -pourtant constamment \u00e9rig\u00e9s en priorit\u00e9s- ont cependant souvent fait l&rsquo;objet de lenteur en termes de r\u00e9sultats dans de nombreux pays, le d\u00e9ploiement de la BAD au cours de ce mandat de cinq et renouvelable une fois, pourrait susciter une certaine expectative.<\/p>\n","protected":false},"excerpt":{"rendered":"La c\u00e9r\u00e9monie qui s&rsquo;est tenue ce lundi au Sofitel H\u00f4tel Ivoire d&rsquo;Abidjan, marque l&rsquo;ouverture d&rsquo;une nouvelle \u00e8re \u00e0&hellip;\n","protected":false},"author":2,"featured_media":17275,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[390,6,5213,2224,18,51,4759,8196,8199,8198,1632,8197,67,68,69,70],"class_list":{"0":"post-36503","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-390","9":"tag-afrique","10":"tag-bad","11":"tag-batir","12":"tag-europe","13":"tag-europe-afrique","14":"tag-finances-la-tribune-afrique","15":"tag-ould","16":"tag-robuste","17":"tag-sengage","18":"tag-sidi","19":"tag-tah","20":"tag-ue","21":"tag-ue-afrique","22":"tag-union-europeenne","23":"tag-union-europeenne-afrique"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116192768535592077","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/36503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=36503"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/36503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/17275"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=36503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=36503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=36503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}