{"id":42247,"date":"2026-03-13T16:09:11","date_gmt":"2026-03-13T16:09:11","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/42247\/"},"modified":"2026-03-13T16:09:11","modified_gmt":"2026-03-13T16:09:11","slug":"la-haye-le-maroc-elu-a-la-presidence-du-conseil-executif-de-loiac","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/42247\/","title":{"rendered":"La Haye : Le Maroc \u00e9lu \u00e0 la Pr\u00e9sidence du Conseil ex\u00e9cutif de l&rsquo;OIAC"},"content":{"rendered":"<p>Le Maroc vient d\u2019\u00eatre \u00e9lu par acclamation, \u00e0 La Haye, \u00e0 la Pr\u00e9sidence du Conseil Ex\u00e9cutif de l\u2019Organisation pour l\u2019Interdiction des Armes Chimiques (OIAC) au nom du Groupe africain, et ce pour un mandat d\u2019une ann\u00e9e \u00e0 partir du 12 mai prochain.<\/p>\n<p>Cette \u00e9lection, en la personne de Mohamed BASRI, Ambassadeur du Maroc aux Pays-Bas et repr\u00e9sentant permanent du Royaume aupr\u00e8s de l\u2019OIAC, intervient suite au soutien unanime apport\u00e9 par le groupe des Etats africains parties \u00e0 la Convention sur l\u2019interdiction des armes chimiques \u00e0 la candidature marocaine, ainsi que de l\u2019ensemble des Etats membres du Conseil ex\u00e9cutif.<br \/>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Le Maroc vient d\u2019\u00eatre \u00e9lu par acclamation, \u00e0 La Haye, \u00e0 la Pr\u00e9sidence du Conseil Ex\u00e9cutif de l\u2019Organisation&hellip;\n","protected":false},"author":2,"featured_media":42248,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[281,245,1124,1125,1122,1126,1121,86,133,1128,126,1123,46,1127],"class_list":{"0":"post-42247","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-maroc","8":"tag-actualite","9":"tag-culture","10":"tag-finance-economie","11":"tag-high-tech","12":"tag-infos","13":"tag-lifestyle","14":"tag-linformation-ma","15":"tag-maroc","16":"tag-monde","17":"tag-people","18":"tag-politique","19":"tag-site-infos","20":"tag-sport","21":"tag-videos"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116222739296525265","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/42247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=42247"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/42247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/42248"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=42247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=42247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=42247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}