{"id":44000,"date":"2026-03-15T11:32:06","date_gmt":"2026-03-15T11:32:06","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/44000\/"},"modified":"2026-03-15T11:32:06","modified_gmt":"2026-03-15T11:32:06","slug":"la-culture-provencale-sexporte-le-temps-dune-soiree","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/44000\/","title":{"rendered":"la culture proven\u00e7ale s&rsquo;exporte le temps d&rsquo;une soir\u00e9e"},"content":{"rendered":"<p>\u00ab\u00a0L&rsquo;ann\u00e9e derni\u00e8re nous avons assur\u00e9 70 repr\u00e9sentations et nous comptons bien continuer sur cette lanc\u00e9e en 2026\u00a0\u00bb, se r\u00e9jouit <a href=\"https:\/\/www.laprovence.com\/article\/culture-loisirs\/33464039317853\/le-groupe-bandura-de-maillane-a-fait-rayonner-la-provence-a-the-voice\" target=\"_blank\" rel=\"nofollow noopener\">Th\u00e9o Pastor<\/a>, cr\u00e9ateur et musicien du groupe Band\u00f9ra, qui r\u00e9invente le patrimoine proven\u00e7al.<br \/>Fond\u00e9 en septembre 2017, le groupe musical s&rsquo;est donn\u00e9 pour mission de r\u00e9interpr\u00e9ter des sons traditionnels avec une \u00e9nergie moderne. Ce ne sont pas moins de 25 musiciens, \u00e2g\u00e9s de 18 \u00e0 70 ans, ainsi que six danseuses, qui composent ce groupe. Guitare, cornemuse, fl\u00fbte, galoubet ou violon : chaque instrument trouve sa place dans ce dialogue entre hier et aujourd&rsquo;hui. Pour ce nouveau rendez-vous, le public d\u00e9couvrira \u00e9galement une nouvelle fl\u00fbtiste, <a href=\"https:\/\/www.laprovence.com\/article\/region\/4319881028080514\/a-eyragues-les-soeurs-pigaglio-proposent-un-concert-de-flute-et-harpe-en-avant-premiere-dimanche-4-mai-2025\" target=\"_blank\" rel=\"nofollow noopener\">Chlo\u00e9 Pigaglio<\/a>, dipl\u00f4m\u00e9e de la Haute \u00e9cole de musique de Lausanne.<\/p>\n<p>Dans le cadre des Journ\u00e9es de sensibilisation aux traditions proven\u00e7ales organis\u00e9es par la mairie de Ch\u00e2teaurenard, le groupe maillanais (dont la r\u00e9putation d\u00e9passe d\u00e9sormais les fronti\u00e8res des Bouches-du-Rh\u00f4ne) a \u00e9t\u00e9 invit\u00e9 pour un concert exceptionnel. En pr\u00e9sence d&rsquo;<a href=\"https:\/\/www.laprovence.com\/article\/region\/6572364234134715\/amelie-laugier-xxveme-reine-darles-jai-grandi-avec-ce-reve\" target=\"_blank\" rel=\"nofollow noopener\">Am\u00e9lie Laugier, Reine d&rsquo;Arles<\/a>, et de sa demoiselle d&rsquo;honneur, Band\u00f9ra prouvera une nouvelle fois sa renomm\u00e9e. Si le groupe reste profond\u00e9ment attach\u00e9 \u00e0 ses racines maillanaises, sa renomm\u00e9e a depuis longtemps franchi les fronti\u00e8res du d\u00e9partement. Du Maroc \u00e0 l&rsquo;\u00c9cosse, en passant par l&rsquo;Italie et New York, le groupe fait rayonner la culture proven\u00e7ale partout dans le monde. Un engagement qui se poursuivra en Bretagne en juin 2026, puis en Corse en 2027, avec quatre concerts, pour c\u00e9l\u00e9brer leurs dix ans.<br \/>Le samedi 28 mars 2026 \u00e0 20h (ouverture des portes \u00e0 partir de 19h15), la salle de l&rsquo;\u00c9toile de Ch\u00e2teaurenard vibrera au rythme d&rsquo;un spectacle total. V\u00e9ritable soir\u00e9e interg\u00e9n\u00e9rationnelle, la repr\u00e9sentation accueillera les jeunes danseuses proven\u00e7ales de l&rsquo;association du Moulin de Bretoule de Barbentane, ainsi que la chorale La Casca\u00efado de <a href=\"https:\/\/www.laprovence.com\/vaucluse\/l-isle-sur-la-sorgue-84054\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;Isle-sur-la-Sorgue<\/a>.<br \/>Durant 1h30, le r\u00e9pertoire surprendra par son dynamisme : des reprises de Queen et de Johnny Hallyday c\u00f4toieront des tableaux celtiques, proven\u00e7aux, tziganes, ou encore une s\u00e9quence de danse classique port\u00e9e par la talentueuse Toulonnaise Marie Barral.<\/p>\n<p>Enfin, le concert r\u00e9serve une surprise de taille : une annonce sp\u00e9ciale concernant le 10e anniversaire du groupe sera officiellement communiqu\u00e9e au public.<\/p>\n<p>15 \u20ac l&rsquo;entr\u00e9e et gratuit pour les moins de 12 ans.Pour plus d&rsquo;informations au 06 98 98 90 03 ou sur le site de la Salle de l&rsquo;\u00c9toile : https:\/\/www.etoile-chateaurenard.com\/spectacles\/.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00ab\u00a0L&rsquo;ann\u00e9e derni\u00e8re nous avons assur\u00e9 70 repr\u00e9sentations et nous comptons bien continuer sur cette lanc\u00e9e en 2026\u00a0\u00bb, se&hellip;\n","protected":false},"author":2,"featured_media":44001,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[58,245,3492,368,193,17844,17845,86,17846],"class_list":{"0":"post-44000","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-maroc","8":"tag-58","9":"tag-culture","10":"tag-ecosse","11":"tag-et","12":"tag-etats-unis","13":"tag-loisirs-traditions","14":"tag-maillane","15":"tag-maroc","16":"tag-provencale"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116232974679094247","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/44000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=44000"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/44000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/44001"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=44000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=44000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=44000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}