{"id":4572,"date":"2026-02-06T05:57:22","date_gmt":"2026-02-06T05:57:22","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/4572\/"},"modified":"2026-02-06T05:57:22","modified_gmt":"2026-02-06T05:57:22","slug":"en-cote-divoire-leconomie-peut-elle-supporter-le-coup-politique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/4572\/","title":{"rendered":"En C\u00f4te d\u2019Ivoire, l\u2019\u00e9conomie peut-elle supporter le coup politique ?"},"content":{"rendered":"<p>L&rsquo;heure est \u00e0 la c\u00e9l\u00e9bration des 65 ans d&rsquo;ind\u00e9pendance de la C\u00f4te d&rsquo;Ivoire, ce 7 ao\u00fbt, dont les festivit\u00e9s se tiennent exceptionnellement cette ann\u00e9e \u00e0 Bouak\u00e9, ville du centre du pays, o\u00f9 la France, le Maroc et les Etats-Unis participent au d\u00e9fil\u00e9 des militaires, sous le regard d&rsquo;Alassane Ouattara, son gouvernement et des citoyens ivoiriens. Dans son discours pour l&rsquo;occasion, le pr\u00e9sident &#8211; qui a suscit\u00e9 un toll\u00e9 le 29 juillet en annon\u00e7ant sa candidature \u00e0 la pr\u00e9sidentielle du 25 octobre prochain pour un quatri\u00e8me mandat &#8211; s&rsquo;est r\u00e9joui de la \u00ab r\u00e9silience \u00bb de son pays face aux \u00ab grandes incertitudes \u00bb r\u00e9gionales et internationales. \u00ab Nous avons su faire les bons choix, dans la rigueur et l&rsquo;anticipation, pour r\u00e9tablir les \u00e9quilibres macro-\u00e9conomiques, soutenir l&rsquo;activit\u00e9 \u00e9conomique et maintenir le cap du d\u00e9veloppement, tout en garantissant notre souverainet\u00e9 \u00bb, a-t-il d\u00e9clar\u00e9, soulignant la stabilit\u00e9, la s\u00e9curit\u00e9 et prosp\u00e9rit\u00e9 qui caract\u00e9risent son pays.<\/p>\n<p>Premier producteur mondial de cacao avec pr\u00e8s de 45% de la production plan\u00e9taire, la C\u00f4te d&rsquo;Ivoire est la premi\u00e8re \u00e9conomie de l&rsquo;Union \u00e9conomique et mon\u00e9taire d&rsquo;Afrique de l&rsquo;Ouest (UEMOA). Avec une croissance du PIB de 6% en 2024, cette destination phare des investissements en Afrique subsaharienne francophone, b\u00e9n\u00e9ficie de notations souveraines am\u00e9lior\u00e9es \u00e0 BB par les agences de notation depuis l&rsquo;an dernier, Fitch Ratings lui ayant attribu\u00e9 en juin 2025 la note de BB- avec perspectives stables. Plusieurs projets d&rsquo;envergure en cours ou pr\u00e9vus sont cens\u00e9s marquer davantage le d\u00e9veloppement du pays dans plusieurs secteurs : les mines avec le projet aurif\u00e8re de Kon\u00e9 ; les zones industrielles de Bouak\u00e9 et San Pedro ; le transport avec le projet de m\u00e9tro d&rsquo;Abidjan ou encore le gisement Baleine qui devrait porter la production nationale de p\u00e9trole \u00e0 200 000 barils par jour d&rsquo;ici 2027. Toute cette dynamique est \u00e9galement rehauss\u00e9e par la forte attractivit\u00e9 d&rsquo;Abidjan pour le tourisme d&rsquo;affaires avec notamment les multiples rendez-vous \u00e9conomiques internationaux qui \u00e9lisent r\u00e9guli\u00e8rement domicile dans la capitale ivoirienne.<\/p>\n","protected":false},"excerpt":{"rendered":"L&rsquo;heure est \u00e0 la c\u00e9l\u00e9bration des 65 ans d&rsquo;ind\u00e9pendance de la C\u00f4te d&rsquo;Ivoire, ce 7 ao\u00fbt, dont les&hellip;\n","protected":false},"author":2,"featured_media":4573,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[390,722,216,3024,723,1188,3022,126,3021,3023],"class_list":{"0":"post-4572","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cote-divoire","8":"tag-390","9":"tag-cote","10":"tag-cote-divoire","11":"tag-coup","12":"tag-divoire","13":"tag-leconomie","14":"tag-peut-elle","15":"tag-politique","16":"tag-politique-la-tribune-afrique","17":"tag-supporter"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116022151904727892","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/4572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=4572"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/4572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/4573"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=4572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=4572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=4572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}