{"id":48233,"date":"2026-03-19T07:01:06","date_gmt":"2026-03-19T07:01:06","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/48233\/"},"modified":"2026-03-19T07:01:06","modified_gmt":"2026-03-19T07:01:06","slug":"amedee-et-fatiah-collectent-des-fonds-pour-des-assos-dafrique-de-lest","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/48233\/","title":{"rendered":"Am\u00e9d\u00e9e et Fatiah collectent des fonds pour des assos d\u2019Afrique de l\u2019Est"},"content":{"rendered":"<p>\n                Article premium,<br \/>\n                    R\u00e9serv\u00e9 aux\u00a0abonn\u00e9s\n            <\/p>\n<p class=\"su-standfirst chapeau\">Samedi 4\u00a0avril 2026 \u00e0 19\u00a0h, l\u2019association Diriya organise une soir\u00e9e festive \u00e0 Ingrandes\u00a0(Maine-et-Loire) destin\u00e9e \u00e0 collecter des fonds pour les enfants de Djibouti et d\u2019\u00c9thiopie.<\/p>\n<p>                                        <img decoding=\"async\" class=\"su-media\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM.webp\" alt=\"L\u2019association d\u2019Ingrandes, Diriya, est partenaire d\u2019une association \u00e9thiopienne qui finance la scolarit\u00e9 d\u2019enfants d\u00e9favoris\u00e9s.\"  \/><\/p>\n<p>                            L\u2019association d\u2019Ingrandes, Diriya, est partenaire d\u2019une association \u00e9thiopienne qui finance la scolarit\u00e9 d\u2019enfants d\u00e9favoris\u00e9s. | OUEST-FRANCE<\/p>\n<p>                            fermer<\/p>\n<p><img decoding=\"async\" data-ofmaxheight=\"\" class=\"su-media lazyload\" alt=\"L\u2019association d\u2019Ingrandes, Diriya, est partenaire d\u2019une association \u00e9thiopienne qui finance la scolarit\u00e9 d\u2019enfants d\u00e9favoris\u00e9s.\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAYAAAA7KqwyAAAAGXRFWHRTb2Z0d2FyZQBBZG9iZSBJbWFnZVJlYWR5ccllPAAAABhJREFUeNpi\/P\/\/PwMlgHHUgFEDgAAgwAD+lBrvy+NcxAAAAABJRU5ErkJggg==\" data-oflazyload=\"{&quot;srcset&quot;:&quot;https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=320&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=aa561503b80ce21006484e42fcb9fe4bb079207eb0181ddbc2602f284609f330 320w,https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=375&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=d075593a72161f20754f7e0fd06273569333a01c25ee705900d77db37815bb28 360w,https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=480&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=b976af7963549ebf60f6d251717ead958c4ed2429580f67d4ebf95f2cdc17933 480w,https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=630&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=7db3220e5c93313acb3802a2a0dbc833e7fa59f9acedbfea9fb6c2f943e69000 630w,https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=940&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=af31fd90c8064637edeb1ad8cf6b19e1420cd7fd2f8f1e6e050b0ed219011ef4 940w,https:\/\/media.ouest-france.fr\/v1\/pictures\/MjAyNjAzM2RlNTI3NDU4OTRlNDczNGYwYWZmZWUzNDQ4YjViNWM?width=1260&amp;focuspoint=50%2C25&amp;cropresize=1&amp;client_id=bpeditorial&amp;sign=a5ea8304e14fb05d356d3ec05986c4df937325af7a4f5c4d0cbd337b0365d001 1260w&quot;}\"\/>L\u2019association d\u2019Ingrandes, Diriya, est partenaire d\u2019une association \u00e9thiopienne qui finance la scolarit\u00e9 d\u2019enfants d\u00e9favoris\u00e9s. | OUEST-FRANCE                            <\/p>\n<p>        Publi\u00e9 le 19\/03\/2026  \u00e0 07h32<\/p>\n<p>                            Lire plus tard<\/p>\n<p>                            Partager<\/p>\n<p>                        FacebookFacebookBlueSkyBlueSkyFlipboardFlipboardlinkedinLinkedIn<\/p>\n<p class=\"su-h3 su-margin-bottom-xs\">Newsletter La Matinale<\/p>\n<p>Chaque matin, l\u2019actualit\u00e9 du jour s\u00e9lectionn\u00e9e par Ouest-France<\/p>\n<p class=\"su-margin-top-s su-text-xsmall texte-rgpd su-hidden\">Votre e-mail, avec votre consentement, est utilis\u00e9 par Ouest-France pour recevoir notre newsletter. <a class=\"su-link-light\" href=\"https:\/\/www.ouest-france.fr\/politique-de-protection-des-donnees-personnelles\/\" rel=\"nofollow noopener\" target=\"_blank\">En\u00a0savoir\u00a0plus<\/a>.<\/p>\n<p>Diriya en langue somali signifie donner de la chaleur humaine explique Am\u00e9d\u00e9e Leclercq. C\u2019est le nom l\u2019association qu\u2019il a cr\u00e9\u00e9e en 2012 avec son \u00e9pouse Fatiah, originaire du Somaliland, \u00e0 Ingrandes\u00a0(Maine-et-Loire). J\u2019ai travaill\u00e9 pendant 10\u00a0ans comme g\u00e9om\u00e8tre dans la r\u00e9gion de Djibouti. C\u2019est l\u00e0 que j\u2019ai rencontr\u00e9 ma femme. Quand nous sommes rentr\u00e9s en France, nous avons voulu rester en lien avec cette r\u00e9gion du monde et lui tendre la main. Alors, nous avons cr\u00e9\u00e9 Diriya&#8230;<\/p>\n<p style=\"text-align: center;\">Offre sans engagement<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\">\u2713 L&rsquo;acc\u00e8s \u00e0 tous les articles<br \/>\u2713 Le journal num\u00e9rique d\u00e8s 5h<\/p>\n<p style=\"text-align: center;\">\u2713 Lecture sans publicit\u00e9<\/p>\n<p style=\"text-align: center; padding-bottom: 10px;\"><a data-ida=\"\" data-trkartmonet=\"Tunnel OF+\" data-trk-sipa=\"{&#010;\" blockcategory=\"\" paywall=\"\" :=\"\" m=\"\" of=\"\" class=\"&#010;        su-button&#010;        su-primary&#010;        &#010;        &#010;    \" data-trk-bloc=\"paywall\" href=\"https:\/\/abonnement.ouest-france.fr\/tunnel\/pack-numerique-jeux-article\/122099116100?int_medium=lien&amp;int_campaign=PW-PN3M3-V2MUNICIPALES-OF&amp;int_content=page-article-payant_boutonjaune-paywall&amp;marquesource=OF&amp;rt=https:\/\/www.ouest-france.fr\/associations\/rester-en-lien-avec-cette-region-du-monde-amedee-et-fatiah-collectent-des-fonds-pour-des-assos-dafrique-de-lest-089592dc-2247-11f1-b886-f0257df9f01f\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n    Je m&rsquo;abonne<br \/>\n<\/a><\/p>\n<p style=\"text-align: center;\">ou<\/p>\n<p style=\"text-align: center;\">Jusqu&rsquo;\u00e0 -75% la premi\u00e8re ann\u00e9e<\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\">D\u00e9j\u00e0 abonn\u00e9 ? <a data-trkartmonet=\"Identification\" data-trk-sipa=\"{\" blockcategory=\"\" paywall=\"\" href=\"http:\/\/www.ouest-france.fr\/login?redirect=https:\/\/www.ouest-france.fr\/associations\/rester-en-lien-avec-cette-region-du-monde-amedee-et-fatiah-collectent-des-fonds-pour-des-assos-dafrique-de-lest-089592dc-2247-11f1-b886-f0257df9f01f\" rel=\"nofollow noopener\" title=\"Se connecter \u00e0 Ouest-France\" class=\"su-link-light\" target=\"_blank\">Connectez-vous<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Article premium, R\u00e9serv\u00e9 aux\u00a0abonn\u00e9s Samedi 4\u00a0avril 2026 \u00e0 19\u00a0h, l\u2019association Diriya organise une soir\u00e9e festive \u00e0 Ingrandes\u00a0(Maine-et-Loire) destin\u00e9e&hellip;\n","protected":false},"author":2,"featured_media":48234,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[5042,3576,19121,7171,2846,262,19122,7173,7176,7175],"class_list":{"0":"post-48233","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ethiopie","8":"tag-angers","9":"tag-associations","10":"tag-benevole","11":"tag-cholet","12":"tag-djibouti","13":"tag-ethiopie","14":"tag-ingrandes-le-fresne-sur-loire","15":"tag-maine-et-loire","16":"tag-saumur","17":"tag-segre-en-anjou-bleu"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116254558319751703","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/48233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=48233"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/48233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/48234"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=48233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=48233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=48233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}