{"id":49417,"date":"2026-03-20T08:41:14","date_gmt":"2026-03-20T08:41:14","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/49417\/"},"modified":"2026-03-20T08:41:14","modified_gmt":"2026-03-20T08:41:14","slug":"les-valeurs-a-suivre-a-paris-et-en-europe-actualise-20-03-2026-a-0854","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/49417\/","title":{"rendered":"Les valeurs \u00e0 suivre \u00e0 Paris et en Europe (actualis\u00e9) &#8211; 20\/03\/2026 \u00e0 08:54"},"content":{"rendered":"<p>\n (Actualis\u00e9 avec Alstom, pr\u00e9cisions sur Unilever, Thyssenkrupp<br \/>\nSmiths Group, DHL, Infineon)\n<\/p>\n<p>\n Les valeurs \u00e0 suivre vendredi<br \/>\n\u00e0 la Bourse de Paris et en Europe :\n<\/p>\n<p>\n * ALSTOM<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1rPALO\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  ALSO.PA<br \/>\n <\/a><br \/>\n a annonc\u00e9 vendredi avoir prolong\u00e9 son<br \/>\ncontrat d&rsquo;exploitation et de maintenance avec Metrolinx,<br \/>\nl&rsquo;agence publique de transport de l&rsquo;Ontario, au Canada, pour<br \/>\nenviron 800 millions d&rsquo;euros.\n<\/p>\n<p>\n * INFINEON<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zIFX\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  IFXGn.DE<br \/>\n <\/a><br \/>\n &#8211; JP Morgan a relev\u00e9 sa recommandation<br \/>\nsur le groupe allemand de semi-conducteurs \u00e0 \u00ab\u00a0surpond\u00e9rer\u00a0\u00bb,<br \/>\nestimant qu&rsquo;il sera l&rsquo;un des principaux b\u00e9n\u00e9ficiaires de la<br \/>\ncroissance de la demande en semi-conducteurs de puissance<br \/>\ndestin\u00e9s \u00e0 l&rsquo;intelligence artificielle. L&rsquo;action prend 4,6% en<br \/>\navant-Bourse.\n<\/p>\n<p>\n * BOUYGUES<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1rPEN\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  BOUY.PA<br \/>\n <\/a><br \/>\n &#8211; Colas, filiale du groupe fran\u00e7ais, a<br \/>\nannonc\u00e9 vendredi le groupe la signature d&rsquo;un accord pour<br \/>\nacqu\u00e9rir les activit\u00e9s routi\u00e8res et de recyclage de Frauenrath<br \/>\nen Allemagne.\n<\/p>\n<p>\n * EXAIL TECHNOLOGIES<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1rPEXA\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  EXA.PA<br \/>\n <\/a><br \/>\n a annonc\u00e9 vendredi avoir<br \/>\nd\u00e9cid\u00e9 de r\u00e9duire son capital social par voie d&rsquo;annulation de<br \/>\n380.000 actions.\n<\/p>\n<p>\n * Le groupe autrichien OMV<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2u0MKH.LQ\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  OMVV.VI<br \/>\n <\/a><br \/>\n et la compagnie<br \/>\np\u00e9troli\u00e8re nationale d&rsquo;Abu Dhabi ADNOC pr\u00e9voient de finaliser<br \/>\nd&rsquo;ici la fin du mois de mars une m\u00e9gafusion pour cr\u00e9er un g\u00e9ant<br \/>\nmondial de la chimie, ont annonc\u00e9 jeudi les deux soci\u00e9t\u00e9s, apr\u00e8s<br \/>\ndes ann\u00e9es de n\u00e9gociations.\n<\/p>\n<p>\n * UNILEVER<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uULVR.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  ULVR.L<br \/>\n <\/a><br \/>\n a d\u00e9clar\u00e9 vendredi \u00eatre en discussions<br \/>\navec la soci\u00e9t\u00e9 am\u00e9ricaine MCCORMICK &amp; COMPANY<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/MKC\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  MKC.N<br \/>\n <\/a><br \/>\n en vue de<br \/>\nlui vendre son activit\u00e9 agroalimentaire, qui comprend des<br \/>\nmarques telles que la mayonnaise Hellmann&rsquo;s ainsi que les soupes<br \/>\net assaisonnements Knorr.\n<\/p>\n<p>\n * ELMOS SEMICONDUCTOR<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zELG\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  ELGG.DE<br \/>\n <\/a><br \/>\n envisage une cession, ses<br \/>\nfondateurs souhaitant se retirer de l&rsquo;entreprise, selon trois<br \/>\nsources au fait du dossier.\n<\/p>\n<p>\n * NOVARTIS<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2aNOVN\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  NOVN.S<br \/>\n <\/a><br \/>\n a annonc\u00e9 vendredi avoir conclu un<br \/>\naccord en vue d&rsquo;acqu\u00e9rir le candidat-m\u00e9dicament contre le cancer<br \/>\ndu sein SNV4818 aupr\u00e8s de Synnovation Therapeutics, moyennant un<br \/>\npaiement initial de deux milliards de dollars et jusqu&rsquo;\u00e0 un<br \/>\nmilliard de dollars suppl\u00e9mentaires en fonction des r\u00e9sultats<br \/>\nobtenus lors des phases de d\u00e9veloppement ult\u00e9rieures.\n<\/p>\n<p>\n * THYSSENKRUPP<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zTKA\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  TKAG.DE<br \/>\n <\/a><br \/>\n &#8211; Les n\u00e9gociations visant \u00e0 c\u00e9der<br \/>\nla division sid\u00e9rurgique de \u00e0 la soci\u00e9t\u00e9 indienne Jindal Steel<br \/>\nInternational n&rsquo;avancent pas, a d\u00e9clar\u00e9 vendredi le<br \/>\nvice-pr\u00e9sident du conseil de surveillance de l&rsquo;entreprise<br \/>\nallemande, ce qui fait craindre que cette transaction tant<br \/>\nattendue ne se concr\u00e9tise pas.\n<\/p>\n<p>\n * SMITHS GROUP<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uSMIN.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  SMIN.L<br \/>\n <\/a><br \/>\n &#8211; Le groupe d&rsquo;ing\u00e9nierie britannique<br \/>\na dit vendredi pr\u00e9voir une croissance organique de son chiffre<br \/>\nd&rsquo;affaires comprise entre 3% et 4% pour 2026 et a annonc\u00e9 qu&rsquo;il<br \/>\nallait reverser 1,5 milliard de livres sterling suppl\u00e9mentaires<br \/>\n\u00e0 ses actionnaires.\n<\/p>\n<p>\n * DHL GROUP<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zDHL\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  DHLn.DE<br \/>\n <\/a><br \/>\n &#8211; L&rsquo;action prend de 2% avant la<br \/>\ncloche, dans le sillage des r\u00e9sultats au troisi\u00e8me trimestre de<br \/>\nFedEx<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/FDX\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  FDX.N<br \/>\n <\/a><br \/>\n .\n<\/p>\n<p>\n * BRIDGEPOINT<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uBPT.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  BPTB.L<br \/>\n <\/a><br \/>\n &#8211; La soci\u00e9t\u00e9 de rachat pr\u00e9pare<br \/>\nactuellement des propositions en vue d&rsquo;une offre sur l&rsquo;op\u00e9rateur<br \/>\nhospitalier priv\u00e9 britannique SPIRE HEALTHCARE<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uSPI.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  SPI.L<br \/>\n <\/a><br \/>\n , a<br \/>\nrapport\u00e9 jeudi Sky News.\n<\/p>\n<p>\n * La Haute Cour de Singapour a rejet\u00e9 la demande de STANDARD<br \/>\nCHARTERED<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uSTAN.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  STAN.L<br \/>\n <\/a><br \/>\n et de la BSI Bank visant \u00e0 \u00eatre entendues<br \/>\ndans le cadre de la proc\u00e9dure de liquidation de certaines<br \/>\nentit\u00e9s \u00e9trang\u00e8res, dans le but de r\u00e9cup\u00e9rer des actifs li\u00e9s au<br \/>\nfonds souverain malaisien 1MDB, \u00e9clabouss\u00e9 par un scandale,<br \/>\nselon un jugement rendu jeudi.\n<\/p>\n<p>\n * JD WETHERSPOON<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uJDW.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  JDW.L<br \/>\n <\/a><br \/>\n &#8211; La cha\u00eene britannique de pubs a<br \/>\naverti vendredi que son b\u00e9n\u00e9fice pourrait s&rsquo;av\u00e9rer inf\u00e9rieur aux<br \/>\nestimations, en raison de la hausse des co\u00fbts \u00e9nerg\u00e9tiques et<br \/>\nfiscaux, ainsi que du ralentissement des d\u00e9penses de<br \/>\nconsommation.\n<\/p>\n<p>\n L&rsquo;AGENDA FRANCE &amp; INTERNATIONAL \u00c0 7 JOURS:<br \/>\n nL8N4010L4\n<\/p>\n<p>\n (R\u00e9dig\u00e9 par Claude Chendjou et Diana Mandi\u00e1, \u00e9dit\u00e9 par Augustin<br \/>\nTurpin)<\/p>\n","protected":false},"excerpt":{"rendered":"(Actualis\u00e9 avec Alstom, pr\u00e9cisions sur Unilever, Thyssenkrupp Smiths Group, DHL, Infineon) Les valeurs \u00e0 suivre vendredi \u00e0 la&hellip;\n","protected":false},"author":2,"featured_media":4539,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[593,591,601,598,18,596,595,592,597,594,599,600],"class_list":{"0":"post-49417","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-europe","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116260613842356459","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/49417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=49417"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/49417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/4539"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=49417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=49417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=49417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}