{"id":53187,"date":"2026-03-24T08:08:11","date_gmt":"2026-03-24T08:08:11","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/53187\/"},"modified":"2026-03-24T08:08:11","modified_gmt":"2026-03-24T08:08:11","slug":"en-cote-divoire-le-casse-tete-des-stocks-de-cacao-qui-saccumulent-24-03-2026-a-0817","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/53187\/","title":{"rendered":"En C\u00f4te d&rsquo;Ivoire, le \u00ab\u00a0casse-t\u00eate\u00a0\u00bb des stocks de cacao qui s&rsquo;accumulent &#8211; 24\/03\/2026 \u00e0 08:17"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/196091bfa67d56b09f3cf3b5cad77be5-760x507.jpg\" alt=\"Des ouvriers ramassent des f\u00e8ves de cacao sur la place d'Aboisso, dans le sud-est ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Des ouvriers ramassent des f\u00e8ves de cacao sur la place d&rsquo;Aboisso, dans le sud-est ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )<\/p>\n<p>\n Sur la place d&rsquo;Aboisso, dans le sud-est ivoirien, des f\u00e8ves de cacao s\u00e8chent sur des b\u00e2ches au soleil avant de retourner dans leur hangar, o\u00f9 elles s&rsquo;ab\u00eement depuis plusieurs mois dans l&rsquo;humidit\u00e9, symbole d&rsquo;une crise qui persiste dans le secteur.\n<\/p>\n<p>\n En C\u00f4te d&rsquo;Ivoire, premier exportateur mondial d&rsquo;or brun, le prix d&rsquo;achat aux planteurs est fix\u00e9 par l&rsquo;Etat et d\u00e9but octobre, juste avant la pr\u00e9sidentielle qui a vu la r\u00e9\u00e9lection d&rsquo;Alassane Ouattara, il avait atteint 2.800 francs CFA le kilo (4,27 euros), du jamais vu dans le pays.\n<\/p>\n<p>\n Mais apr\u00e8s avoir atteint des sommets fin 2024, les cours mondiaux du cacao avaient d\u00e9j\u00e0 commenc\u00e9 \u00e0 d\u00e9visser \u00e0 l&rsquo;\u00e9t\u00e9 2025, notamment en raison du retour d&rsquo;une production abondante apr\u00e8s des ann\u00e9es de p\u00e9nurie, et le prix d&rsquo;achat ivoirien est ainsi devenu trop \u00e9lev\u00e9.\n<\/p>\n<p>\n R\u00e9sultat, les exportations ont ralenti, les stocks se sont entass\u00e9s dans les entrep\u00f4ts des coop\u00e9ratives agricoles &#8211; interm\u00e9diaire entre producteurs et exportateurs tels des d\u00e9p\u00f4ts-ventes &#8211;  et beaucoup de planteurs n&rsquo;ont pas \u00e9t\u00e9 pay\u00e9s.\n<\/p>\n<p>\n Pour ces derniers, la douche froide redout\u00e9e est arriv\u00e9e d\u00e9but mars.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/3760477bce9e338b792fb7d063308756-760x507.jpg\" alt=\"Le g\u00e9rant d'une coop\u00e9rative agricole inspecte les stocks de cacao dans un entrep\u00f4t \u00e0 Aboisso, dans le sud ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Le g\u00e9rant d&rsquo;une coop\u00e9rative agricole inspecte les stocks de cacao dans un entrep\u00f4t \u00e0 Aboisso, dans le sud ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )<\/p>\n<p>\n Afin d&rsquo;enrayer la crise dans un secteur qui p\u00e8se 14% du PIB et fait vivre 5 millions de personnes, le gouvernement ivoirien a drastiquement baiss\u00e9 le prix d&rsquo;achat du cacao aux planteurs, \u00e0 1.200 francs (1,82 euro).\n<\/p>\n<p>\n Quelques semaines apr\u00e8s cette d\u00e9cision, dans les hangars d&rsquo;Aboisso, les f\u00e8ves continuent de s&rsquo;ab\u00eemer au contact prolong\u00e9 de l&rsquo;humidit\u00e9 tropicale.\n<\/p>\n<p>\n \u00ab\u00a0On est oblig\u00e9s, de temps en temps, de les exposer au soleil pour limiter les d\u00e9g\u00e2ts. Sinon la moisissure rentre dans le produit et on ne saura pas o\u00f9 le vendre\u00a0\u00bb, explique \u00e0 l&rsquo;AFP Dongo Yao Kra, 49 ans, pr\u00e9sident de la coop\u00e9rative Socoopagos qui travaille avec quelque 2.300 producteurs de la r\u00e9gion du Sud-Como\u00e9.\n<\/p>\n<p>\n Ce processus de s\u00e9chage a un co\u00fbt: \u00ab\u00a0plus on perd du temps, plus on perd en qualit\u00e9\u00a0\u00bb, ajoute t-il, soulignant un manque \u00e0 gagner suppl\u00e9mentaire pour la coop\u00e9rative.\n<\/p>\n<p>\n Une partie de ce stock concerne la r\u00e9colte faite avant la baisse du prix du cacao, et la coop\u00e9rative s&rsquo;\u00e9tait engag\u00e9e \u00e0 l&rsquo;honorer aupr\u00e8s des producteurs \u00e0 2.800 francs le kilo.\n<\/p>\n<p>\n \u00ab\u00a0C&rsquo;est un v\u00e9ritable casse-t\u00eate chinois\u00a0\u00bb, r\u00e9sume M. Yao Kra qui \u00e9value le co\u00fbt total qu&rsquo;il devrait d\u00e9bourser \u00e0 230 millions de francs CFA (350.000 euros), une somme introuvable dans sa tr\u00e9sorerie.\n<\/p>\n<p> &#8211; \u00ab\u00a0Il faut qu&rsquo;on nous respecte\u00a0\u00bb &#8211;<\/p>\n<p>\n La semaine derni\u00e8re, une r\u00e9union de crise convoqu\u00e9e par la coop\u00e9rative a rassembl\u00e9 une cinquantaine de planteurs \u00e0 Songan, un village \u00e0 trois heures de piste au nord d&rsquo;Aboisso.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/5994ce9a9145a095af3108fd54deb1e2-760x507.jpg\" alt=\"Des employ\u00e9s ferment des sacs de f\u00e8ve de cacao le 17 mars 2026 \u00e0 Aboisso, dans le sud ivoirien ( AFP \/ Sia KAMBOU )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Des employ\u00e9s ferment des sacs de f\u00e8ve de cacao le 17 mars 2026 \u00e0 Aboisso, dans le sud ivoirien ( AFP \/ Sia KAMBOU )<\/p>\n<p>\n Au milieu des \u00e9changes m\u00e9contents, en fran\u00e7ais ou en malink\u00e9, on s&rsquo;indigne du timing de cette baisse du prix du cacao.\n<\/p>\n<p>\n \u00ab\u00a0C&rsquo;est comme si on avait arr\u00eat\u00e9 un match de foot en plein milieu pour changer les r\u00e8gles\u00a0\u00bb, d\u00e9nonce avec v\u00e9h\u00e9mence Antoine Ouattara Si\u00e9 Kouabou, 54 ans et p\u00e8re de cinq enfants, qui attend toujours son d\u00fb pour sa production de 830 kilos.\n<\/p>\n<p>\n Certains producteurs craignent m\u00eame de retourner dans leurs champs, o\u00f9 la main d&rsquo;\u0153uvre qu&rsquo;ils emploient d&rsquo;ordinaire attend elle aussi d&rsquo;\u00eatre r\u00e9mun\u00e9r\u00e9e.\n<\/p>\n<p>\n En janvier pourtant, le Conseil Caf\u00e9 Cacao (CCC), organe r\u00e9gulateur de la fili\u00e8re, s&rsquo;\u00e9tait engag\u00e9 \u00e0 racheter les volumes n&rsquo;ayant pas trouv\u00e9 preneur, mais \u00e0 ce jour, dans la coop\u00e9rative, seules 45 sur 380 tonnes ont \u00e9t\u00e9 enlev\u00e9es.\n<\/p>\n<p>\n D&rsquo;aucuns regrettent aussi que la \u00ab\u00a0promesse\u00a0\u00bb de l&rsquo;\u00c9tat de garantir le prix du cacao par temps difficiles, via un fond de r\u00e9serve du CCC, n&rsquo;ait pas \u00e9t\u00e9 tenue.\n<\/p>\n<p>\n \u00ab\u00a0C&rsquo;est une arnaque, ils nous ont tromp\u00e9s\u00a0\u00bb, d\u00e9plore Dolford Diby, 55 ans, qui survit aujourd&rsquo;hui gr\u00e2ce \u00e0 ses autres activit\u00e9s, la culture de l&rsquo;h\u00e9v\u00e9a et l&rsquo;\u00e9levage de porcs.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/02bd16d6a0c1e1a47783fdcfae617584-760x507.jpg\" alt=\"Des producteurs de cacao brandissent des re\u00e7us montrant qu'ils n'ont toujours pas \u00e9t\u00e9 pay\u00e9s, lors d'une r\u00e9union avec les coop\u00e9ratives d'achat, \u00e0 Songan, un village pr\u00e8s d'Aboisso, dans le sud ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Des producteurs de cacao brandissent des re\u00e7us montrant qu&rsquo;ils n&rsquo;ont toujours pas \u00e9t\u00e9 pay\u00e9s, lors d&rsquo;une r\u00e9union avec les coop\u00e9ratives d&rsquo;achat, \u00e0 Songan, un village pr\u00e8s d&rsquo;Aboisso, dans le sud ivoirien, le 17 mars 2026 ( AFP \/ Sia KAMBOU )<\/p>\n<p>\n \u00ab\u00a0Ce pays repose sur l&rsquo;agriculture, il faut qu&rsquo;on nous respecte\u00a0\u00bb, ajoute-t-il.\n<\/p>\n<p>\n Alors on tente le tout pour le tout. S&rsquo;agissant de la production ant\u00e9rieure \u00e0 mars: \u00ab\u00a0Accepteriez-vous d&rsquo;\u00eatre pay\u00e9s \u00e0 1.200 francs ?\u00a0\u00bb, lance un membre de la coop\u00e9rative \u00e0 l&rsquo;assembl\u00e9e des planteurs.\n<\/p>\n<p>\n Les sourcils se froncent et les voix grondent. \u00ab\u00a0Non!\u00a0\u00bb, r\u00e9pond l&rsquo;un, se levant de sa chaise. \u00ab\u00a0On n&rsquo;est pas d&rsquo;accord!\u00a0\u00bb, rench\u00e9rit un autre, brandissant un re\u00e7u o\u00f9 il est \u00e9crit noir sur blanc qu&rsquo;il serait pay\u00e9 2.800 francs le kilo.\n<\/p>\n<p>\n M\u00eame son de cloche dans l&rsquo;ouest de la C\u00f4te d&rsquo;Ivoire, \u00e0 Du\u00e9kou\u00e9, rapporte \u00e0 l&rsquo;AFP le planteur et syndicaliste Yao Yao. \u00ab\u00a0C&rsquo;est l&rsquo;\u00c9tat qui doit prendre les choses en main, ou bien les exportateurs\u00a0\u00bb, estime-t-il.\n<\/p>\n<p>\n Mercredi, le vice-pr\u00e9sident de l&rsquo;interprofession du cacao (OIA), Obed Blond\u00e9 Doua, a fait savoir \u00e0 la presse qu&rsquo;il restait \u00ab\u00a0entre 57.000 et 60.000 tonnes\u00a0\u00bb de cacao \u00e0 enlever sur les 100.000 initialement recens\u00e9es.\n<\/p>\n<p>\n Deux semaines plus t\u00f4t, le ministre Bruno Kon\u00e9 indiquait lui sur RFI que 64.000 tonnes avaient d\u00e9j\u00e0 \u00e9t\u00e9 achet\u00e9es.\n<\/p>\n<p>\n Le CCC n&rsquo;a pas r\u00e9pondu aux sollicitations de l&rsquo;AFP.\n<\/p>\n<p>\n \u00ab\u00a0Faisons en sorte que les producteurs puissent gagner les 2.800 francs sur le stock r\u00e9siduel\u00a0\u00bb, a encourag\u00e9 M. Blond\u00e9 Doua, \u00ab\u00a0pour que le climat social puisse \u00eatre paisible\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"Des ouvriers ramassent des f\u00e8ves de cacao sur la place d&rsquo;Aboisso, dans le sud-est ivoirien, le 17 mars&hellip;\n","protected":false},"author":2,"featured_media":53188,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[593,591,601,598,216,596,595,592,597,594,599,600],"class_list":{"0":"post-53187","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cote-divoire","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-cote-divoire","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116283133327628796","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/53187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=53187"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/53187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/53188"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=53187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=53187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=53187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}