{"id":53971,"date":"2026-03-24T21:49:17","date_gmt":"2026-03-24T21:49:17","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/53971\/"},"modified":"2026-03-24T21:49:17","modified_gmt":"2026-03-24T21:49:17","slug":"leurope-finit-sur-de-faibles-variations-dans-des-echanges-prudents-24-03-2026-a-1807","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/53971\/","title":{"rendered":"L&rsquo;Europe finit sur de faibles variations dans des \u00e9changes prudents &#8211; 24\/03\/2026 \u00e0 18:07"},"content":{"rendered":"<p>\n *    En Europe, le CAC 40 a gagn\u00e9 0,23% et le Stoxx 600 0,46%\n<\/p>\n<p>\n *    Wall Street h\u00e9site en raison de l&rsquo;incertitude au Moyen-Orient\n<\/p>\n<p>\n *    Isra\u00ebl entend contr\u00f4ler le sud du fleuve Litani au Liban\n<\/p>\n<p>\n *    Les cours du p\u00e9trole bondissent de pr\u00e8s de 5%\n<\/p>\n<p>\n par Claude Chendjou\n<\/p>\n<p>\n Les Bourses europ\u00e9ennes ont termin\u00e9 mardi sur<br \/>\nde faibles variations dans des \u00e9changes domin\u00e9s par la prudence dans un contexte<br \/>\nd&rsquo;incertitude persistante au Moyen-Orient au 25e jour de guerre men\u00e9e par Isra\u00ebl<br \/>\net les Etats-Unis contre l&rsquo;Iran.\n<\/p>\n<p>\n \u00c0 Paris, le CAC 40<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1rPCAC\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .FCHI<br \/>\n <\/a><br \/>\n a fini sur un gain de 0,23% \u00e0 7.743,92 points, \u00e0<br \/>\nl&rsquo;issue d&rsquo;une s\u00e9ance volatile. Le Footsie britannique<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/UKX.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .FTSE<br \/>\n <\/a><br \/>\n a avanc\u00e9 de 0,60%,<br \/>\nmais le Dax allemand<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/5pDAX\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .GDAXI<br \/>\n <\/a><br \/>\n a reflu\u00e9 de 0,06%.\n<\/p>\n<p>\n L&rsquo;indice EuroStoxx 50<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2cSX5E\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .STOXX50E<br \/>\n <\/a><br \/>\n a gagn\u00e9 0,19%, le FTSEurofirst 300\n<\/p>\n<p>\n <a href=\"https:\/\/www.boursorama.com\/cours\/3uE3X3760.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .FTEU3<br \/>\n <\/a><br \/>\n 0,45% et le Stoxx 600<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2cSXXP\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .STOXX<br \/>\n <\/a><br \/>\n 0,46%.\n<\/p>\n<p>\n Au moment de la cl\u00f4ture en Europe, le Dow Jones<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/%24INDU\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .DJI<br \/>\n <\/a><br \/>\n grappille 0,19%, mais<br \/>\nle Standard &amp; Poor&rsquo;s 500<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/%24INX\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .SPX<br \/>\n <\/a><br \/>\n perd 0,01% et le Nasdaq<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/%24COMPX\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .IXIC<br \/>\n <\/a><br \/>\n abandonne 0,47%\n<\/p>\n<p>\n Face aux d\u00e9clarations contradictoires des Etats-Unis et de l&rsquo;Iran, les<br \/>\npremiers laissant esp\u00e9rer un r\u00e8glement diplomatique du conflit, le deuxi\u00e8me<br \/>\nd\u00e9mentant tout contact, le doute est revenu sur les march\u00e9s apr\u00e8s le bref<br \/>\nsoulagement de la veille.\n<\/p>\n<p>\n Parall\u00e8lement, l&rsquo;Iran et Isra\u00ebl poursuivaient mardi leurs \u00e9changes de tirs<br \/>\nde missiles, tandis que Tsahal entend contr\u00f4ler une partie du sud du Liban<br \/>\ns&rsquo;\u00e9tendant jusqu&rsquo;au fleuve Litani, signe que le conflit est loin d&rsquo;\u00eatre termin\u00e9.\n<\/p>\n<p>\n \u00ab\u00a0C&rsquo;est comme (recevoir) un coup de fouet. Vous vous r\u00e9veillez tous les<br \/>\nmatins en vous demandant ce qui va se passer encore (&#8230;)\u00a0\u00bb, r\u00e9sume Christopher<br \/>\nO&rsquo;Keefe, gestionnaire de portefeuille chez Logan Capital Management.\n<\/p>\n<p>\n Dans ce contexte, les indices mesurant la peur \u00e0 Wall Street et sur<br \/>\nl&rsquo;EuroStoxx 50  .VIX .V2TX  sont rest\u00e9s \u00e0 des niveaux \u00e9lev\u00e9s, proches des 30<br \/>\npoints, tandis que les cours du p\u00e9trole sont repartis \u00e0 la hausse et les<br \/>\nrendements obligataires \u00e0 nouveau sous tension.\n<\/p>\n<p>\n VALEURS EN EUROPE\n<\/p>\n<p>\n Le compartiment europ\u00e9en de l&rsquo;\u00e9nergie<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2cSXEP\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  .SXEP<br \/>\n <\/a><br \/>\n s&rsquo;est distingu\u00e9 avec un gain<br \/>\nde 2,32%, suivant le rebond des cours du p\u00e9trole et du gaz.\n<\/p>\n<p>\n Puig<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/FF55-PUIG\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  PUIGb.MC<br \/>\n <\/a><br \/>\n a bondi de 12,97%, le groupe espagnol de produits de beaut\u00e9<br \/>\nayant confirm\u00e9 \u00eatre en discussions avec Est\u00e9e Lauder<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/EL\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  EL.N<br \/>\n <\/a><br \/>\n en vue d&rsquo;une fusion.\n<\/p>\n<p>\n Bayer<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zBAYN\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  BAYGn.DE<br \/>\n <\/a><br \/>\n a recul\u00e9 de 1,88% apr\u00e8s une information selon laquelle<br \/>\nInclusive Capital Partners envisage de c\u00e9der une participation qu&rsquo;il d\u00e9tient<br \/>\ndans le groupe.\n<\/p>\n<p>\n Kingfisher<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1uKGF.L\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  KGF.L<br \/>\n <\/a><br \/>\n a fini en repli de 2,29% apr\u00e8s la publication de ses<br \/>\nr\u00e9sultats annuels.\n<\/p>\n<p>\n SAP<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1zSAP\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  SAPG.DE<br \/>\n <\/a><br \/>\n a abandonn\u00e9 4,06%, JPMorgan ayant abaiss\u00e9 sa recommandation<br \/>\nsur l&rsquo;\u00e9diteur de logiciels de \u00ab\u00a0surpond\u00e9rer\u00a0\u00bb \u00e0 \u00ab\u00a0neutre\u00a0\u00bb.\n<\/p>\n<p>\n LES INDICATEURS DU JOUR\n<\/p>\n<p>\n La croissance du secteur priv\u00e9 dans la zone euro a fortement ralenti en<br \/>\nmars, la guerre au Moyen-Orient ayant propuls\u00e9 les co\u00fbts des intrants \u00e0 leur<br \/>\nplus haut niveau depuis plus de trois ans et provoqu\u00e9 les pires perturbations de<br \/>\nla cha\u00eene d&rsquo;approvisionnement depuis mi-2022, selon l&rsquo;enqu\u00eate PMI.\n<\/p>\n<p>\n L&rsquo;\u00e9conomie de la France devrait cro\u00eetre de 0,2% au premier et au deuxi\u00e8me<br \/>\ntrimestres, un taux identique \u00e0 celui du quatri\u00e8me trimestre, indique l&rsquo;Insee<br \/>\ndans ses perspectives \u00e0 court terme.\n<\/p>\n<p>\n CHANGES\n<\/p>\n<p>\n Le dollar se raffermit de nouveau mardi, de 0,44%, face \u00e0 un panier de<br \/>\ndevises de r\u00e9f\u00e9rence  .DXY , \u00e0 mesure que s&rsquo;estompe l&rsquo;optimisme quant \u00e0 une fin<br \/>\nrapide de la guerre en Iran. Le billet vert s&rsquo;est renforc\u00e9 de 1,7% depuis le<br \/>\nd\u00e9but du mois et est passe de r\u00e9aliser sa plus forte progression mensuelle<br \/>\ndepuis octobre, le conflit en cours ayant aliment\u00e9 la demande vers les actifs<br \/>\nrefuge.\n<\/p>\n<p>\n L&rsquo;euro<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1xEURUS\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  EUR=<br \/>\n <\/a><br \/>\n c\u00e8de 0,21%, \u00e0 1,1588 dollar, tandis que la livre sterling\n<\/p>\n<p>\n <a href=\"https:\/\/www.boursorama.com\/cours\/1xGBPUS\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  GBP=<br \/>\n <\/a><br \/>\n s&rsquo;\u00e9change \u00e0 1,3386 dollar (-0,31%), apr\u00e8s respectivement un gain de 0,40%<br \/>\net pr\u00e8s de 1% lundi.\n<\/p>\n<p>\n TAUX\n<\/p>\n<p>\n Le rendement du Bund allemand, r\u00e9f\u00e9rence pour la zone euro, a fini en l\u00e9g\u00e8re<br \/>\nbaisse, \u00e0 3,015%, contre 3,077% lundi, qui \u00e9tait alors son plus haut niveau<br \/>\ndepuis juin 2011, sur fond de craintes persistantes de conflit au Moyen-Orient.\n<\/p>\n<p>\n Le rendement des bons du Tr\u00e9sor am\u00e9ricain \u00e0 dix ans<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/2xUSABM10A\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  US10YT=RR<br \/>\n <\/a><br \/>\n \u00e9tait, pour<br \/>\nsa part, toujours ferme, prenant 4,8 points de base, \u00e0 4,3817%, proche d&rsquo;un pic<br \/>\nde huit ans.\n<\/p>\n<p>\n Les march\u00e9s financiers ne croient plus \u00e0 une baisse des taux de la R\u00e9serve<br \/>\nf\u00e9d\u00e9rale cette ann\u00e9e, tandis qu&rsquo;ils tablent sur deux rel\u00e8vements des co\u00fbts<br \/>\nd&#8217;emprunt par la Banque centrale europ\u00e9enne (BCE) d&rsquo;ici juillet\n<\/p>\n<p>\n EURESTECBM3X4=ICAP , avec la perspective d&rsquo;une r\u00e9surgence de l&rsquo;inflation et<br \/>\nd&rsquo;un ralentissement \u00e9conomique.\n<\/p>\n<p>\n L&rsquo;impact de la guerre s&rsquo;est fait sentir dans l&rsquo;enqu\u00eate PMI qui montre un net<br \/>\nralentissement de la croissance du secteur priv\u00e9 en zone euro en mars. Des<br \/>\nenqu\u00eates similaires men\u00e9es en Allemagne ont indiqu\u00e9 que la croissance du secteur<br \/>\npriv\u00e9 avait atteint son niveau le plus faible en trois mois, tandis qu&rsquo;en<br \/>\nFrance, elle s&rsquo;est contract\u00e9e au rythme le plus rapide depuis octobre.\n<\/p>\n<p>\n P\u00c9TROLE\n<\/p>\n<p>\n Le march\u00e9 p\u00e9trolier a rebondi mardi avec la persistance des perturbations<br \/>\ndans l&rsquo;approvisionnement mondial et le d\u00e9menti de l&rsquo;Iran sur d&rsquo;\u00e9ventuelles<br \/>\nn\u00e9gociations avec les Etats-Unis\n<\/p>\n<p>\n Le Brent grimpe de 4,26% \u00e0 104,24 dollars le baril<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/8xBRN\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  LCOc1<br \/>\n <\/a><br \/>\n et le brut l\u00e9ger<br \/>\nam\u00e9ricain (West Texas Intermediate, WTI) bondit de 4,92% \u00e0 92,47 dollars<br \/>\n <a href=\"https:\/\/www.boursorama.com\/cours\/_CL\/\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n  CLc1<br \/>\n <\/a><br \/>\n .\n<\/p>\n<p>\n A SUIVRE MERCREDI:<br \/>\n nL8N40823Y\n<\/p>\n<p>\n (R\u00e9dig\u00e9 par Claude Chendjou, \u00e9dit\u00e9 par Tangi Sala\u00fcn)<\/p>\n","protected":false},"excerpt":{"rendered":"* En Europe, le CAC 40 a gagn\u00e9 0,23% et le Stoxx 600 0,46% * Wall Street h\u00e9site&hellip;\n","protected":false},"author":2,"featured_media":53972,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[593,591,601,598,18,596,595,592,597,594,599,600],"class_list":{"0":"post-53971","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-europe","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116286361606601090","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/53971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=53971"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/53971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/53972"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=53971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=53971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=53971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}