{"id":56708,"date":"2026-03-27T08:18:08","date_gmt":"2026-03-27T08:18:08","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/56708\/"},"modified":"2026-03-27T08:18:08","modified_gmt":"2026-03-27T08:18:08","slug":"en-afrique-du-sud-le-mohair-prospere-dans-le-desert-27-03-2026-a-0847","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/56708\/","title":{"rendered":"En Afrique du Sud, le mohair prosp\u00e8re dans le d\u00e9sert &#8211; 27\/03\/2026 \u00e0 08:47"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/3827b5ba6fab2fda660414067d5a5700-760x507.jpg\" alt=\"Des ch\u00e8vres mohair et leur berger dans un p\u00e2turage dans les environs de la ferme Wheatlands, \u00e0 Graaf-Reinet, en Afrique du Sud le 4 mars 2026. ( AFP \/ MARCO LONGARI )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Des ch\u00e8vres mohair et leur berger dans un p\u00e2turage dans les environs de la ferme Wheatlands, \u00e0 Graaf-Reinet, en Afrique du Sud le 4 mars 2026. ( AFP \/ MARCO LONGARI )<\/p>\n<p>\n Vaste semi-d\u00e9sert sud-africain, le Karoo est parcouru de pistes de terre qui m\u00e8nent \u00e0 plusieurs fermes s\u00e9culaires o\u00f9 paissent des ch\u00e8vres angora, \u00e9lev\u00e9es pour leur mohair. Le pays concentre plus de la moiti\u00e9 de la production mondiale de cette fibre naturelle.\n<\/p>\n<p>\n Seules les pales d&rsquo;acier d&rsquo;\u00e9oliennes de pompage ponctuent le \u00ab\u00a0veld\u00a0\u00bb, la steppe herbeuse sud-africaine. Apr\u00e8s des kilom\u00e8tres sur une piste cahoteuse, des pignons \u00e0 volutes typiques de l&rsquo;architecture coloniale n\u00e9erlandaise \u00e9mergent.\n<\/p>\n<p>\n \u00ab\u00a0Wheatlands 1912\u00a0\u00bb, affiche l&rsquo;un d&rsquo;eux. \u00ab\u00a0C&rsquo;est le b\u00e2timent le plus r\u00e9cent ici\u00a0\u00bb, pr\u00e9vient l&rsquo;\u00e9leveur Lloyd Short, qui a grandi sur l&rsquo;exploitation familiale de 7.700 hectares.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/d0ad236bd1e71f579c0fe20f82a024e8-760x507.jpg\" alt=\"Un troupeau de ch\u00e8vres \u00e0 laine mohair dans la bergerie de la ferme Wheatlands, pr\u00e8s de Graaf-Reinet, en Afrique du Sud, le 4 mars 2026. ( AFP \/ MARCO LONGARI )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Un troupeau de ch\u00e8vres \u00e0 laine mohair dans la bergerie de la ferme Wheatlands, pr\u00e8s de Graaf-Reinet, en Afrique du Sud, le 4 mars 2026. ( AFP \/ MARCO LONGARI )<\/p>\n<p>\n Sa r\u00e9putation, Wheatlands ne la doit pas au charme de sa th\u00e9ba\u00efde raffin\u00e9e. Le tr\u00e9sor des lieux est constitu\u00e9 de ch\u00e8vres angora, b\u00eates singuli\u00e8res aux oreilles tombantes, aux cornes courbes et \u00e0 la toison d&rsquo;or. Leurs boucles aussi soyeuses que duveteuses se vendent jusqu&rsquo;\u00e0 900 rands (45 euros) le kilo et servent \u00e0 confectionner pulls et tricots, le plus souvent m\u00e9lang\u00e9es \u00e0 de la laine.\n<\/p>\n<p>\n L&rsquo;entreprise de filature italienne Vitale Barberis Canonico, un des plus prestigieux fabricants de tissus pour costume, se fournit par exemple aussi en mohair sud-africain.\n<\/p>\n<p>\n \u00ab\u00a0Les deux premi\u00e8res tontes sont les plus lucratives\u00a0\u00bb, explique Lloyd Short. L&rsquo;\u00e9leveur de septi\u00e8me g\u00e9n\u00e9ration r\u00e9cup\u00e8re alors en moyenne 1 kg par animal \u00e0 la premi\u00e8re tonte, puis 1,5 kg \u00e0 la deuxi\u00e8me. Le poids augmente ensuite un peu avec l&rsquo;\u00e2ge mais la fibre perd en qualit\u00e9 avec le vieillissement.\n<\/p>\n<p>\n Il poss\u00e8de environ 2.000 ch\u00e8vres angora, autant que son fr\u00e8re. Les Short ont la chance &#8211; une cons\u00e9cration &#8211; d&rsquo;\u00eatre les uniques fournisseurs d&rsquo;une c\u00e9l\u00e8bre maison de couture fran\u00e7aise. Une fa\u00e7on pour la marque d&rsquo;assurer la tra\u00e7abilit\u00e9 de son approvisionnement avec un producteur de confiance et de prot\u00e9ger son image.\n<\/p>\n<p>\n Car le mohair sud-africain a subi en 2018 une crise ayant laiss\u00e9 le secteur m\u00e9fiant. L&rsquo;ONG de d\u00e9fense des animaux Peta avait diffus\u00e9 une vid\u00e9o d&rsquo;un incident, rarissime selon les \u00e9leveurs: une ch\u00e8vre achev\u00e9e apr\u00e8s la coupe accidentelle d&rsquo;une art\u00e8re lors de la tonte.\n<\/p>\n<p>\n Du jour au lendemain, de nombreuses marques internationales avaient annonc\u00e9 publiquement abandonner cette fibre. Il a fallu deux ans pour convaincre le monde de la mode d&rsquo;y revenir, apr\u00e8s la mise en place d&rsquo;un label d&rsquo;\u00e9levage responsable pr\u00e9voyant des contr\u00f4les par une tierce partie.\n<\/p>\n<p>\n \u00ab\u00a0En 2020, la situation a chang\u00e9 et la demande a commenc\u00e9 \u00e0 remonter un peu\u00a0\u00bb, explique Marco Coetzee, directeur de l&rsquo;organisation repr\u00e9sentative du secteur Mohair South Africa.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/2ff1ba6748ce3c5563db4c32fbdda4fb-760x506.jpg\" alt=\"Un troupeau de ch\u00e8vres mohair traverse un gu\u00e9 sur le chemin vers les p\u00e2turages de la ferme Wheatlands, pr\u00e8s de Graaf-Reinet, en Afrique du Sud, le 4 mars 2026. ( AFP \/ MARCO LONGARI )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"506\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Un troupeau de ch\u00e8vres mohair traverse un gu\u00e9 sur le chemin vers les p\u00e2turages de la ferme Wheatlands, pr\u00e8s de Graaf-Reinet, en Afrique du Sud, le 4 mars 2026. ( AFP \/ MARCO LONGARI )<\/p>\n<p> &#8211; De la Turquie au Karoo &#8211;<\/p>\n<p>\n Le pays a fourni 56% de la production mondiale en 2024, d&rsquo;apr\u00e8s ses chiffres. Le secteur compte environ 30.000 emplois dont des centaines dans le Karoo, devenu terre d&rsquo;accueil inattendue de la ch\u00e8vre angora, une race venue de Turquie.\n<\/p>\n<p>\n Son introduction dans la premi\u00e8re moiti\u00e9 du XIXe si\u00e8cle est floue. Cadeau d&rsquo;un dignitaire ottoman ou importation par un militaire britannique ? Les versions divergent mais, pr\u00e8s de deux si\u00e8cles plus tard, les angoras s&rsquo;y d\u00e9lectent des plantes succulentes locales.\n<\/p>\n<p>\n \u00ab\u00a0On y trouve de magnifiques esp\u00e8ces du veld, des plantes au go\u00fbt sucr\u00e9. Presque tout est comestible\u00a0\u00bb, vante Sean Hobson, propri\u00e9taire de la ferme Martyrsford, qui \u00e9l\u00e8ve des angoras depuis 1865.\n<\/p>\n<p>\n \u00ab\u00a0Les r\u00e9gions \u00e0 l&rsquo;humidit\u00e9 plus \u00e9lev\u00e9e ne sont pas aussi propices \u00e0 la production de fibres\u00a0\u00bb, d\u00e9taille-t-il. \u00ab\u00a0On y trouve beaucoup plus de parasites et de tiques.\u00a0\u00bb\n<\/p>\n<p>\n Pour s&rsquo;en prot\u00e9ger, les ch\u00e8vres passent r\u00e9guli\u00e8rement dans des bacs de trempage entre les deux tontes annuelles. Un bain d&rsquo;apr\u00e8s-shampoing sert aussi \u00e0 donner un \u00ab\u00a0bon d\u00e9part\u00a0\u00bb aux m\u00e8ches de poils pour \u00ab\u00a0donner cette belle boucle\u00a0\u00bb, selon M. Hobson.\n<\/p>\n<p>\n \u00ab\u00a0Le monde entier ach\u00e8te du mohair, d&rsquo;abord pour son lustre. Ce n&rsquo;est pas que \u00e7a brille mais \u00e7a fait ressortir les couleurs\u00a0\u00bb, d\u00e9crit Pierre van der Vyver, directeur g\u00e9n\u00e9ral du courtier House of Fiber.\n<\/p>\n<p>\n Des effluves de bergerie embaument son entrep\u00f4t o\u00f9 reposent des centaines de balles de mohair, \u00e0 deux pas des quais de Gqeberha (ex-Port-Elizabeth). Avec son principal concurrent OVK, sud-africain \u00e9galement, ils se partagent \u00e0 parts quasi \u00e9gales plus de 70% du march\u00e9 mondial &#8211; rien que le Lesotho voisin pesant 16% de celui-ci.\n<\/p>\n<p>\n Presque tous les clients, except\u00e9 Vitale Barberis Canonico, l&rsquo;ach\u00e8tent en pelotes. Elles sont transform\u00e9es par un duopole, encore une fois sud-africain (Samil et Stucken), qui se partage le secteur dans les m\u00eames proportions et traite des fibres venues d&rsquo;Australie ou du Royaume-Uni.\n<\/p>\n<p>\n \u00ab\u00a0Les Chinois aimeraient nous concurrencer, mais heureusement, le travail du mohair demande beaucoup de savoir-faire technique\u00a0\u00bb, analyse Pierre van der Vyver. \u00ab\u00a0C&rsquo;est un processus bien plus lent que pour la laine. C&rsquo;est une fibre sp\u00e9ciale.\u00a0\u00bb Elle prosp\u00e8re dans le d\u00e9sert.<\/p>\n","protected":false},"excerpt":{"rendered":"Des ch\u00e8vres mohair et leur berger dans un p\u00e2turage dans les environs de la ferme Wheatlands, \u00e0 Graaf-Reinet,&hellip;\n","protected":false},"author":2,"featured_media":56709,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[593,6,591,601,598,596,595,592,597,594,599,600],"class_list":{"0":"post-56708","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-action-cac-40","9":"tag-afrique","10":"tag-bourse-de-paris","11":"tag-boursorama","12":"tag-cotations","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116300159599265716","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/56708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=56708"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/56708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/56709"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=56708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=56708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=56708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}