{"id":56821,"date":"2026-03-27T10:16:09","date_gmt":"2026-03-27T10:16:09","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/56821\/"},"modified":"2026-03-27T10:16:09","modified_gmt":"2026-03-27T10:16:09","slug":"prudence-en-europe-face-aux-incertitudes-liees-au-conflit-au-moyen-orient-27-03-2026-a-1035","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/56821\/","title":{"rendered":"Prudence en Europe face aux incertitudes li\u00e9es au conflit au Moyen-Orient &#8211; 27\/03\/2026 \u00e0 10:35"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/fe83fb099b52457feae0c2400461ac4e-760x541.jpg\" alt=\"Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l'ancienne Bourse de Paris, situ\u00e9 Place de la Bourse \u00e0 Paris\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"541\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l&rsquo;ancienne Bourse de Paris, situ\u00e9 Place de la Bourse \u00e0 Paris<\/p>\n<p>\n Les principales Bourses \u200ceurop\u00e9ennes \u00e9voluent sur une note prudente en d\u00e9but de s\u00e9ance alors \u200bque l&rsquo;incertitude domine autour du conflit au Moyen-Orient en cours depuis pr\u00e8s d&rsquo;un mois.\n<\/p>\n<p>\n L&rsquo;annonce d&rsquo;un nouveau report de l&rsquo;ultimatum adress\u00e9 par le \u200bpr\u00e9sident am\u00e9ricain Donald Trump \u00e0 l&rsquo;Iran n&rsquo;a provoqu\u00e9 qu&rsquo;un bref soulagement sur les march\u00e9s \u200bfinanciers. Le rebond signal\u00e9 par les \u2060contrats \u00e0 terme sur les indices boursiers en Europe n&rsquo;a \u200cpas tenu et les cours du p\u00e9trole sont repartis \u00e0 la hausse.\n<\/p>\n<p>\n \u00c0 Paris, le CAC 40 perd 0,35% \u200b\u00e0 7.743,10 points \u200cvers 08h30 GMT. A Francfort, le Dax recule \u2060de 0,48% tandis qu&rsquo;\u00e0 Londres, le FTSE 100 prend 0,09%.\n<\/p>\n<p>\n L&rsquo;indice EuroStoxx 50 est en baisse de 0,48%, le FTSEurofirst 300 de 0,28% \u2060et le Stoxx \u200c600 de 0,55%.\n<\/p>\n<p>\n Donald Trump a annonc\u00e9 jeudi soir que \u2060Washington s&rsquo;abstiendrait pendant 10 jours de mettre \u00e0 ex\u00e9cution sa \u200cmenace de d\u00e9truire les centrales \u00e9nerg\u00e9tiques iraniennes, repoussant \u00e0 \u2060nouveau son ultimatum en raison, a-t-il dit, de l&rsquo;avanc\u00e9e \u2060des n\u00e9gociations avec \u200cT\u00e9h\u00e9ran.\n<\/p>\n<p>\n Mais de son c\u00f4t\u00e9, l&rsquo;Iran se montre beaucoup plus r\u00e9serv\u00e9. Aucun \u200bprojet de pourparlers ne semble \u200cr\u00e9aliste \u00e0 ce stade, a d\u00e9clar\u00e9 \u00e0 Reuters un responsable iranien, qui a affirm\u00e9 \u200bque la proposition am\u00e9ricaine de sortie du conflit qui a \u00e9t\u00e9 transmise \u00e0 l&rsquo;Iran est \u00ab\u00a0\u00e0 sens unique et injuste\u00a0\u00bb.\n<\/p>\n<p>\n Aux \u2060valeurs, Pernod Ricard rebondit de plus de 3%, en t\u00eate du CAC 40, apr\u00e8s avoir chut\u00e9 de 5% la veille apr\u00e8s des informations, confirm\u00e9es depuis, sur des discussions en vue d&rsquo;un rapprochement avec le groupe am\u00e9ricain Brown-Forman, propri\u00e9taire de la marque de whisky Jack \u200bDaniel&rsquo;s.\n<\/p>\n<p>\n (R\u00e9dig\u00e9 par Blandine H\u00e9nault)<\/p>\n","protected":false},"excerpt":{"rendered":"Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l&rsquo;ancienne Bourse de Paris, situ\u00e9 Place de&hellip;\n","protected":false},"author":2,"featured_media":56822,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[593,591,601,598,18,596,595,592,597,594,599,600],"class_list":{"0":"post-56821","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-europe","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116300623542037101","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/56821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=56821"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/56821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/56822"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=56821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=56821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=56821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}