{"id":58992,"date":"2026-03-29T08:25:23","date_gmt":"2026-03-29T08:25:23","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/58992\/"},"modified":"2026-03-29T08:25:23","modified_gmt":"2026-03-29T08:25:23","slug":"rebond-en-vue-en-europe-apres-le-nouveau-report-de-lultimatum-de-trump-a-liran-27-03-2026-a-0742","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/58992\/","title":{"rendered":"Rebond en vue en Europe apr\u00e8s le nouveau report de l&rsquo;ultimatum de Trump \u00e0 l&rsquo;Iran &#8211; 27\/03\/2026 \u00e0 07:42"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/fe83fb099b52457feae0c2400461ac4e-760x541.jpg\" alt=\"Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l'ancienne Bourse de Paris, situ\u00e9 Place de la Bourse \u00e0 Paris\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"541\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l&rsquo;ancienne Bourse de Paris, situ\u00e9 Place de la Bourse \u00e0 Paris<\/p>\n<p>\n par Blandine Henault\n<\/p>\n<p>\n Les principales Bourses europ\u00e9ennes devraient tenter un rebond vendredi \u00e0 l&rsquo;ouverture, apr\u00e8s le nouveau \u200creport de l&rsquo;ultimatum adress\u00e9 par le pr\u00e9sident am\u00e9ricain Donald Trump \u00e0 l&rsquo;Iran, m\u00eame si la prudence devrait rester de mise alors que les combats se poursuivent et que le d\u00e9troit d&rsquo;Ormuz reste ferm\u00e9.\n<\/p>\n<p>\n D&rsquo;apr\u00e8s les premi\u00e8res indications \u200bdisponibles, le CAC 40 parisien pourrait gagner 0,47% \u00e0 l&rsquo;ouverture.\n<\/p>\n<p>\n Les contrats \u00e0 terme signalent une hausse de 0,72% pour le Dax \u00e0 Francfort, de 0,46% pour le FTSE \u00e0 Londres et de 0,47% pour le Stoxx 600.\n<\/p>\n<p>\n Donald Trump a annonc\u00e9 jeudi soir que Washington s&rsquo;abstiendrait pendant 10 jours de mettre \u00e0 ex\u00e9cution sa menace de d\u00e9truire les centrales \u00e9nerg\u00e9tiques iraniennes, repoussant \u00e0 nouveau son ultimatum en raison, a-t-il dit, de \u200bl&rsquo;avanc\u00e9e des n\u00e9gociations avec T\u00e9h\u00e9ran.\n<\/p>\n<p>\n La nouvelle a provoqu\u00e9 une l\u00e9g\u00e8re baisse du cours du brut qui avaient grimp\u00e9 jeudi sur fond de regain d&rsquo;inqui\u00e9tude au Moyen-Orient. Les contrats \u00e0 terme \u00e0 Wall Street, qui a cl\u00f4tur\u00e9 en net repli la veille, indiquent une ouverture en hausse \u200bce vendredi.\n<\/p>\n<p>\n Mais le soulagement reste tout relatif: aucun projet de pourparlers ne semble r\u00e9aliste \u00e0 ce stade, \u2060a d\u00e9clar\u00e9 \u00e0 Reuters un responsable iranien, qui a affirm\u00e9 que la proposition am\u00e9ricaine de sortie du conflit qui a \u00e9t\u00e9 transmise \u00e0 l&rsquo;Iran est \u00ab\u00a0\u00e0 sens unique et injuste\u00a0\u00bb.\n<\/p>\n<p>\n Le nouveau report \u200cde l&rsquo;ultimatum am\u00e9ricain \u00ab\u00a0ach\u00e8te du temps mais au prix d\u2019une incertitude prolong\u00e9e\u00a0\u00bb, observe John Plassard, responsable de la strat\u00e9gie d&rsquo;investissement de Cit\u00e9 Gestion. \u00ab\u00a0Chaque nouveau report r\u00e9duit la cr\u00e9dibilit\u00e9 de la menace am\u00e9ricaine, ce qui pourrait encourager l\u2019Iran \u00e0 maintenir une position ferme.\u00a0\u00bb\n<\/p>\n<p>\n \u00ab\u00a0Tant que le d\u00e9troit d\u2019Ormuz n\u2019est pas pleinement rouvert et s\u00e9curis\u00e9, la prime de risque \u200b\u00e9nerg\u00e9tique restera int\u00e9gr\u00e9e dans les march\u00e9s\u00a0\u00bb, ajoute-t-il.\n<\/p>\n<p>\n P\u00c9TROLE\n<\/p>\n<p>\n Les cours du p\u00e9trole reculent sous l&rsquo;effet du \u200cnouveau report de l&rsquo;ultimatum de Trump \u00e0 l&rsquo;Iran.\n<\/p>\n<p>\n Le baril de Brent recule de 0,16% \u00e0 107,84 dollars et celui du brut l\u00e9ger am\u00e9ricain (WTI) \u2060perd 0,56% \u00e0 93,95 dollars.\n<\/p>\n<p>\n Si le conflit devait s&rsquo;achever prochainement, les prix du p\u00e9trole pourraient chuter rapidement dans les mois \u00e0 venir, tout en restant \u00e0 leur niveau d&rsquo;avant le conflit, ont indiqu\u00e9 dans une note les analystes de Macquarie.\n<\/p>\n<p>\n Les prix pourraient toutefois atteindre 200 dollars si la guerre se prolongeait jusqu&rsquo;\u00e0 fin juin, estiment-ils.\n<\/p>\n<p>\n LES VALEURS A SUIVRE EN EUROPE :\n<\/p>\n<p>\n Le fabricant fran\u00e7ais de spiritueux Pernod Ricard et le groupe am\u00e9ricain Brown-Forman, \u2060propri\u00e9taire de la marque de whisky Jack \u200cDaniel&rsquo;s, ont confirm\u00e9 jeudi tenir des discussions en vue d&rsquo;une possible fusion.\n<\/p>\n<p>\n L&rsquo;information, d&rsquo;abord d\u00e9voil\u00e9e par Bloomberg, a fait chuter le titre Pernod-Ricard de plus de 5% jeudi \u2060alors que l&rsquo;action Brown-Forman s&rsquo;est envol\u00e9e de pr\u00e8s de 9% \u00e0 la Bourse de New York.\n<\/p>\n<p>\n A WALL STREET\n<\/p>\n<p>\n La Bourse de New York a fini en nette baisse jeudi, le Nasdaq confirmant une correction par rapport \u200c\u00e0 son record de cl\u00f4ture du 29 octobre dernier, alors que les investisseurs s&rsquo;inqui\u00e9taient d&rsquo;une possible escalade dans la guerre des Etats-Unis et d&rsquo;Isra\u00ebl contre l&rsquo;Iran, un conflit qui a \u2060provoqu\u00e9 un bond des prix p\u00e9troliers et aliment\u00e9 les craintes sur l&rsquo;inflation.\n<\/p>\n<p>\n L&rsquo;indice Dow Jones a c\u00e9d\u00e9 1,01% \u00e0 45.960,11 points. Le S&amp;P-500, plus large, \u2060a perdu 1,74%, \u00e0 6.477,16 points.\n<\/p>\n<p>\n Le Nasdaq Composite \u200ca recul\u00e9 de son c\u00f4t\u00e9 de 2,38% \u00e0 21.408,08 points.\n<\/p>\n<p>\n L&rsquo;indice \u00e0 forte composante technologique a enregistr\u00e9 depuis son pic de cl\u00f4ture d&rsquo;octobre dernier une baisse de 10,7%, confirmant qu&rsquo;il se trouvait depuis lors en correction.\n<\/p>\n<p>\n Les \u200bcontrats \u00e0 terme sur les trois indices signalent pour l&rsquo;heure une hausse de l&rsquo;ordre de 0,5% \u00e0 l&rsquo;ouverture vendredi.\n<\/p>\n<p>\n EN \u200cASIE\n<\/p>\n<p>\n La Bourse de Tokyo recule de 0,36% \u00e0 l&rsquo;approche de la cl\u00f4ture.\n<\/p>\n<p>\n En Chine, l&rsquo;indice composite de la Bourse de Shanghai progresse de 0,44% et le CSI 300 des grandes capitalisations avance de 0,38%.\n<\/p>\n<p>\n Selon des donn\u00e9es officielles publi\u00e9es vendredi, les profits \u200bdes groupes industriels chinois ont progress\u00e9 de 15,2% au cours des deux premiers mois de l&rsquo;ann\u00e9e par rapport \u00e0 la p\u00e9riode correspondante de 2025, renfor\u00e7ant les signes de reprise de la deuxi\u00e8me \u00e9conomie mondiale en d\u00e9pit du conflit au Moyen-Orient qui menace de peser sur l&rsquo;\u00e9conomie mondiale.\n<\/p>\n<p>\n La Bourse de Hong Kong avance de 0,48%.\n<\/p>\n<p>\n TAUX\n<\/p>\n<p>\n Le rendement des Treasuries \u00e0 dix ans progresse de plus d&rsquo;un point de base, \u00e0 4,4278% \u2060apr\u00e8s avoir grimp\u00e9 la veille de dix points, alors que le conflit au Moyen-Orient fait bondir les prix de l&rsquo;\u00e9nergie et alimente les craintes inflationnistes &#8211; ce qui pourrait conduire les banques centrales \u00e0 adopter un biais plus restrictif.\n<\/p>\n<p>\n CHANGES\n<\/p>\n<p>\n Le dollar se replie de 0,08% face \u00e0 un panier de devises de r\u00e9f\u00e9rence apr\u00e8s le nouveau report de l&rsquo;ultimatum de Donald Trump \u00e0 l&rsquo;Iran.\n<\/p>\n<p>\n Il reste n\u00e9anmoins port\u00e9 en toile de fond par son statut d&rsquo;actif refuge dans le contexte de la guerre au Moyen-Orient.\n<\/p>\n<p>\n \u00ab\u00a0Il ne semble pas que le conflit prenne fin de sit\u00f4t\u00a0\u00bb, observe Carol Kong, strat\u00e8ge sur les devises chez Commonwealth Bank of Australia. \u00ab\u00a0Le dollar reste roi tant que ce conflit perdure.\u00a0\u00bb\n<\/p>\n<p>\n L&rsquo;euro gagne 0,14% \u00e0 1,1543 dollar.\n<\/p>\n<p>\n PRINCIPAUX INDICATEURS \u00c9CONOMIQUES \u00c0 L&rsquo;AGENDA DU VENDREDI 27 MARS :\n<\/p>\n<p>\n PAYS    GMT    INDICATEUR                     P\u00c9RIODE     CONSENSUS     PR\u00c9C\u00c9DENT\n<\/p>\n<p>\n GB      07h00  Ventes au d\u00e9tail               f\u00e9vrier\n<\/p>\n<p>\n &#8211; sur un mois                              -0,7%         1,8%\n<\/p>\n<p>\n &#8211; sur un an                                2,1%          4,5%\n<\/p>\n<p>\n USA     14h00  Indice de l&rsquo;Universit\u00e9 du      mars        54,0          55,5*\n<\/p>\n<p>\n Michigan (d\u00e9finitif)\n<\/p>\n<p>\n * premi\u00e8re estimation\n<\/p>\n<p>\n (R\u00e9dig\u00e9 par \u200bBlandine H\u00e9nault avec les bureaux de Reuters, \u00e9dit\u00e9 par Augustin Turpin)<\/p>\n","protected":false},"excerpt":{"rendered":"Le mot Bourse figure sur un panneau pr\u00e8s du Palais Brongniart, l&rsquo;ancienne Bourse de Paris, situ\u00e9 Place de&hellip;\n","protected":false},"author":2,"featured_media":56822,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[593,591,601,598,18,596,595,592,597,594,599,600],"class_list":{"0":"post-58992","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-europe","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116311511692121712","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/58992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=58992"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/58992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/56822"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=58992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=58992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=58992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}