{"id":59288,"date":"2026-03-29T14:59:12","date_gmt":"2026-03-29T14:59:12","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/59288\/"},"modified":"2026-03-29T14:59:12","modified_gmt":"2026-03-29T14:59:12","slug":"guerre-au-moyen-orient-debut-des-entretiens-entre-pakistan-arabie-saoudite-turquie-et-egypte-29-03-2026-a-1514","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/59288\/","title":{"rendered":"Guerre au Moyen-Orient : d\u00e9but des entretiens entre Pakistan, Arabie Saoudite, Turquie et Egypte &#8211; 29\/03\/2026 \u00e0 15:14"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/3ad2ef9b2cee648a5cbb1ce994204b71-760x506.jpg\" alt=\"Photo diffus\u00e9e le 29 mars 2026 par le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res montrant le ministre pakistanais des Affaires \u00e9trang\u00e8res, Ishaq Dar (2e d), avec ses homologues turc Hakan Fidan (d), saoudien Faisal bin Farhan (2e g) et \u00e9gyptien Badr Abdelatty avant leur r\u00e9union \u00e0 Islamabad ( Pakistan Foreign Ministry \/ - )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"506\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Photo diffus\u00e9e le 29 mars 2026 par le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res montrant le ministre pakistanais des Affaires \u00e9trang\u00e8res, Ishaq Dar (2e d), avec ses homologues turc Hakan Fidan (d), saoudien Faisal bin Farhan (2e g) et \u00e9gyptien Badr Abdelatty avant leur r\u00e9union \u00e0 Islamabad ( Pakistan Foreign Ministry \/ &#8211; )<\/p>\n<p>\n Les ministres des Affaires \u00e9trang\u00e8res du Pakistan, d&rsquo;Arabie saoudite, d&rsquo;Egypte et de Turquie ont d\u00e9but\u00e9 dimanche \u00e0 Islamabad des discussions quadripartites sur la guerre au Moyen-Orient, dans laquelle le Pakistan joue le r\u00f4le d&rsquo;interm\u00e9diaire entre les \u00c9tats-Unis et l&rsquo;Iran.\n<\/p>\n<p>\n Commenc\u00e9e dans l&rsquo;apr\u00e8s-midi, la r\u00e9union des ministres des Affaires \u00e9trang\u00e8res de ces pays musulmans doit aborder \u00ab\u00a0un \u00e9ventail de questions, notamment les efforts visant \u00e0 d\u00e9samorcer les tensions dans la r\u00e9gion\u00a0\u00bb, a indiqu\u00e9 le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res, Ishaq Dar. Elle se poursuivra lundi.\n<\/p>\n<p>\n Badr Abdelatty, pour l&rsquo;\u00c9gypte, et Hakan Fidan, pour la Turquie, sont arriv\u00e9s \u00e0 Islamabad samedi soir, tandis que le chef de la diplomatie saoudienne, Fay\u00e7al ben Farhane, a atterri dimanche apr\u00e8s-midi \u00e0 Islamabad.\n<\/p>\n<p>\n Plusieurs routes menant \u00e0 la \u00ab\u00a0zone rouge\u00a0\u00bb d&rsquo;Islamabad \u2013 o\u00f9 se trouvent les principaux b\u00e2timents gouvernementaux et les missions diplomatiques \u2013 ont \u00e9t\u00e9 ferm\u00e9es, ont constat\u00e9 des journalistes de l\u2019AFP. La s\u00e9curit\u00e9 \u00e9tait renforc\u00e9e et la voie menant au minist\u00e8re des Affaires \u00e9trang\u00e8res pavois\u00e9e des drapeaux des quatre pays.\n<\/p>\n<p>\n Ishaq Dar a tenu dimanche matin des entretiens bilat\u00e9raux s\u00e9par\u00e9s avec MM. Abdelatty et Fidan. Ceux-ci ont ensuite rencontr\u00e9 ensemble le puissant chef de l&rsquo;arm\u00e9e pakistanaise, le mar\u00e9chal Asim Munir.\n<\/p>\n<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/03\/06172f278a851c8bb9824dce99b1ee34-760x506.jpg\" alt=\"Photo diffus\u00e9e le 29 mars 2026 par le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res montrant le ministre pakistanais des Affaires \u00e9trang\u00e8res, Ishaq Dar (2e g), et ses homologues saoudien Faisal bin Farhan (g), turc Hakan Fidan (2e d) et \u00e9gyptien Badr Abdelatty lors d'une r\u00e9union \u00e0 Islamabad ( Pakistan Foreign Ministry \/ - )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"506\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Photo diffus\u00e9e le 29 mars 2026 par le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res montrant le ministre pakistanais des Affaires \u00e9trang\u00e8res, Ishaq Dar (2e g), et ses homologues saoudien Faisal bin Farhan (g), turc Hakan Fidan (2e d) et \u00e9gyptien Badr Abdelatty lors d&rsquo;une r\u00e9union \u00e0 Islamabad ( Pakistan Foreign Ministry \/ &#8211; )<\/p>\n<p>\n Le gouvernement pakistanais s&rsquo;est impos\u00e9 comme un facilitateur cl\u00e9 entre l&rsquo;Iran et les \u00c9tats-Unis, permettant l&rsquo;\u00e9change de messages, alors que la guerre, que Washington m\u00e8ne avec Isra\u00ebl, vient d&rsquo;entrer dans son deuxi\u00e8me mois.\n<\/p>\n<p>\n Islamabad entretient des liens anciens avec T\u00e9h\u00e9ran et des contacts \u00e9troits dans le Golfe, tandis que le Premier ministre Shehbaz Sharif et le mar\u00e9chal Munir ont nou\u00e9 une relation personnelle avec le pr\u00e9sident am\u00e9ricain Donald Trump.\n<\/p>\n<p>\n T\u00e9h\u00e9ran d\u00e9ment la tenue de tous pourparlers officiels avec Washington, mais a transmis une r\u00e9ponse au plan en 15 points de M. Trump visant \u00e0 mettre fin \u00e0 la guerre, via Islamabad, selon une source anonyme cit\u00e9e par l&rsquo;agence de presse iranienne Tasnim.\n<\/p>\n<p>\n Samedi, M. Sharif a indiqu\u00e9 qu&rsquo;il avait eu une conversation t\u00e9l\u00e9phonique de plus d&rsquo;une heure avec le pr\u00e9sident iranien Massoud Pezeshkian, d\u00e9taillant \u00ab\u00a0l&rsquo;action diplomatique en cours\u00a0\u00bb de son pays.\n<\/p>\n<p>\n M. Pezeshkian a remerci\u00e9 Islamabad \u00ab\u00a0pour ses efforts de m\u00e9diation afin de mettre fin \u00e0 l&rsquo;agression\u00a0\u00bb.\n<\/p>\n<p>\n Tard samedi, M. Dar, qui est \u00e9galement vice-Premier ministre, a annonc\u00e9 que l&rsquo;Iran avait autoris\u00e9 20 navires battant pavillon pakistanais suppl\u00e9mentaires \u2013 soit deux navires par jour \u2013 \u00e0 transiter par le d\u00e9troit d&rsquo;Ormuz.\n<\/p>\n<p>\n \u00ab\u00a0Le dialogue, la diplomatie et ce type de mesures de confiance sont la seule voie \u00e0 suivre\u00a0\u00bb, a d\u00e9clar\u00e9 M. Dar sur X, dans un post adress\u00e9 au vice-pr\u00e9sident am\u00e9ricain JD Vance, au secr\u00e9taire d&rsquo;\u00c9tat Marco Rubio, \u00e0 l&rsquo;\u00e9missaire Steve Witkoff et au ministre iranien des Affaires \u00e9trang\u00e8res Abbas Araghchi.<\/p>\n","protected":false},"excerpt":{"rendered":"Photo diffus\u00e9e le 29 mars 2026 par le minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res montrant le ministre pakistanais des&hellip;\n","protected":false},"author":2,"featured_media":59289,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[593,591,601,598,139,596,595,592,597,594,599,600],"class_list":{"0":"post-59288","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-egypte","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-egypte","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sicav","18":"tag-trackers","19":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116313061034362652","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/59288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=59288"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/59288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/59289"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=59288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=59288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=59288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}