{"id":60897,"date":"2026-03-30T22:43:07","date_gmt":"2026-03-30T22:43:07","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/60897\/"},"modified":"2026-03-30T22:43:07","modified_gmt":"2026-03-30T22:43:07","slug":"lequipe-se-complique-la-vie-toute-seule-nagelsmann-met-ses-joueurs-en-garde-contre-un-grand-danger-pour-la-coupe-du-monde","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/60897\/","title":{"rendered":"\u00ab L&rsquo;\u00e9quipe se complique la vie toute seule ! \u00bb Nagelsmann met ses joueurs en garde contre un grand danger pour la Coupe du monde"},"content":{"rendered":"<p>\u00ab Comme le match se d\u00e9roulait tr\u00e8s, tr\u00e8s bien, nous sommes devenus un peu impatients et nous n&rsquo;avons plus aussi bien occup\u00e9 les postes. C&rsquo;\u00e9tait \u00e0 nouveau beaucoup de jeu improvis\u00e9, comme contre la Suisse. Et puis, parfois, nous ne sommes tout simplement pas assez s\u00fbrs du ballon pour nous permettre ce genre de jeu improvis\u00e9 \u00bb, a critiqu\u00e9 Nagelsmann.<\/p>\n<p>L&rsquo;effectif ne serait que partiellement adapt\u00e9 \u00e0 un tel style de jeu. \u00ab Il y a certes quelques joueurs capables d&rsquo;\u00e9voluer \u00e0 tous les postes, mais il y en a aussi dans l&rsquo;effectif qui se sentent tout simplement plus \u00e0 l&rsquo;aise \u00e0 un poste pr\u00e9cis et qui sont plus satisfaits lorsqu&rsquo;ils occupent ce poste et peuvent ainsi bien jouer. \u00bb<\/p>\n<p>En revanche, lorsque le jeu devient trop \u00ab freestyle \u00bb, l\u2019\u00e9quipe est plus vuln\u00e9rable aux contre-attaques.<\/p>\n<p>Pourtant, l\u2019\u00e9quipe avait tr\u00e8s bien appliqu\u00e9 la tactique pendant les 25 premi\u00e8res minutes. \u00ab On avait l\u2019impression que le Ghana n\u2019\u00e9tait m\u00eame pas dans notre moiti\u00e9 de terrain \u00bb, a salu\u00e9 Nagelsmann. L\u2019\u00e9quipe allemande a \u00e9galement eu suffisamment d\u2019occasions pour sceller le sort du match d\u00e8s le d\u00e9but. \u00ab Dans l\u2019ensemble, nous avons mieux jou\u00e9 que contre la Suisse, m\u00eame si nous avons marqu\u00e9 moins de buts \u00bb, a r\u00e9sum\u00e9 le s\u00e9lectionneur national.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00ab Comme le match se d\u00e9roulait tr\u00e8s, tr\u00e8s bien, nous sommes devenus un peu impatients et nous n&rsquo;avons&hellip;\n","protected":false},"author":2,"featured_media":60898,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161],"tags":[3056,22571,295,17569,17568,22572,278,23153,8868,247],"class_list":{"0":"post-60897","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ghana","8":"tag-allemagne","9":"tag-allemagne-vs-ghana","10":"tag-coupe-du-monde","11":"tag-friendlies","12":"tag-germany","13":"tag-germany-vs-ghana","14":"tag-ghana","15":"tag-j-nagelsmann","16":"tag-matchs-amicaux","17":"tag-world-cup"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/60897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=60897"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/60897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/60898"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=60897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=60897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=60897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}