{"id":65164,"date":"2026-04-03T15:49:07","date_gmt":"2026-04-03T15:49:07","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/65164\/"},"modified":"2026-04-03T15:49:07","modified_gmt":"2026-04-03T15:49:07","slug":"lancien-selectionneur-allemand-joachim-low-devoile-la-verite-sur-les-rumeurs-concernant-un-poste-au-ghana-a-lapproche-de-la-coupe-du-monde","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/65164\/","title":{"rendered":"L&rsquo;ancien s\u00e9lectionneur allemand Joachim L\u00f6w d\u00e9voile la v\u00e9rit\u00e9 sur les rumeurs concernant un poste au Ghana \u00e0 l&rsquo;approche de la Coupe du monde"},"content":{"rendered":"<p>Bien qu&rsquo;il ait d\u00e9menti toute implication actuelle avec ce pays d&rsquo;Afrique de l&rsquo;Ouest, l&rsquo;homme qui a men\u00e9 l&rsquo;Allemagne \u00e0 la victoire en 2014 n&rsquo;a pas ferm\u00e9 la porte \u00e0 un retour sur le banc. Apr\u00e8s avoir d\u00e9clin\u00e9 plusieurs propositions \u00e0 l&rsquo;issue de l&rsquo;Euro 2020, y compris une offre pr\u00e9sum\u00e9e de l&rsquo;Ouzb\u00e9kistan l&rsquo;ann\u00e9e derni\u00e8re, L\u00f6w admet qu&rsquo;il est toujours \u00e0 la recherche du projet id\u00e9al.<\/p>\n<p>\u00ab En gros, j&rsquo;ai dit que je ne voulais pas prendre ma retraite maintenant. Surtout s&rsquo;il y a une autre offre int\u00e9ressante et de bonnes perspectives \u00bb, a d\u00e9clar\u00e9 L\u00f6w.<\/p>\n<p>Il a ensuite pr\u00e9cis\u00e9 sa pr\u00e9f\u00e9rence pour le football international en d\u00e9clarant : \u00ab D&rsquo;apr\u00e8s mon exp\u00e9rience, ce serait \u00e9galement la meilleure option pour moi. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"Bien qu&rsquo;il ait d\u00e9menti toute implication actuelle avec ce pays d&rsquo;Afrique de l&rsquo;Ouest, l&rsquo;homme qui a men\u00e9 l&rsquo;Allemagne&hellip;\n","protected":false},"author":2,"featured_media":65165,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161],"tags":[3056,295,17568,278,24537,24318,247],"class_list":{"0":"post-65164","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ghana","8":"tag-allemagne","9":"tag-coupe-du-monde","10":"tag-germany","11":"tag-ghana","12":"tag-j-loew","13":"tag-joachim-low","14":"tag-world-cup"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116341569120157678","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/65164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=65164"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/65164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/65165"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=65164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=65164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=65164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}