{"id":94454,"date":"2026-05-06T08:23:12","date_gmt":"2026-05-06T08:23:12","guid":{"rendered":"https:\/\/www.europesays.com\/afrique\/94454\/"},"modified":"2026-05-06T08:23:12","modified_gmt":"2026-05-06T08:23:12","slug":"rita-babihuga-nsanze-afc-laviation-est-un-secteur-encore-sous-estime-en-afrique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/afrique\/94454\/","title":{"rendered":"Rita Babihuga-Nsanze (AFC) : \u00ab L\u2019aviation est un secteur encore sous-estim\u00e9 en Afrique \u00bb"},"content":{"rendered":"<p>Face \u00e0 la pression exerc\u00e9e par les tensions g\u00e9opolitiques sur les flux de capitaux \u00e9trangers, l\u2019Africa Finance Corporation (AFC) dans son dernier rapport met en lumi\u00e8re la possibilit\u00e9 pour l\u2019Afrique de mobiliser les capitaux domestiques, estimant que certains domaines, comme l\u2019aviation, devraient \u00eatre davantage explor\u00e9s. D\u00e9cryptage avec Rita Babihuga-Nsanze, \u00e9conomiste en chef qui a dirig\u00e9 l\u2019\u00e9tude,.<\/p>\n<p>Le continent africain dispose d\u2019une base de capitaux domestiques de plus de 4 000 milliards de dollars sous la forme de r\u00e9serves de capitaux domestiques non bancaires, d\u2019actifs des r\u00e9gimes de retraite et d&rsquo;assurance nationaux, de r\u00e9serves des banques centrales et d\u2019or, selon le dernier rapport de l\u2019Africa Finance Corporation (AFC) qui pr\u00e9conise la mise en place de syst\u00e8mes favorisant la disponibilit\u00e9 de ces fonds pour la construction des infrastructures dont le l\u2019Afrique a besoin pour pr\u00e9tendre au d\u00e9veloppement \u00e9conomique et social, dans un contexte international incertain.\u00a0\u00a0<\/p>\n<p>Pass\u00e9e par la Banque mondiale, le Fonds mon\u00e9taire international (FMI), la Banque centrale du Royaume-Uni, Moody\u2019s ou Barclays, Rita Babihuga-Nsanze est \u00e9conomiste en chef \u00e0 l\u2019AFC et c\u2019est elle qui a chapeaut\u00e9 l\u2019\u00e9tude.<\/p>\n<p>LA TRIBUNE AFRIQUE \u2013 Avec vos \u00e9quipes, vous soutenez dans le rapport que les infrastructures ne doivent pas \u00eatre consid\u00e9r\u00e9es comme des actifs isol\u00e9s, mais plut\u00f4t comme des \u00e9cosyst\u00e8mes int\u00e9gr\u00e9s, moteurs de transformation \u00e9conomique, notamment en raison de l\u2019existence de capitaux sur le continent. Comment l\u2019expliquez-vous ?<\/p>\n<p>RITA BABIHUGA-NSANZE \u2013 Nous sommes partis d\u2019une observation, \u00e0 savoir qu&rsquo;en d\u00e9pit du d\u00e9ficit connu, il existe des infrastructures en Afrique. Si on consid\u00e8re un pays moyen comme le Kenya \u00e0 titre d\u2019exemple, il dispose de routes, de ports, de chemins de fer, de zones \u00e9conomiques sp\u00e9ciales \u2026, bref, une vari\u00e9t\u00e9 d&rsquo;actifs d&rsquo;infrastructures autonomes, construits par diff\u00e9rents acteurs. Mais le Kenya est encore une \u00e9conomie que l&rsquo;on qualifierait, en fin de compte, de non industrialis\u00e9e. Et ce, pour la simple raison que les infrastructures disponibles ne se compl\u00e8tent pas n\u00e9cessairement entre elles ou ne sont pas reli\u00e9es de mani\u00e8re \u00e0 construire des syst\u00e8mes industriels modernes et ainsi avoir un impact maximal sur l\u2019\u00e9conomie.<\/p>\n<p>Je vais pousser un peu plus loin cette illustration avec l\u2019exemple d\u2019un chemin de fer. L\u2019un des d\u00e9fis que nous rencontrons avec les chemins de fer en Afrique, c\u2019est qu\u2019ils ont \u00e9t\u00e9 construits essentiellement pour exporter les mati\u00e8res premi\u00e8res hors du continent. Les chemins de fer sont des projets tr\u00e8s co\u00fbteux. Et en termes d\u2019investissement, ils ne sont souvent pas bancables. On ne trouve pas d\u2019argument \u00e9conomique, de viabilit\u00e9, dans le dossier du chemin de fer. Mais si l\u2019on relie le chemin de fer \u00e0 une mine, \u00e0 un centre de traitement ou \u00e0 une zone industrielle et que l\u2019on achemine les minerais extraits via le chemin de fer jusqu\u2019\u00e0 la zone de traitement situ\u00e9e pr\u00e8s d\u2019une centrale \u00e9lectrique, cela permettrait d\u2019ajouter de la valeur, de transformer ces minerais en produits, voire d\u2019effectuer la deuxi\u00e8me \u00e9tape de la transformation dans une zone \u00e9conomique sp\u00e9ciale. Cela cr\u00e9erait essentiellement un syst\u00e8me int\u00e9gr\u00e9 comprenant diff\u00e9rentes infrastructures (une mine, un chemin de fer, de l\u2019\u00e9nergie, une zone \u00e9conomique sp\u00e9ciale) qui permet de transformer les mati\u00e8res premi\u00e8res en produits finis qui sont imm\u00e9diatement achemin\u00e9s vers les march\u00e9s.\u00a0\u00a0<\/p>\n<p>NewsletterMa Tribune<\/p>\n<p class=\"text-2xl mb-8\">L\u2019actualit\u00e9 qui compte pour vous, chaque jour dans votre bo\u00eete mail.<\/p>\n<p>S&rsquo;inscrireS&rsquo;inscrireS&rsquo;inscrire<img alt=\"Illustration de la newsletter Ma Tribune\" loading=\"lazy\" decoding=\"async\" data-nimg=\"fill\" class=\"relative! rounded-xl\" style=\"position:absolute;height:100%;width:100%;left:0;top:0;right:0;bottom:0;object-fit:cover;color:transparent\"   src=\"https:\/\/www.europesays.com\/afrique\/wp-content\/uploads\/2026\/04\/1775746687_775_ma-tribune.png\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Face \u00e0 la pression exerc\u00e9e par les tensions g\u00e9opolitiques sur les flux de capitaux \u00e9trangers, l\u2019Africa Finance Corporation&hellip;\n","protected":false},"author":2,"featured_media":94455,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[58,5231,6,34079,1569,59,34078,1196,34080],"class_list":{"0":"post-94454","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-afrique","8":"tag-58","9":"tag-afc","10":"tag-afrique","11":"tag-babihuga-nsanze","12":"tag-laviation","13":"tag-la-tribune-afrique","14":"tag-rita","15":"tag-secteur","16":"tag-sous-estime"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@afrique\/116526672077670737","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/94454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/comments?post=94454"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/posts\/94454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media\/94455"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/media?parent=94454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/categories?post=94454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/afrique\/wp-json\/wp\/v2\/tags?post=94454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}