{"id":118167,"date":"2026-04-22T18:48:11","date_gmt":"2026-04-22T18:48:11","guid":{"rendered":"https:\/\/www.europesays.com\/at\/118167\/"},"modified":"2026-04-22T18:48:11","modified_gmt":"2026-04-22T18:48:11","slug":"petersberger-klimadialog-friedrich-merz-warnt-vor-deindustrialisierung-durch-klimaschutz","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/118167\/","title":{"rendered":"Petersberger Klimadialog: Friedrich Merz warnt vor Deindustrialisierung durch Klimaschutz"},"content":{"rendered":"<p class=\"paragraph article__item\">Bundeskanzler <a class=\"rtr-entity\" href=\"https:\/\/www.zeit.de\/thema\/friedrich-merz\" rel=\"nofollow noopener\" target=\"_blank\">Friedrich Merz<\/a> (CDU) hat sich auf dem 17. Petersberger Klimadialog grunds\u00e4tzlich zum <a href=\"https:\/\/www.zeit.de\/wirtschaft\/2026-04\/klimaschutz-china-usa-wirtschaft-frieden\" target=\"_blank\" rel=\"nofollow noopener\">Klimaschutz<\/a> bekannt. Zugleich machte er die Einschr\u00e4nkung, dass dieser nicht die <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/gruene-transformation-industrie-klimaschutz-gewerkschaften\" target=\"_blank\" rel=\"nofollow noopener\">Wettbewerbsf\u00e4higkeit der Industrie<\/a> behindern d\u00fcrfe. \u00bbKlimaschutz darf nicht die industrielle Basis unserer L\u00e4nder gef\u00e4hrden\u00ab, sagte Merz in seiner Rede in Berlin.\n<\/p>\n<p class=\"paragraph article__item\">\u00bbEin Wandel, der zu einer \u2060Deindustrialisierung f\u00fchrt, wird in \u200bder Bev\u00f6lkerung keine Akzeptanz finden und letztendlich die Innovation behindern\u00ab, sagte der Kanzler. Deutschland sei dennoch entschlossen, einen starken <a href=\"https:\/\/www.zeit.de\/politik\/deutschland\/2026-03\/klimaschutzprogramm-reiche-schneider-5vor8\" target=\"_blank\" rel=\"nofollow noopener\">Beitrag gegen den Klimawandel<\/a> zu leisten. So werde das Land weiterhin \u200bein wichtiger Geber f\u00fcr \u00f6ffentliche Klimafinanzierung sein.\n<\/p>\n<p>                        \u00bbSaubere Energie ist ein Treiber des Wachstums geworden\u00ab        <\/p>\n<p class=\"paragraph article__item\">Merz hob die Notwendigkeit hervor, <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/klimaschutzprogramm-umweltminister-carsten-schneider-nachrichtenpodcast\" target=\"_blank\" rel=\"nofollow noopener\">Klimaschutz<\/a>, Energiepolitik und Innovation st\u00e4rker miteinander zu verkn\u00fcpfen. Klimapolitik m\u00fcsse auch Politik \u00bbf\u00fcr Sicherheit und weltweiten Wohlstand\u00ab sein. Der Bundesregierung sei dabei bewusst, dass der Klimawandel Konflikte verst\u00e4rke, wirtschaftliche Kosten verursache und \u2013 etwa durch Extremwetter \u2013 Sch\u00e4den an Wirtschaft und Infrastruktur nach sich ziehe.\n<\/p>\n<p class=\"paragraph article__item\">Als Mittel f\u00fcr mehr Klimaschutz nannte der Kanzler den Ausbau erneuerbarer Energien in Deutschland. \u00bbSaubere Energie ist ein<br \/>\nTreiber des Wachstums geworden\u00ab, sagte er. Der \u200cCDU-Chef bekannte sich zudem zu einer CO\u2082-Bepreisung \u00fcber ein<br \/>\nEmissionshandelssystem. Dieses sei \u00bbmarktbasiert und technologieneutral\u00ab,<br \/>\nsagte Merz. Der EU-Emissionshandel m\u00fcsse<br \/>\ndaher \u00bbbeibehalten und fit f\u00fcr die Zukunft\u00ab gemacht werden, \u00bbmit dem<br \/>\nklaren Fokus auf der Bewahrung der Wettbewerbsf\u00e4higkeit\u00ab.\n<\/p>\n<p>        Vorbereitung auf die COP31        <\/p>\n<p class=\"paragraph article__item\">Im Mittelpunkt des 17. Petersberger Klimadialogs stand unter anderem die Frage, <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/atomkraft-europa-energie-klimaziele-frankreich\" target=\"_blank\" rel=\"nofollow noopener\">welchen Beitrag Klimapolitik zu einer sicheren Energieversorgung leisten kann<\/a>. Diskutiert wurden dabei konkrete Wege zur Elektrifizierung von Wirtschaft, Verkehr und W\u00e4rmeerzeugung sowie der weitere Ausbau erneuerbarer Energien als Ersatz f\u00fcr Kohle, \u00d6l und Gas. Dar\u00fcber hinaus stand die internationale Klimafinanzierung auf der Agenda.\n<\/p>\n<p class=\"paragraph article__item\">An dem zweit\u00e4gigen internationalen Treffen nahmen Ministerinnen und Minister aus mehr als 40 L\u00e4ndern teil. Schwerpunkte waren der klimapolitische Austausch sowie die Vorbereitung der 31. Weltklimakonferenz (COP31), die vom 9. bis 20. November in Antalya stattfinden soll. Deutschland war durch Bundesumweltminister Carsten Schneider (SPD) und Umweltstaatssekret\u00e4r Jochen Flasbarth vertreten.\n<\/p>\n<p>Mehr zum Thema<\/p>\n<p>                <a href=\"https:\/\/www.zeit.de\/hamburg\/2026-04\/co2-abscheidung-hamburger-hafen-klimaneutralitaet-faq\" data-ct-label=\"CO\u2082-Abscheidung im Hamburger Hafen: &quot;Ohne uns wird die Stadt ihre Klimaziele nicht erreichen&quot;\" data-uuid=\"49d2c22c-76fd-4f16-ae78-01432f5f089a\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>        Z+ (abopflichtiger Inhalt);<\/p>\n<p>    CO\u2082-Abscheidung im Hamburger Hafen:<br \/>\n                        &#8222;Ohne uns wird die Stadt ihre Klimaziele nicht erreichen&#8220;<\/p>\n<p>                <\/a><\/p>\n<p>                <a href=\"https:\/\/www.zeit.de\/wirtschaft\/2026-04\/klimaschutz-china-usa-wirtschaft-frieden\" data-ct-label=\"Klimaschutz: Nein, es ist nicht egal, was Deutschland f\u00fcrs Klima tut\" data-uuid=\"68e33ebf-ae68-4a41-ad01-8363b6666339\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>                        Klimaschutz:<br \/>\n                        Nein, es ist nicht egal, was Deutschland f\u00fcrs Klima tut<\/p>\n<p>                <\/a><\/p>\n<p>                <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/gruene-transformation-industrie-klimaschutz-gewerkschaften\" data-ct-label=\"Krisenpodcast &quot;Auch das noch?&quot;: &quot;Klimaschutz und Industriearbeit sind kein Widerspruch.&quot;\" data-uuid=\"0f6ef7c8-f4cb-427d-a6c5-355754dfd441\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>                        Krisenpodcast &#8222;Auch das noch?&#8220;:<br \/>\n                        &#8222;Klimaschutz und Industriearbeit sind kein Widerspruch.&#8220;<\/p>\n<p>                <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Bundeskanzler Friedrich Merz (CDU) hat sich auf dem 17. Petersberger Klimadialog grunds\u00e4tzlich zum Klimaschutz bekannt. Zugleich machte er&hellip;\n","protected":false},"author":2,"featured_media":118168,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[2840,8501,741,41639,3281,40,41,41638,39,66,3295,65,64],"class_list":{"0":"post-118167","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-cdu","9":"tag-emissionshandel","10":"tag-friedrich-merz","11":"tag-industriebetrieb","12":"tag-klimawandel","13":"tag-nachrichten","14":"tag-news","15":"tag-petersberger-klimadialog","16":"tag-schlagzeilen","17":"tag-welt","18":"tag-wissen","19":"tag-world","20":"tag-world-news"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116449856884988728","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/118167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=118167"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/118167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/118168"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=118167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=118167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=118167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}