{"id":147460,"date":"2026-05-08T15:24:07","date_gmt":"2026-05-08T15:24:07","guid":{"rendered":"https:\/\/www.europesays.com\/at\/147460\/"},"modified":"2026-05-08T15:24:07","modified_gmt":"2026-05-08T15:24:07","slug":"alles-was-zaehlt-heute-im-tv-wenn-die-wahrheit-ans-licht-kommt-unterhaltung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/147460\/","title":{"rendered":"\u201eAlles was z\u00e4hlt\u201c heute im TV: Wenn die Wahrheit ans Licht kommt | Unterhaltung"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>Die beliebte Daily Soap \u201eAlles was z\u00e4hlt\u201c begeistert t\u00e4glich seit fast zwei Jahrzehnten mit fesselnden Geschichten rund um Liebe, Ehrgeiz und famili\u00e4re Konflikte. In der beliebten Serie \u201eAlles was z\u00e4hlt\u201c ist immer etwas los. Doch was erwartet die Zuschauer heute? Eines ist sicher: Auch heute gibt es wieder einige spannende Wendungen. <\/p>\n<p>Lesen Sie hier die Vorschau auf die Folge 4942 von \u201eAlles was z\u00e4hlt\u201c am 8. Mai 2026 im TV.<\/p>\n<p>Darum geht es heute bei \u201eAlles was z\u00e4hlt\u201c<\/p>\n<p>Hier ist die Vorschau zur neuen Folge 4942 von <a href=\"https:\/\/www.bild.de\/unterhaltung\/tv\/alles-was-zaehlt\/alles-was-zaehlt-alle-infos-86249316.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">\u201eAlles was z\u00e4hlt\u201c<\/a> am Freitag, dem 8. Mai 2026, im Free-TV:<\/p>\n<p>Sp\u00e4testens nach dem positiven Dopingtest wird Charlie (Shaolyn Fernandez) schnell klar, was geschehen sein muss: Offenbar hat Valea (Antonia Kolano, 21) ihr heimlich ein verbotenes Mittel verabreicht, um sie von der Teilnahme an der Deutschen Meisterschaft auszuschlie\u00dfen. Beweisen kann sie ihren Verdacht jedoch nicht, und Valea weist jede Schuld zur\u00fcck. Kurz darauf sieht sich Charlie gezwungen, die WG zu verlassen, die sie sich neben Leyla (Suri Abbassi, 31) und Lucie (Julia Wiedemann, 30) auch mit Valea teilt. Bevor sie geht, stellt sie Valea ein letztes Mal vor ihren Mitbewohnerinnen zur Rede \u2013 doch diese bleibt bei ihrer Version und streitet weiterhin alles ab.<\/p>\n<p>Nachdem Charlie ausgezogen ist, sucht Valea das Gespr\u00e4ch mit Leyla und Lucie unter vier Augen. Dabei versucht sie, die beiden davon zu \u00fcberzeugen, dass Charlie die Tabletten selbst eingenommen habe. Doch gelingt es ihr, ihre Freundinnen auf ihre Seite zu ziehen? Parallel dazu distanziert sich Joana (Josephine Martz, 25) zunehmend von Valeas b\u00f6sartigem Plan. Zwischen den beiden kommt es zu Spannungen, die schlie\u00dflich in einem heftigen Streit mit gravierenden Folgen eskalieren.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Mikas (Daniel Noah, 39) Partnerin in Crime taucht auf \u2013 und der Zeitpunkt k\u00f6nnte kaum schlechter sein\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/05\/e44d3a24dade30c693ffee79356607d1,466de0d8.jpeg\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Mikas (Daniel Noah, 39) Partnerin in Crime taucht auf \u2013 und der Zeitpunkt k\u00f6nnte kaum schlechter sein<\/p>\n<p>Foto: RTL\/Julia Feldhagen<\/p>\n<p>Infolge eines intensiven Momentes mit Imani (F\u00e9r\u00e9ba Kon\u00e9, 35) beginnt Mika (Daniel Noah, 39) mehr und mehr, an seinen r\u00fccksichtslosen Pl\u00e4nen zu zweifeln \u2013 doch unerwartete Entwicklungen bringen ihn zus\u00e4tzlich ins Wanken. Auch bei den Steinkamps gehen die Emotionen auseinander: W\u00e4hrend einige versuchen, der Situation etwas Positives abzugewinnen, kochen bei anderen die Gef\u00fchle hoch. Wie es weitergeht, sehen Sie schon heute bei \u201eAlles was z\u00e4hlt\u201c, am 8. Mai um 19:05 Uhr, auf RTL im <a href=\"https:\/\/www.bild.de\/unterhaltung\/tv\/tv\/tv-15479870.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Free-TV<\/a>.<\/p>\n<p>Wo und wann l\u00e4uft \u201eAlles was z\u00e4hlt\u201c?<\/p>\n<p>\u201eAlles was z\u00e4hlt\u201c l\u00e4uft montags bis freitags um 19:05 Uhr auf <a href=\"https:\/\/www.bild.de\/themen\/organisationen\/rtl\/groesster-privatsender-in-deutschland-19409690.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">RTL<\/a>. Die neuesten Folgen sind bereits eine Woche vorab um 19:40 Uhr im Stream auf <a href=\"https:\/\/my.plus.rtl.de\/buchen\/initial?ref=CTA-BUCHEN-MENU&amp;utm_source=awin&amp;utm_medium=cpo&amp;utm_campaign=TVN00001_Affiliate&amp;utm_term=508711&amp;utm_content=statics.teams.cdn.office.net&amp;awc=16040_1723632692_f28796a5c3f66306bcbcc20f14e47abd\" target=\"_blank\" rel=\"nofollow noopener\" class=\"text-link--external text-link\">RTL+<\/a> (ANZEIGE) verf\u00fcgbar.<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Die beliebte Daily Soap \u201eAlles was z\u00e4hlt\u201c begeistert t\u00e4glich seit fast zwei Jahrzehnten mit fesselnden&hellip;\n","protected":false},"author":2,"featured_media":147461,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[2351,46,42,989,147,987,44,281,986,156,155,988,148],"class_list":{"0":"post-147460","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serien","8":"tag-alles-was-zaehlt","9":"tag-at","10":"tag-austria","11":"tag-daily-soap","12":"tag-entertainment","13":"tag-g-standard","14":"tag-oesterreich","15":"tag-rtl","16":"tag-seo-nicht-benutzen","17":"tag-serien","18":"tag-series","19":"tag-tv-formate","20":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116539651824343129","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/147460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=147460"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/147460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/147461"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=147460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=147460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=147460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}