{"id":14956,"date":"2026-02-26T17:30:06","date_gmt":"2026-02-26T17:30:06","guid":{"rendered":"https:\/\/www.europesays.com\/at\/14956\/"},"modified":"2026-02-26T17:30:06","modified_gmt":"2026-02-26T17:30:06","slug":"leitboersen-in-asien-ueberwiegend-hoeher","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/14956\/","title":{"rendered":"Leitb\u00f6rsen in Asien \u00fcberwiegend h\u00f6her"},"content":{"rendered":"<p>Die positiven Impulse kamen vor allem aus den USA. Dort hatten die wichtigsten Indizes ihre Erholung vor der Ver\u00f6ffentlichung von Quartalszahlen von Nvidia fortgesetzt. Nachb\u00f6rslich lieferte die KI-Koryph\u00e4e dann zwar, denn mit dem Schlussquartal 2025\/26 setzte Nvidia nochmals eins drauf und meldete das bisher beste Quartal in der Unternehmensgeschichte.<\/p>\n<p>Die Freude \u00fcber den 14. Gewinnanstieg in Folge sowie \u00fcber die besser als erwartet ausgefallene Umsatzprognose f\u00fcr das erste Gesch\u00e4ftsquartal blieb aber teils ged\u00e4mpft. Zwischenzeitlich zeichneten sich f\u00fcr Donnerstag Verluste f\u00fcr das Papier ab, zuletzt dann aber wieder Gewinne. Die Zahlen reichten nach Einsch\u00e4tzung von Marktexperte Thomas Altmann von QC Partners nicht aus, um die uneingeschr\u00e4nkte Begeisterung rund um K\u00fcnstliche Intelligenz (KI) zur\u00fcckzubringen.<\/p>\n<p>Mit Blick auf die Anleger in Asien allerdings behielt aber wohl Marktstratege Stephen Innes vom Verm\u00f6gensverwalter SPI Asset Management zun\u00e4chst weiter recht: Anstatt die negativen Folgen von KI f\u00fcr viele Bereiche der Wirtschaft zu diskutieren, konzentriere man sich in Asien allgemein mehr auf die Investitionen in die ben\u00f6tigte Infrastruktur.<\/p>\n<p>Der japanische Leitindex Nikkei 225 schloss 0,3 Prozent h\u00f6her mit 58.753,39 Punkten. Im Fokus der Anleger stand nicht zuletzt Toyota Motor. Toyota strebt laut einem Bericht der Nachrichtenagentur Reuters eine Verringerung strategischer Beteiligungen im Wert von rund 3 Billionen Yen (16 Mrd Euro) an, die Banken und anderen Finanzinstitute an dem Autobauer halten. Toyota strebe diesen Verkauf voraussichtlich noch in diesem Jahr an, es sei aber auch m\u00f6glich, dass der Plan ganz verworfen werde, hie\u00df es von mit der Angelegenheit vertrauten Personen. Ein Sprecher von Toyota Motor lehnte eine Stellungnahme zu dem Bericht Reuters gegen\u00fcber ab.<\/p>\n<p>Aus Sicht der Corporate Governance, einer guten Unternehmensf\u00fchrung, sei diese Nachricht positiv, sagte ein Experte. Toyotas Plan falle zudem mit der geplanten \u00dcberarbeitung des japanischen Corporate-Governance-Kodex in diesem Jahr zusammen, sodass der Autobauer von den positiven Auswirkungen profitieren d\u00fcrfte. Die Aktie legte um 1,5 Prozent zu.<\/p>\n<p>Der australische ASX lag wie der Nikkei ebenfalls moderat im Plus. Zudem ging es in S\u00fcdkorea, wo die dortige Zentralbank den Leitzins bei 2,50 Prozent beibehielt, sehr deutlich weiter nach oben.<\/p>\n<p>Der CSI-300-Index der chinesischen Festlandb\u00f6rsen gab hingegen um 0,19 Prozent auf 4.727 Z\u00e4hler nach. Der Hang Seng in Hongkong b\u00fc\u00dfte 1,44 Prozent auf 26.381 Punkte ein.<\/p>\n","protected":false},"excerpt":{"rendered":"Die positiven Impulse kamen vor allem aus den USA. Dort hatten die wichtigsten Indizes ihre Erholung vor der&hellip;\n","protected":false},"author":2,"featured_media":14957,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[874,2338,46,42,95,249,90,89,7899,538,1013,534,91,927,94,7900,44,7901,2337,93,92,921,535],"class_list":{"0":"post-14956","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-unternehmen-maerkte","8":"tag-aktienmarkt","9":"tag-asien","10":"tag-at","11":"tag-austria","12":"tag-business","13":"tag-china","14":"tag-companies","15":"tag-companies-markets","16":"tag-hongkong","17":"tag-horizontal","18":"tag-japan","19":"tag-kurz","20":"tag-markets","21":"tag-marktbericht","22":"tag-maerkte","23":"tag-nikkei-225","24":"tag-oesterreich","25":"tag-stocks","26":"tag-tokio","27":"tag-unternehmen","28":"tag-unternehmen-maerkte","29":"tag-wirtschaft-boerse","30":"tag-wissen-update-me"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/14956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=14956"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/14956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/14957"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=14956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=14956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=14956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}