{"id":151634,"date":"2026-05-11T06:27:09","date_gmt":"2026-05-11T06:27:09","guid":{"rendered":"https:\/\/www.europesays.com\/at\/151634\/"},"modified":"2026-05-11T06:27:09","modified_gmt":"2026-05-11T06:27:09","slug":"ein-unscheinbares-protein-programmiert-bakterien-auf-angriff","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/151634\/","title":{"rendered":"Ein unscheinbares Protein programmiert Bakterien auf Angriff"},"content":{"rendered":"<p>Bakterielle Infektionen k\u00f6nnen harmlos bleiben, doch manche nehmen einen gef\u00e4hrlichen Verlauf. Beispielsweise bei der Leptospirose, hier reicht das Verlaufsspektrum von asymptomatisch bis hin zu t\u00f6dlich. Ob eine Infektion mit dem Bakterium Leptospira leicht oder schwer verl\u00e4uft, entscheidet ein unscheinbares Protein im Inneren des Bakteriums. Denn diese Bakterien sind nicht dauerhaft gef\u00e4hrlich. Sie aktivieren ihre Angriffsf\u00e4higkeit erst im richtigen Moment. Eben diesen Mechanismus hat ein Forschungsteam nun entschl\u00fcsselt. Die Ergebnisse stammen aus einer <a href=\"https:\/\/www.nature.com\/articles\/s41467-026-71783-4\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Studie<\/a> der\u00a0<a href=\"https:\/\/www.biozentrum.unibas.ch\/de\/news\/detail\/how-pathogens-switch-on-their-virulence\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Universit\u00e4t Basel<\/a>, ver\u00f6ffentlicht im Fachjournal\u00a0Nature Communications. <\/p>\n<p>Das Protein funktioniert dabei wie ein Schalter und entscheidet, wann ein Erreger im K\u00f6rper aktiv wird. Dieser Baustein steuert das Angriffspotenzial des Bakteriums Leptospira. Blockiert man diesen Schalter, k\u00f6nnten Infektionen auch ohne Antibiotika abgeschw\u00e4cht werden.<\/p>\n<p>Krankheitserreger werden erst im K\u00f6rper gef\u00e4hrlich<\/p>\n<p>Mit Leptospirose infizieren sich Menschen meist \u00fcber verunreinigtes Wasser oder Erde, die Tr\u00e4ger der Leptospira-Bakterien sind Nager oder infizierte Nutztiere. Weltweit erkranken jedes Jahr rund eine Million Menschen schwer. Etwa 60.000 sterben daran. Ohne schnelle Behandlung droht Organversagen. <\/p>\n<p>Besonders in Regionen mit wenig medizinischer Versorgung ist die Krankheit ein gro\u00dfes Problem. Auch in Europa treten immer wieder F\u00e4lle auf, vor allem bei Landwirten, Tier\u00e4rzten, Laborpersonal oder Kanalarbeitern.<\/p>\n<p>Ein Protein h\u00e4lt den Erreger vorerst in Schach<\/p>\n<p>Der Erreger verh\u00e4lt sich zun\u00e4chst unauff\u00e4llig. Erst im K\u00f6rper aktiviert er gezielt seine krankmachenden Eigenschaften. Im Zentrum steht das Protein LvrB. Es steuert, ob das Bakterium gef\u00e4hrlich wird. Im Ruhezustand bleibt LvrB blockiert.<\/p>\n<p>\u201eIm Aus-Zustand ist LvrB in einer symmetrischen und damit inaktiven Form fixiert, in der es keine Virulenzfaktoren aktivieren kann\u201c, erkl\u00e4rt Erstautor <a href=\"https:\/\/scholar.google.com\/citations?user=UrAyTEQAAAAJ&amp;hl=en\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Elia Agustoni<\/a>. In diesem Zustand produziert der Erreger keine krankmachenden Faktoren. Das spart Energie und verhindert unn\u00f6tige Aktivit\u00e4t au\u00dferhalb eines Wirts.<\/p>\n<p>Ein Signal kippt die Struktur und startet den Angriff<\/p>\n<p>Sobald das Bakterium in den K\u00f6rper gelangt, \u00e4ndern sich die Bedingungen. Signale vom Wirt l\u00f6sen zun\u00e4chst eine chemische Reaktion aus. \u201eLvrB ver\u00e4ndert seine Form, die Symmetrie wird aufgebrochen, wodurch das Protein quasi aktiviert wird\u201c, sagt Agustoni. Die zuvor blockierten Bereiche werden beweglich. Das Protein kann sich selbst aktivieren und gibt Signale weiter.<\/p>\n<p>Nach der Aktivierung arbeitet LvrB mit einem Partnerprotein namens LvrC zusammen. Dieses wirkt als sogenannter Anti-\u03c3-Faktor und greift direkt in die Gensteuerung ein. Innerhalb kurzer Zeit werden hunderte <a href=\"https:\/\/smartup-news.de\/wissen\/wilde-gene-machen-viele-aepfel-widerstandsfaehiger\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Gene<\/a> umprogrammiert. Sie steuern die Angriffsf\u00e4higkeit des Erregers:<\/p>\n<p>Der Erreger kann sich im K\u00f6rper vermehren<\/p>\n<p>Er kann Gewebe befallen<\/p>\n<p>Er kann das Immunsystem umgehen<\/p>\n<p>So passt sich das Bakterium gezielt an seine Umgebung an und breitet sich aus.<\/p>\n<p>Neuer Therapieansatz setzt direkt am Schalter an<\/p>\n<p>Die Erkenntnisse aus der Baseler Studie er\u00f6ffnen neue Wege in der Medizin. Statt Bakterien abzut\u00f6ten, l\u00e4sst sich ihr Gefahrenpotenzial blockieren. Bleibt LvrB inaktiv, kann der Erreger keine <a href=\"https:\/\/smartup-news.de\/finanzen\/finanzieller-knick-krankheit-kostet-oft-jahrelang-einkommen\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Krankheit<\/a> ausl\u00f6sen. Studienleiter\u00a0<a href=\"https:\/\/www.biozentrum.unibas.ch\/de\/forschung\/research-groups\/research-groups-a-z\/overview\/unit\/forschungsgruppe-sebastian-hiller\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Sebastian Hiller<\/a>\u00a0sagt: \u201eGel\u00e4nge es, LvrB dauerhaft auszuschalten, k\u00f6nnte man verhindern, dass der Erreger im K\u00f6rper auf \u201avirulent\u2018, also auf \u201agef\u00e4hrlich\u2018 umschaltet.\u201c<\/p>\n<p>Ein solcher Ansatz bietet mehrere Vorteile:<\/p>\n<p>Der Erreger bleibt zwar vorhanden, richtet aber keinen Schaden an<\/p>\n<p>Der Selektionsdruck sinkt, Resistenzen entstehen langsamer<\/p>\n<p>Therapien k\u00f6nnten gezielter wirken<\/p>\n<p>Fachleute sehen in der Blockade des Proteins eine m\u00f6gliche Alternative zu klassischen Antibiotika.<\/p>\n<p>Mechanismus k\u00f6nnte viele Krankheitserreger betreffen<\/p>\n<p>Das Protein LvrB geh\u00f6rt zu einer gr\u00f6\u00dferen Gruppe von sogenannten Histidin-Kinasen. Diese kommen in vielen Bakterien vor. Der jetzt entschl\u00fcsselte Mechanismus liefert ein Modell f\u00fcr \u00e4hnliche Systeme.<\/p>\n<p>\u201eWir verstehen nun auf atomarer Ebene, wie dieser molekulare Schalter funktioniert\u201c, sagt Hiller. \u201eUnd noch wichtiger, wir haben einen generellen Aktivierungsmechanismus entdeckt, der eine Vielzahl weiterer bakterieller Proteine betrifft.\u201c Damit w\u00e4chst die Chance, neue <a href=\"https:\/\/smartup-news.de\/gesundheit\/magenkrebs-neuer-wirkstoff-60-mal-effektiver-gegen-bakterium\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Wirkstoffe<\/a> zu entwickeln, die gezielt an solchen Schaltern ansetzen.<\/p>\n<p>Kurz zusammengefasst:<\/p>\n<p>Krankheitserreger werden nicht dauerhaft gef\u00e4hrlich, sondern aktivieren ihre Angriffsf\u00e4higkeit erst im K\u00f6rper \u00fcber einen pr\u00e4zisen molekularen Schalter wie das Protein LvrB.<\/p>\n<p>Dieser Schalter ver\u00e4ndert seine Struktur durch Signale des Wirts, aktiviert dadurch hunderte Gene und erm\u00f6glicht dem Erreger, sich anzupassen, sich zu vermehren und das Immunsystem zu umgehen.<\/p>\n<p>Neue Therapien k\u00f6nnten ansetzen, indem sie den Schalter blockieren und Krankheitserreger unsch\u00e4dlich machen.<\/p>\n<p>\u00dcbrigens: \u00c4hnlich wie Bakterien schalten auch Pilze ihre Gef\u00e4hrlichkeit durch Aktivierung bestimmter Mechanismen frei \u2013 vor allem bei W\u00e4rme und im menschlichen K\u00f6rper. Was dahinter steckt und warum daraus neue Krankheitserreger entstehen k\u00f6nnen, mehr dazu in unserem <a href=\"https:\/\/smartup-news.de\/wissen\/pilze-werden-krankheitserreger-wenn-die-umwelt-koerperwarm-wird\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Artikel<\/a>.<\/p>\n<p>Bild: \u00a9 <a href=\"https:\/\/phil.cdc.gov\/PHIL_Images\/20050308\/22ad4ce53a1648feb011a7d6dd26fbb6\/138_lores.jpg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">CDC\/ Rob Weyant<\/a> via <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Leptospira_scanning_micrograph.jpg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Wikimedia<\/a> unter <a href=\"https:\/\/en.wikipedia.org\/wiki\/Public_domain\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Public Domain<\/a><\/p>\n<p>                Tags: <a href=\"https:\/\/smartup-news.de\/tag\/antibiotika\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Antibiotika<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/antibiotikaresistenzen\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Antibiotikaresistenzen<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/bakterien\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Bakterien<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/gesundheit\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Gesundheit<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/krankheitserreger\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Krankheitserreger<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/leptospira\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Leptospira<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/leptospirose\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Leptospirose<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/medizin\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Medizin<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/protein\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Protein<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/smart-up-news\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Smart Up News<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/studie\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Studie<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/universitaet-basel\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Universit\u00e4t Basel<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/virulenz\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Virulenz<\/a>,<a href=\"https:\/\/smartup-news.de\/tag\/zoonose\/\" rel=\"tag nofollow noopener\" target=\"_blank\">Zoonose<\/a>            <\/p>\n<p>              0%<br \/>\n              Love<\/p>\n<p>              0%<br \/>\n              Funny<\/p>\n<p>              0%<br \/>\n              Wow<\/p>\n<p>              0%<br \/>\n              Sad<\/p>\n<p>              0%<br \/>\n              Angry<\/p>\n<p>\t\tBeitragsnavigation<\/p>\n","protected":false},"excerpt":{"rendered":"Bakterielle Infektionen k\u00f6nnen harmlos bleiben, doch manche nehmen einen gef\u00e4hrlichen Verlauf. Beispielsweise bei der Leptospirose, hier reicht das&hellip;\n","protected":false},"author":2,"featured_media":151635,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[4865,49159,46,42,3358,124,123,49160,49161,49162,125,44,17782,43409,1490,26069,36866,11597],"class_list":{"0":"post-151634","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gesundheit","8":"tag-antibiotika","9":"tag-antibiotikaresistenzen","10":"tag-at","11":"tag-austria","12":"tag-bakterien","13":"tag-gesundheit","14":"tag-health","15":"tag-krankheitserreger","16":"tag-leptospira","17":"tag-leptospirose","18":"tag-medizin","19":"tag-oesterreich","20":"tag-protein","21":"tag-smart-up-news","22":"tag-studie","23":"tag-universitaet-basel","24":"tag-virulenz","25":"tag-zoonose"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116554527045068116","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/151634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=151634"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/151634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/151635"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=151634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=151634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=151634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}