{"id":155255,"date":"2026-05-13T01:20:10","date_gmt":"2026-05-13T01:20:10","guid":{"rendered":"https:\/\/www.europesays.com\/at\/155255\/"},"modified":"2026-05-13T01:20:10","modified_gmt":"2026-05-13T01:20:10","slug":"erste-sitzung-von-ungarns-neuer-regierung-nicht-in-budapest","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/155255\/","title":{"rendered":"Erste Sitzung von Ungarns neuer Regierung nicht in Budapest"},"content":{"rendered":"<p _ngcontent-tt-com-www-c3071245697=\"\" data-cy=\"body\">Die erste Sitzung der am Dienstag angelobten ungarischen Regierung findet am Mittwoch nicht in der Hauptstadt Budapest statt, sondern ab 15.00 Uhr in der rund 2.000 Einwohner z\u00e4hlenden Ortschaft \u00d2pusztaszer im Komitat Csongr\u00e1d-Csan\u00e1d. Das schrieb Ministerpr\u00e4sident P\u00e8ter Magyar Dienstagabend auf Facebook. \u00d3pusztaszer gilt als Wiege der ungarischen Staatlichkeit. Im Jahr 896 soll F\u00fcrst \u00c1rp\u00e1d hier mit seinen sieben Stammesf\u00fchrern die ersten gemeinsamen Gesetze kodifiziert haben.<\/p>\n<p _ngcontent-tt-com-www-c3071245697=\"\" data-cy=\"body\">Heute ist der Ort als &#8222;Nationaler Historischer Gedenkpark&#8220; ein bedeutendes Freilichtmuseum, das die Geschichte, Kultur und Landnahme der Ungarn durch Ausstellungen, historische Geb\u00e4ude und das ber\u00fchmte 120 Meter lange Feszty-Panorama-Gem\u00e4lde erlebbar macht. <\/p>\n<p _ngcontent-tt-com-www-c3071245697=\"\" data-cy=\"body\">Neben der historischen Bedeutung wurde die Wahl des Ortes in der s\u00fcdungarischen Tiefebene auch mit der aktuell au\u00dferordentlichen D\u00fcrre gerechtfertigt. Vor der Sitzung soll es zu Begegnungen mit Wasser- und Landwirtschaftsexperten kommen, die das neue Kabinett mit Informationen \u00fcber die aktuelle Lage versorgen soll. Danach werde \u00fcber notwendige kurzfristige Ma\u00dfnahmen entschieden, hie\u00df es.<\/p>\n<p _ngcontent-tt-com-www-c3071245697=\"\" data-cy=\"body\">Laut Magyar wird die Regierung die sofortige, umfassende \u00dcberpr\u00fcfung von Ministerien, Staatsunternehmen sowie die Aussetzung von Zahlungen und Verpflichtungen er\u00f6rtern, die \u00fcber den Rahmen der normalen Verwaltung hinausgehen. Auf der Tagesordnung stehen weiters geplante \u00c4nderungen des Grundgesetzes und anderer wichtiger Rechtsbestimmungen sowie Informationen zur Lage der Energieversorgung des Landes und Kinderschutz.<\/p>\n<p _ngcontent-tt-com-www-c3071245697=\"\" data-cy=\"body\">Es soll laut Magyar auch um die Freigabe ehemaliger geheimer Regierungsbeschl\u00fcsse und internationaler Vertr\u00e4ge gehen. Die \u00d6ffentlichkeit soll nach der Regierungssitzung dar\u00fcber informiert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"Die erste Sitzung der am Dienstag angelobten ungarischen Regierung findet am Mittwoch nicht in der Hauptstadt Budapest statt,&hellip;\n","protected":false},"author":2,"featured_media":155256,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[2371,75,8366,3281,679,40,41,1434,39,2066,66,65,64],"class_list":{"0":"post-155255","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-welt","8":"tag-budapest","9":"tag-europa","10":"tag-grundrechte","11":"tag-klimawandel","12":"tag-konflikte","13":"tag-nachrichten","14":"tag-news","15":"tag-newsticker","16":"tag-schlagzeilen","17":"tag-ungarn","18":"tag-welt","19":"tag-world","20":"tag-world-news"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/155255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=155255"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/155255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/155256"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=155255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=155255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=155255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}