{"id":15620,"date":"2026-02-27T02:00:08","date_gmt":"2026-02-27T02:00:08","guid":{"rendered":"https:\/\/www.europesays.com\/at\/15620\/"},"modified":"2026-02-27T02:00:08","modified_gmt":"2026-02-27T02:00:08","slug":"shia-labeouf-knallhart-urteil-nach-suff-schlaegerei-unterhaltung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/15620\/","title":{"rendered":"Shia LaBeouf: Knallhart-Urteil nach Suff-Schl\u00e4gerei | Unterhaltung"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>New Orleans (USA) \u2013 Er war einst einer der gefragtesten Schauspieler Hollywoods\u00a0\u2013 dann kam der gro\u00dfe Fall! Schauspieler Shia LaBeouf (39, \u201eTransformers\u201c) muss sich nach seiner Festnahme in New Orleans nun erneut einem Drogen- und Alkoholentzug unterziehen. Das ordnete eine Richterin jetzt an.<\/p>\n<p>Der Vorwurf wiegt schwer: Beim legend\u00e4ren Mardi Gras (Karneval) soll <a href=\"https:\/\/www.bild.de\/themen\/personen\/shia-labeouf\/unterhaltung-leute-nachrichten-news-fotos-videos-15815030.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Shia LaBeouf <\/a>am 17. Februar vor einer Bar nahe dem ber\u00fchmten French Quarter mehrere Menschen geschlagen haben. Laut Polizeibericht kehrte er sogar zur\u00fcck \u2013 und soll mit geschlossener Faust auf G\u00e4ste losgegangen sein, nachdem man ihn zuvor aus dem Lokal geworfen hatte.<\/p>\n<p>Aufnahmen zeigen, wie der Filmstar auf mehrere Personen einschl\u00e4gt. Auf einem Video ist zu sehen, <a href=\"https:\/\/www.bild.de\/unterhaltung\/stars-und-leute\/pruegelnacht-shia-labeouf-gab-kontrahent-eine-kopfnuss-6995065e6e842744e5c58dae\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">dass der Schauspieler einem Kontrahenten eine Kopfnuss verpasste.<\/a> Ein mutma\u00dfliches Opfer erlitt eine schwere Nasenverletzung. <\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"661\" alt=\"Shia LaBeouf war einst ein Frauenschwarm und einer der ganz gro\u00dfen Stars in Hollywood\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/02\/a1ff1a1684e55e7c3aeaff752024ee82,288e3ef4.jpeg\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Shia LaBeouf war einst ein Frauenschwarm und einer der ganz gro\u00dfen Stars in Hollywood<\/p>\n<p>Foto: IMAGO\/ABACAPRESS<\/p>\n<p>Richterin r\u00fcgt schwulenfeindliche \u00c4u\u00dferungen <\/p>\n<p>Zus\u00e4tzlich steht der Vorwurf im Raum, dass LaBeouf w\u00e4hrend des Vorfalls schwulenfeindliche Beleidigungen ge\u00e4u\u00dfert haben soll. Die Richterin r\u00fcgte ihn daf\u00fcr deutlich im Gerichtssaal. Opfer Jeffrey Damnit (49) sagte zu \u201e<a href=\"https:\/\/people.com\/shia-labeouf-s-mugshot-released-after-mardi-gras-arrest-in-new-orleans-11908777\" target=\"_blank\" rel=\"nofollow noopener\" class=\"text-link--external text-link\">People<\/a>\u201c, der Schauspieler habe in der Bar \u201eRoyal Street Inn &amp; R Bar\u201c homophobe Beleidigungen ge\u00e4u\u00dfert und angefangen, \u201ealle anzuschreien\u201c und G\u00e4ste \u201eanzugehen\u201c. LaBeouf soll volltrunken gewesen sein. Eine genaue Promillezahl ist nicht bekannt. <\/p>\n<p>Mehr zum Thema<\/p>\n<p>Wegen zweifacher K\u00f6rperverletzung ist LaBeouf angeklagt. Die Richterin setzte eine Kaution in H\u00f6he von 100.000 Dollar fest \u2013 die zahlte der Schauspieler umgehend. Eine Hauptverhandlung folgt. <\/p>\n<p>Kino-Star muss w\u00f6chentlich zum Drogentest <\/p>\n<p>Doch damit nicht genug: Shia LaBeouf muss sich nun w\u00f6chentlich Drogentests unterziehen. Einer wurde direkt im Gerichtssaal durchgef\u00fchrt. Laut seiner Anw\u00e4ltin wurden dabei keine illegalen Substanzen festgestellt.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"662\" alt=\"Shia LaBeouf (damals 22, r.) 2008 mit Harrison Ford (damals 66, heute 83) im Blockbuster \u201eIndiana Jones und das K\u00f6nigreich des Kristallsch\u00e4dels\u201c\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/02\/c7744800dff225ccf4b184b364bce1ad,5aca8b09.jpeg\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Shia LaBeouf (damals 22, r.) 2008 mit Harrison Ford (damals 66, heute 83) im Blockbuster \u201eIndiana Jones und das K\u00f6nigreich des Kristallsch\u00e4dels\u201c<\/p>\n<p>Foto: David James\/Paramount Pictures<\/p>\n<p>Auch sein Wunsch, im M\u00e4rz nach <a href=\"https:\/\/www.bild.de\/themen\/orte\/rom\/nachrichten-news-fotos-videos-17248314.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Rom (Italien) <\/a>zu reisen, wurde abgelehnt. Die Richterin verweigerte die Ausreisegenehmigung. Er wollte angeblich zur Taufe seines Vaters fliegen. <\/p>\n<p>F\u00fcr LaBeouf beginnt damit erneut eine schwierige Phase. Der einstige \u201eTransformers\u201c-Star k\u00e4mpft seit Jahren mit Alkohol- und Drogenproblemen, wurde bereits mehrfach von der Polizei festgenommen (u.a. wegen \u00f6ffentlicher Trunkenheit). Ob er diesmal die Kurve bekommt?<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen New Orleans (USA) \u2013 Er war einst einer der gefragtesten Schauspieler Hollywoods\u00a0\u2013 dann kam der&hellip;\n","protected":false},"author":2,"featured_media":15621,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[4274,46,42,175,147,4272,4273,44,405,176,204,209,210,148,439],"class_list":{"0":"post-15620","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-alkohol","9":"tag-at","10":"tag-austria","11":"tag-celebrities","12":"tag-entertainment","13":"tag-labeouf-shia","14":"tag-new-orleans","15":"tag-oesterreich","16":"tag-polizei","17":"tag-prominente","18":"tag-schauspieler","19":"tag-team-first","20":"tag-texttospeech","21":"tag-unterhaltung","22":"tag-usa"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/15620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=15620"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/15620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/15621"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=15620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=15620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=15620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}