{"id":20611,"date":"2026-03-02T03:31:17","date_gmt":"2026-03-02T03:31:17","guid":{"rendered":"https:\/\/www.europesays.com\/at\/20611\/"},"modified":"2026-03-02T03:31:17","modified_gmt":"2026-03-02T03:31:17","slug":"wuthering-heights-margot-robbie-und-jacob-elordi-entfachen-liebesgeruechte-unterhaltung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/20611\/","title":{"rendered":"\u201eWuthering Heights\u201e: Margot Robbie und Jacob Elordi entfachen Liebesger\u00fcchte | Unterhaltung"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>Die Liebe ist bekanntlich ein seltsames Spiel. Und wirkt manchmal auch seltsam gespielt. Seit Wochen lustwandeln die Hollywoodstars Margot Robbie (35, \u201eBarbie\u201c) und Jacob Elordi (28, \u201eFrankenstein\u201c) \u00fcber die roten Teppiche dieser Welt, um ihren neuen Film \u201eWuthering Heights\u201c (jetzt im Kino) zu bewerben. So weit, so gut, so \u00fcblich.<\/p>\n<p>Doch nicht nur Filmfans fragen sich: Haben die beiden Starschauspieler ihre Rollen vom Set einfach auch ins echte Leben verl\u00e4ngert? Kein <a href=\"https:\/\/www.bild.de\/unterhaltung\/stars-und-leute\/ikonische-looks-margot-robbies-wuthering-heights-tour-ist-hair-lich-69851de27f5bc5017ea80f73\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Auftritt der beiden<\/a> kommt ohne Flirt aus. Vor jeder Kamera ist die Chemie der beiden geradezu greifbar. Und vor allem <a href=\"https:\/\/www.bild.de\/unterhaltung\/leute\/leute\/margot-robbie-im-steckbrief-ihr-weg-zum-hollywoodstar-80963966.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Margot Robbie<\/a> heizt die Ger\u00fcchte immer weiter an, es k\u00f6nne sich mehr zwischen den beiden abspielen als eine gute Arbeitsbeziehung.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Im aktuellen Liebesdrama \u201eWuthering Heights\u201c kommen sich Margot Robbie und Jacob Elordi ganz nah\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/7a25d87f24f523e673c320704ad6f33a,31e47c46.jpeg\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Im aktuellen Liebesdrama \u201eWuthering Heights\u201c kommen sich Margot Robbie und Jacob Elordi ganz nah<\/p>\n<p>Foto: picture alliance\/ASSOCIATED PRESS<\/p>\n<p>Robbie und Elordi \u00fcbersch\u00fctten sich mit Komplimenten<\/p>\n<p><a href=\"https:\/\/www.bild.de\/leben-wissen\/fitness\/unfreiwillig-fit-jacob-elordi-lehnt-hollywood-koerperkult-ab-69847ba682b7e6e05f51b2fb\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Elordi<\/a>, so Robbie, sei sicher ein \u201esehr guter Boyfriend\u201c, was man schon daran erkennen k\u00f6nne, dass er am Valentinstag ihre Garderobe mit Rosen habe schm\u00fccken lassen. Sie sei \u201eco-abh\u00e4ngig\u201c von ihm geworden, weil er so aufmerksam gewesen sei. Schon in den ersten Drehtagen habe sie sich immer wieder suchend nach Elordi umgesehen. War er nicht in Robbies N\u00e4he, war sie \u201enerv\u00f6s und verunsichert\u201c.<\/p>\n<p>Mehr zum Thema<\/p>\n<p>Erstaunlich dabei ist, dass Margot Robbie seit Jahren in einer stabilen Beziehung lebt und sogar verheiratet ist. Ihr Mann <a href=\"https:\/\/www.bild.de\/unterhaltung\/stars-und-leute\/margot-robbie-und-ehemann-tom-ackerley-der-letzte-urlaub-zu-zweit-66d58e744d94b71a3552f959\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Tom Ackerley (35)<\/a> d\u00fcrfte sich \u00fcber die zus\u00e4tzliche Aufmerksamkeit freuen: Er hat \u201eWuthering Heights\u201c produziert. Und der Film, der rund 80 Mio. Dollar gekostet haben soll, hat bereits \u00fcber 220 Mio. Dollar eingespielt. Da d\u00fcrfte ein bisschen gespielte Liebe zu verkraften sein.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"1116\" alt=\"Seit 2016 ist Margot Robbie mit dem Briten Tom Ackerley (35) verheiratet, die beiden sind im Oktober 2024 Eltern eines Sohnes geworden\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/9e9d7fedb5da69b207e02ad314922810,9bd868fb.jpeg\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Seit 2016 ist Margot Robbie mit dem Briten Tom Ackerley (35) verheiratet, die beiden sind im Oktober 2024 Eltern eines Sohnes geworden<\/p>\n<p>Foto: LISA OConnor\/AFF-USA.com\/MEGA<\/p>\n<p>Auch Pamela Anderson setzt auch Liebes-PR<\/p>\n<p>Was auff\u00e4llig ist: Wie offen Hollywood derzeit mit gezielten und gespielten Liebesger\u00fcchten arbeitet. Das Schmierentheater, das <a href=\"https:\/\/www.bild.de\/themen\/personen\/pamela-anderson\/nachrichten-news-fotos-videos-15803432.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Pamela Anderson (58)<\/a> und <a href=\"https:\/\/www.bild.de\/themen\/personen\/liam-neeson\/filme-news-fotos-videos-23470456.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Liam Neeson (73)<\/a> im Sommer 2025 aufgef\u00fchrt haben, um \u201eDie nackte Kanone\u201c zu bewerben (und auch bei BILD auff\u00fchrten), war schlechter als der Film selbst. <\/p>\n<p>Als die Promotionauftritte beendet waren, endeten auch die gegenseitigen, <a href=\"https:\/\/www.bild.de\/unterhaltung\/stars-und-leute\/jetzt-also-doch-pamela-anderson-bestaetigt-romanze-mit-liam-neeson-6938606c11f914c89b8582f8\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">gezielt platzierten Liebesbekundungen<\/a>. Auch, wenn beide bestreiten, dass ihre Liebe nur gespielt gewesen sei. Wir werden es wohl nie erfahren. Was immer bleibt, ist ein schaler Beigeschmack. Und trotzdem schmeckt jedes Liebesger\u00fccht aus Hollywood immer wieder so unglaublich unwiderstehlich.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"1178\" alt=\"2025: Die inszenierte Vertrautheit zwischen Pamela Anderson (58) und Liam Neeson (73) hielt nur einen Sommer\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/a6da5448f511134f14d7086cef975be5,774c19e5.jpeg\"   class=\"portrait\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">2025: Die inszenierte Vertrautheit zwischen Pamela Anderson (58) und Liam Neeson (73) hielt nur einen Sommer<\/p>\n<p>Foto: picture alliance\/Captital Pictures<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Die Liebe ist bekanntlich ein seltsames Spiel. Und wirkt manchmal auch seltsam gespielt. Seit Wochen&hellip;\n","protected":false},"author":2,"featured_media":20612,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[46,42,175,147,152,7878,44,176,10850,204,210,148],"class_list":{"0":"post-20611","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-at","9":"tag-austria","10":"tag-celebrities","11":"tag-entertainment","12":"tag-kino","13":"tag-kinofilme","14":"tag-oesterreich","15":"tag-prominente","16":"tag-robbie-margot","17":"tag-schauspieler","18":"tag-texttospeech","19":"tag-unterhaltung"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/20611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=20611"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/20611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/20612"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=20611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=20611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=20611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}