{"id":24619,"date":"2026-03-04T07:19:06","date_gmt":"2026-03-04T07:19:06","guid":{"rendered":"https:\/\/www.europesays.com\/at\/24619\/"},"modified":"2026-03-04T07:19:06","modified_gmt":"2026-03-04T07:19:06","slug":"claudia-hoeller-komplettiert-vorstand-der-tiroler-landesbank","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/24619\/","title":{"rendered":"Claudia H\u00f6ller komplettiert Vorstand der Tiroler Landesbank"},"content":{"rendered":"<p>Die Tiroler Landesbank hat ihre Weichen f\u00fcr die Zukunft gestellt: Wie vorgesehen komplettiert Claudia H\u00f6ller mit M\u00e4rz 2026 neben Markus Hildmann und Andreas Stadler den 3er-Vorstand der Hypo Tirol. Die erfahrene Bankerin aus dem Bezirk Kitzb\u00fchel \u00fcbernimmt das Resort Risikomanagement &amp; Finanzen und wird k\u00fcnftig auch als Vorstandssprecherin agieren.<\/p>\n<p>Dazu Tirols Landeshauptmann\u00a0Anton Mattle, Eigent\u00fcmervertreter der Hypo Tirol Bank: \u201eIch w\u00fcnsche dem neuen Team viel Erfolg f\u00fcr die anstehenden Aufgaben. Mit der Komplettierung des Vorstandes habe ich gro\u00dfes Vertrauen, dass die Landesbank ihre Rolle als Erm\u00f6glicher f\u00fcr die eigenen vier W\u00e4nde der Tirolerinnen und Tiroler, als Impulsgeber f\u00fcr den Standort und als Garant f\u00fcr stabile Finanzen nachhaltig festigt.&#8220;<\/p>\n<p>\u201eMit Claudia H\u00f6ller, Andreas Stadler und Markus Hildmann haben wir ein schlagkr\u00e4ftiges Team an der Spitze der Tiroler Landesbank. Mit h\u00f6chster Tirol-Kenntnis und h\u00f6chster Kompetenz des 3er-Vorstandes in den jeweiligen Bereichen sind wir bestens aufgestellt, um als starker, kundenorientierter Finanzpartner am Kernmarkt Tirol zu re\u00fcssieren\u201c, ist\u00a0Wilfried Stauder, Aufsichtsratsvorsitzender der Hypo Tirol Bank, \u00fcberzeugt.<\/p>\n<p>Claudia H\u00f6ller\u00a0unterstreicht den Fokus auf den Kernmarkt Tirol:\u00a0\u201eIch freue mich besonders, in meine Heimat zur\u00fcckzukehren und meine Erfahrung verantwortungsvoll f\u00fcr eine starke und erfolgreiche Tiroler Landesbank einzubringen. Mit konsequentem Handeln gilt es, die langfristige Eigenst\u00e4ndigkeit und wirtschaftliche Stabilit\u00e4t der Hypo Tirol als regional fokussierte Bank im Eigentum des Landes Tirol sicherzustellen.\u201c<\/p>\n<p>\u00dcber Claudia H\u00f6ller (Kurzvita):\u00a0H\u00f6ller ist als erfahrene Bankerin seit 1991 im Bankensektor t\u00e4tig und war bereits Risiko- und Finanzvorstand der Erste Bank der \u00f6sterreichischen Sparkassen AG sowie Risiko- und Finanzvorstand der Tiroler Sparkassen AG. Zuletzt war H\u00f6ller Vorstandsmitglied der BKS-Bank in K\u00e4rnten, wo sie ebenso f\u00fcr Risiko und Finanzen zust\u00e4ndig war.<\/p>\n","protected":false},"excerpt":{"rendered":"Die Tiroler Landesbank hat ihre Weichen f\u00fcr die Zukunft gestellt: Wie vorgesehen komplettiert Claudia H\u00f6ller mit M\u00e4rz 2026&hellip;\n","protected":false},"author":2,"featured_media":24620,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1616,12364,12363,46,42,12365,12366,95,12361,90,89,10416,91,94,12362,44,12367,12360,93,92],"class_list":{"0":"post-24619","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-unternehmen-maerkte","8":"tag-finanzen","9":"tag-3er-vorstand","10":"tag-andreas-stadler","11":"tag-at","12":"tag-austria","13":"tag-bankerin","14":"tag-bezirk-kitzbuehel","15":"tag-business","16":"tag-claudia-hoeller","17":"tag-companies","18":"tag-companies-markets","19":"tag-hypo-tirol","20":"tag-markets","21":"tag-maerkte","22":"tag-markus-hildmann","23":"tag-oesterreich","24":"tag-resort-risikomanagement","25":"tag-tiroler-landesbank","26":"tag-unternehmen","27":"tag-unternehmen-maerkte"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116169694570591715","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/24619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=24619"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/24619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/24620"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=24619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=24619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=24619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}