{"id":33478,"date":"2026-03-08T22:44:09","date_gmt":"2026-03-08T22:44:09","guid":{"rendered":"https:\/\/www.europesays.com\/at\/33478\/"},"modified":"2026-03-08T22:44:09","modified_gmt":"2026-03-08T22:44:09","slug":"scr-altach-zur-pleite-bei-sturm-graz-nach-unglaublicher-woche-video","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/33478\/","title":{"rendered":"SCR Altach zur Pleite bei Sturm Graz nach &#8222;unglaublicher Woche&#8220; [Video]"},"content":{"rendered":"<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/sturm-graz.png\" alt=\"\"\/> <\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/02\/altach_scra.jpg\" alt=\"\"\/> <\/p>\n<p>Nach dem erstmaligen Finaleinzug im \u00d6FB-Cup kam der\u00a0<a href=\"https:\/\/ticker.ligaportal.at\/mannschaft\/5\/scr-altach\" rel=\"nofollow noopener\" target=\"_blank\">SCR Altach<\/a>\u00a0mit massig Selbstvertrauen im Gep\u00e4ck zu\u00a0Titelverteidiger <a href=\"https:\/\/ticker.ligaportal.at\/mannschaft\/1715\/sk-sturm-graz\" rel=\"nofollow noopener\" target=\"_blank\">SK Sturm Graz<\/a>\u00a0angereist, musste dort allerdings beim 0:2 die erste Pflichtspielpleite im Kalenderjahr 2026 hinnehmen. Der Weg f\u00fcr Trainer Ognjen Zaric und Co. f\u00fchrt nun in die <a href=\"https:\/\/www.ligaportal.at\/bundesliga\/\" rel=\"nofollow noopener\" target=\"_blank\">Bundesliga<\/a>-Qualifikationsgruppe. Nachfolgend Stimmen des SCRA!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/hoedl-jacob-peter-sk-sturm-vs-scr-altach-08-03-2026-gepa-admiral.jpg\" alt=\"hoedl jacob peter sk sturm vs scr altach 08 03 2026 gepa admiral\"\/><\/p>\n<p>Die Vorarlberger um\u00a0Mohamed Ouedraogo (l.) gingen beim Meister, hier Torsch\u00fctze JP H\u00f6dl, in die Knie.<\/p>\n<p>&#8222;&#8230;sehr stolz&#8220;<\/p>\n<p>Ognjen Zaric (Trainer SCR Altach):<\/p>\n<p>\u2026\u00fcber die Gr\u00fcnde der Niederlage: \u201eDer Hauptgrund ist, dass wir gegen den amtierenden \u00f6sterreichischen Meister gespielt haben. Wir haben in der ersten Halbzeit zweimal eine Phase gehabt mit Doppelchance, Dreifachchance, die du wahrscheinlich in so einem Spiel machen musst, um in F\u00fchrung zu gehen und das Momentum an deine Seite zu rei\u00dfen. Nichtsdestotrotz habe ich der Mannschaft gerade gesagt, dass ich sehr stolz bin auf sie. Wir sind im Cupfinale und es war nat\u00fcrlich herausfordernd heute.\u201c<\/p>\n<p>&#8222;&#8230;bisschen was gefehlt&#8220;<\/p>\n<p>Patrick Greil (Offensivspieler SCR Altach):<\/p>\n<p>\u2026\u00fcber den Spielverlauf: \u201eIch habe das Gef\u00fchl gehabt, dass wir speziell ab der 20. Minute dann wirklich im Spiel drinnen waren. Ich bin sehr stolz auf die Jungs, dass wir nach dieser Woche so eine Energie auf den Platz gebracht haben. Dementsprechend finde ich auch, dass wir uns da was verdient h\u00e4tten. In der zweiten H\u00e4lfte hat uns ein bisschen was gefehlt. Sturm hat das dann besser gemacht und deshalb verdient gewonnen.\u201c<\/p>\n<p>\u2026\u00fcber das Erreichen des Cupfinals: \u201eEs war eine unglaubliche Woche f\u00fcr uns. Der Mittwoch war gro\u00dfartig f\u00fcr uns.\u201c<\/p>\n<p>Zaric-Stimme im VIDEO<\/p>\n<p><p lang=\"de\" dir=\"ltr\">SCR &#13;<br \/>\nAltach-Trainer Ognjen Zaric zur Niederlage beim SK Sturm Graz! \u26bd\ufe0f\ud83c\udfa4<a href=\"https:\/\/twitter.com\/hashtag\/ligaportal?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#ligaportal<\/a>&#13;<br \/>\n <a href=\"https:\/\/twitter.com\/hashtag\/bundesliga?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#bundesliga<\/a>&#13;<br \/>\n <a href=\"https:\/\/twitter.com\/hashtag\/scraltach?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#scraltach<\/a>&#13;<br \/>\n <a href=\"https:\/\/twitter.com\/hashtag\/sturmgraz?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#sturmgraz<\/a>&#13;<br \/>\n <a href=\"https:\/\/t.co\/JjQkGBqp7R\" rel=\"nofollow\">pic.twitter.com\/JjQkGBqp7R<\/a><\/p>\n<p>\u2014&#13;<br \/>\n ligaportal.at (@ligaportal_at) <a href=\"https:\/\/twitter.com\/ligaportal_at\/status\/2030756399613972783?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">March&#13;<br \/>\n 8, 2026<\/a>&#13;\n<\/p>\n<p>Siehe auch:<\/p>\n<p>Statement-Quelle: Sky Sport Austria und Antonio Perner\/Ligaportal<br \/>Fotocredit: GEPA-ADMIRAL<\/p>\n<p>\t\t\t\t<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Nach dem erstmaligen Finaleinzug im \u00d6FB-Cup kam der\u00a0SCR Altach\u00a0mit massig Selbstvertrauen im Gep\u00e4ck zu\u00a0Titelverteidiger SK Sturm Graz\u00a0angereist, musste&hellip;\n","protected":false},"author":2,"featured_media":33479,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[46,42,15340,183,5719,44,2121,4246],"class_list":{"0":"post-33478","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-graz","8":"tag-at","9":"tag-austria","10":"tag-bundesliga-qualifikationsgruppe","11":"tag-graz","12":"tag-oefb-cup","13":"tag-oesterreich","14":"tag-scr-altach","15":"tag-sturm-graz"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116195980932480167","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/33478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=33478"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/33478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/33479"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=33478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=33478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=33478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}