{"id":69163,"date":"2026-03-27T14:43:07","date_gmt":"2026-03-27T14:43:07","guid":{"rendered":"https:\/\/www.europesays.com\/at\/69163\/"},"modified":"2026-03-27T14:43:07","modified_gmt":"2026-03-27T14:43:07","slug":"von-spanien-bis-luxemburg-wie-europa-sterbehilfe-regelt","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/69163\/","title":{"rendered":"Von Spanien bis Luxemburg: Wie Europa Sterbehilfe regelt"},"content":{"rendered":"<p><a href=\"https:\/\/de.euronews.com\/2026\/03\/27\/spanierin-sterbehilfe-assistierter-suizid\" rel=\"nofollow noopener\" target=\"_blank\">Der Fall Noelia Castillo<\/a>, einer 25-j\u00e4hrigen Spanierin, der nach einem langen Rechtsstreit Euthanasie gew\u00e4hrt wurde, hat die Debatte \u00fcber den Umgang mit dem Lebensende neu entfacht. <\/p>\n<p>          <img decoding=\"async\" class=\"c-ad__placeholder__logo\" src=\"https:\/\/static.euronews.com\/website\/images\/logos\/logo-euronews-stacked-outlined-72x72-grey-9.svg\" width=\"72\" height=\"72\" alt=\"\" loading=\"lazy\"\/><br \/>\n          WERBUNG<\/p>\n<p>          <img decoding=\"async\" class=\"c-ad__placeholder__logo\" src=\"https:\/\/static.euronews.com\/website\/images\/logos\/logo-euronews-stacked-outlined-72x72-grey-9.svg\" width=\"72\" height=\"72\" alt=\"\" loading=\"lazy\"\/><br \/>\n          WERBUNG<\/p>\n<p>Castillo war seit einem Suizidversuch im Jahr 2022 nach einer sexuellen Gewalttat querschnittsgel\u00e4hmt. Am Donnerstag, dem 26. M\u00e4rz, erhielt sie in einem Gesundheitszentrum nahe Barcelona Euthanasie. <\/p>\n<p>Der Fall sorgt in ganz Spanien f\u00fcr heftige Diskussionen. Ihr Vater zog mit Unterst\u00fctzung der konservativen Organisation Abogados Cristianos (Christliche Anw\u00e4lte) vor Gericht und argumentierte, seine Tochter sei nicht in der geistigen Verfassung gewesen, um eine solche Entscheidung zu treffen. <\/p>\n<p>Nach einem zwanzigmonatigen Verfahren mit Entscheidungen des spanischen Obersten Gerichtshofs, des Verfassungsgerichts und des Europ\u00e4ischen Gerichtshofs f\u00fcr Menschenrechte best\u00e4tigten alle Instanzen Castillos Recht auf Euthanasie. <\/p>\n<p>Spanien hat Euthanasie und assistierten Suizid im Jahr 2021 legalisiert. Anspruch haben Patientinnen und Patienten mit einer schweren und unheilbaren Krankheit oder einer schweren, chronischen und stark beeintr\u00e4chtigenden Erkrankung, die von der behandelnden \u00c4rztin oder dem behandelnden Arzt best\u00e4tigt wird. <\/p>\n<p>Sie m\u00fcssen zwei Antr\u00e4ge stellen, freiwillig und ohne \u00e4u\u00dferen Druck. Zwischen den Antr\u00e4gen m\u00fcssen mindestens 15 Kalendertage liegen. <\/p>\n<p>In Europa erlauben Belgien, Luxemburg und die Niederlande \u00c4rztinnen und \u00c4rzten ebenfalls die Durchf\u00fchrung von Euthanasie. <\/p>\n<p>Wie ist Sterbehilfe in Europa geregelt?<\/p>\n<p>Niederlande<\/p>\n<p>Die Niederlande waren im Jahr 2002 das erste Land der Welt, das Euthanasie legalisierte. <\/p>\n<p>Das Gesetz erlaubt Euthanasie, wenn eine Patientin oder ein Patient unertr\u00e4glich leidet und keine Aussicht auf Besserung besteht. Das gilt sowohl f\u00fcr psychische als auch f\u00fcr k\u00f6rperliche Erkrankungen. <\/p>\n<p>Die niederl\u00e4ndische Regelung verpflichtet \u00c4rztinnen und \u00c4rzte, vor einer Euthanasie mehrere Voraussetzungen zu pr\u00fcfen. Der Wunsch der Patientin oder des Patienten muss freiwillig und wohl\u00fcberlegt sein. Das Leiden muss unertr\u00e4glich sein, ohne realistische Chance auf Verbesserung. <\/p>\n<p>\u00c4rztinnen und \u00c4rzte m\u00fcssen au\u00dferdem \u00fcber die Situation und Prognose aufkl\u00e4ren, gemeinsam feststellen, dass es keine vern\u00fcnftige Alternative gibt, und eine zweite Meinung bei einer unabh\u00e4ngigen \u00c4rztin oder einem unabh\u00e4ngigen Arzt einholen.<\/p>\n<p>Belgien<\/p>\n<p>Belgien hat Euthanasie im Jahr 2002 unter bestimmten Bedingungen straffrei gestellt. <\/p>\n<p>Die Initiative muss von der Patientin oder dem Patienten ausgehen, die oder der zum Zeitpunkt der Bitte bei vollem Bewusstsein und zurechnungsf\u00e4hig sein muss. Die betroffene Person muss an einer unheilbaren Erkrankung leiden und andauernde, unertr\u00e4gliche k\u00f6rperliche und\/oder seelische Schmerzen haben, die sich nicht lindern lassen. <\/p>\n<p>Luxemburg<\/p>\n<p>Luxemburg hat 2009 ein Gesetz zu Euthanasie und assistiertem Suizid verabschiedet. Es gibt Patientinnen und Patienten die M\u00f6glichkeit, zu sterben, wenn ihr Leiden als unertr\u00e4glich gilt.<\/p>\n<p>Voraussetzung ist eine unheilbare Erkrankung infolge eines Unfalls oder einer Krankheit. <\/p>\n<p>Der Antrag muss gestellt werden, solange die Patientin oder der Patient bei Bewusstsein ist, vollj\u00e4hrig und entscheidungsf\u00e4hig, und ohne Druck von au\u00dfen handelt. <\/p>\n<p>\u00d6sterreich<\/p>\n<p>\u00d6sterreich erlaubt seit 2022 assistierten Suizid. Das Modell sieht ausschlie\u00dflich eine freiwillige Form vor, bei der die Patientin oder der Patient das t\u00f6dliche Medikament selbst einnimmt. Apotheken geben das Mittel erst nach einem strengen Pr\u00fcfverfahren aus.<\/p>\n<p>Das Angebot richtet sich an vollj\u00e4hrige Personen mit Entscheidungsf\u00e4higkeit, die an einer schweren, unheilbaren und dauerhaften Krankheit leiden, die eine \u201edauerhafte Beeintr\u00e4chtigung der Lebensf\u00fchrung\u201c verursacht.<\/p>\n<p>Diese L\u00e4nder beraten \u00fcber die Legalisierung der Sterbehilfe<\/p>\n<p>In Frankreich hat Pr\u00e4sident Emmanuel Macron nach seiner Wiederwahl 2022 angek\u00fcndigt, ein Gesetz zur Sterbehilfe vorzulegen. <\/p>\n<p>Seit der offiziellen Vorstellung des Entwurfs im Jahr 2024 ist das Vorhaben umstritten. Der Text pendelt seither zwischen Nationalversammlung und Senat hin und her. <a href=\"https:\/\/de.euronews.com\/2026\/02\/12\/sterbehilfe-depressionen-macron-gesetzentwurf\" rel=\"nofollow noopener\" target=\"_blank\">Das Verfahren l\u00e4uft noch<\/a>, als N\u00e4chstes steht eine zweite Lesung im Senat an. <\/p>\n<p>Das portugiesische Parlament verabschiedete bereits 2023 ein Gesetz zu Euthanasie und Sterbehilfe. In Kraft ist es jedoch noch nicht. Der portugiesische Pr\u00e4sident legte zweimal ein Veto ein, zudem befasste sich das Verfassungsgericht mit dem Gesetz.<\/p>\n<p>Auf Malta startete die Regierung im vergangenen Jahr eine \u00f6ffentliche Konsultation zu freiwilliger aktiver Sterbehilfe, um \u00fcber einen m\u00f6glichen Gesetzentwurf zu entscheiden.<\/p>\n<p>In Slowenien sprach sich ein unverbindliches Referendum 2024 f\u00fcr Sterbehilfe aus. Die Nationalversammlung setzte dies 2025 in ein Gesetz um. In einem zweiten, verbindlichen Referendum lehnten Ende vergangenen Jahres jedoch 53 Prozent der W\u00e4hlerinnen und W\u00e4hler das Gesetz ab. Die Umsetzung ist nun f\u00fcr mindestens ein Jahr ausgesetzt. <\/p>\n","protected":false},"excerpt":{"rendered":"Der Fall Noelia Castillo, einer 25-j\u00e4hrigen Spanierin, der nach einem langen Rechtsstreit Euthanasie gew\u00e4hrt wurde, hat die Debatte&hellip;\n","protected":false},"author":2,"featured_media":69164,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[76,75,2386,74,124,935,27374],"class_list":{"0":"post-69163","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europa","8":"tag-eu","9":"tag-europa","10":"tag-europaeische-union","11":"tag-europe","12":"tag-gesundheit","13":"tag-spanien","14":"tag-sterbehilfe"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116301673535240316","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/69163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=69163"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/69163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/69164"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=69163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=69163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=69163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}