{"id":72854,"date":"2026-03-29T19:13:14","date_gmt":"2026-03-29T19:13:14","guid":{"rendered":"https:\/\/www.europesays.com\/at\/72854\/"},"modified":"2026-03-29T19:13:14","modified_gmt":"2026-03-29T19:13:14","slug":"russland-wieder-ukrainischer-angriff-auf-oel-hafen-an-der-ostsee","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/72854\/","title":{"rendered":"Russland \u2013 Wieder ukrainischer Angriff auf \u00d6l-Hafen an der Ostsee"},"content":{"rendered":"<p>Verletzte nach Angriffen in der Ukraine, Sch\u00e4den in Russland<\/p>\n<p>Bei n\u00e4chtlichen russischen Angriffen aus der Luft sind in der Ukraine mehrere Menschen verletzt worden. In der vor dem Krieg zweitgr\u00f6\u00dften Stadt des Landes Charkiw schlug nach Beh\u00f6rdenangaben eine Rakete in einem Wohnblock ein. Acht Menschen seien dabei verletzt worden, teilte der ukrainische Katastrophenschutz bei Telegram mit. Weitere Verletzte in der Stadt gab es demnach bei Drohneneinschl\u00e4gen. In der Industrieregion Dnipropetrowsk wurde zudem eine 17-J\u00e4hrige bei Artillerie- und Drohnenangriffen verletzt.<\/p>\n<p>Nach Angaben der ukrainischen Luftwaffe setzte Russland neben der Rakete auch etwas mehr als 100 Drohnen in der Nacht ein. 93 seien abgeschossen oder mit Funkst\u00f6rungen zur Landung gebracht worden, teilte die Flugabwehr mit.\u00a0Auf der Gegenseite verursachten Drohnen erneut Sch\u00e4den weit im russischen Hinterland. Wie in den N\u00e4chten zuvor waren die russischen Ostseeh\u00e4fen Primorsk und Ust-Luga Ziel der Attacken. Alexander Drosdenko, Gouverneur des Umlands der Millionenstadt St. Petersburg, sprach von 36 abgeschossenen Drohnen. Folgen nannte er nicht. Dem ukrainischen Internetportal Exilenova zufolge sind erneut Br\u00e4nde in den H\u00e4fen ausgebrochen, die f\u00fcr Russlands \u00d6lexport wichtig sind.<\/p>\n<p>Zudem traf es eine Phosphatfabrik und ein Stahlwerk in der Gro\u00dfstadt Tscherepowez im nordrussischen Gebiet Wologda. Acht Einschl\u00e4ge habe es in der Region gegeben, schrieb Gouverneur Georgi Filimonow. Das Phosphatwerk Apatit ist f\u00fcr die russische D\u00fcngemittel- sowie Sprengstoffproduktion wichtig. Das Stahlwerk, das zum Konzern Severstal geh\u00f6rt, ist nach Angaben der Leitung weiter in Betrieb. Ernsthafte Besch\u00e4digungen gebe es nicht, hie\u00df es.<\/p>\n","protected":false},"excerpt":{"rendered":"Verletzte nach Angriffen in der Ukraine, Sch\u00e4den in Russland Bei n\u00e4chtlichen russischen Angriffen aus der Luft sind in&hellip;\n","protected":false},"author":2,"featured_media":72855,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[76,75,74,3076],"class_list":{"0":"post-72854","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europa","8":"tag-eu","9":"tag-europa","10":"tag-europe","11":"tag-msc"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116314059777027917","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/72854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=72854"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/72854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/72855"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=72854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=72854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=72854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}