{"id":74296,"date":"2026-03-30T14:17:10","date_gmt":"2026-03-30T14:17:10","guid":{"rendered":"https:\/\/www.europesays.com\/at\/74296\/"},"modified":"2026-03-30T14:17:10","modified_gmt":"2026-03-30T14:17:10","slug":"von-der-ausbildung-in-die-praxis-101-neue-pflegekraefte-fuer-steirische-einrichtungen-land-steiermark","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/74296\/","title":{"rendered":"Von der Ausbildung in die Praxis: 101 neue Pflegekr\u00e4fte f\u00fcr steirische Einrichtungen &#8211; Land Steiermark"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/_Z8G0920.jpg\" alt=\"Gruppenbild von der der Abschlussfeier\" class=\"img-txtblock rs_skip\"\/><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/03\/_Z8G1294.jpg\" alt=\"Bild von der Abschlussfeier in Graz\" class=\"img-txtblock rs_skip\"\/><\/p>\n<p>Graz (30. M\u00e4rz 2026).-\u00a0Das steirische Gesundheitssystem gewinnt neue Fachkr\u00e4fte. Bei der heutigen Abschlussfeier f\u00fcr Pflegeassistenz und Pflegefachassistenz der Schule f\u00fcr Gesundheits- und Krankenpflege am Bildungszentrum Ost in Graz wurden 101 Absolventinnen und Absolventen ausgezeichnet, die ihre Ausbildung in Vollzeit, berufsbegleitend oder in Kooperationen mit der HLW Weiz erfolgreich abgeschlossen haben.<\/p>\n<p>Die Durchl\u00e4ssigkeit der Pflegeausbildungen macht es m\u00f6glich, dass jungen Menschen bereits mit 15 Jahren in die Pflegeausbildung einsteigen k\u00f6nnen. Mit 18 Jahren haben sie neben der Pflichtschule auch den Abschluss der Pflegeassistenz erreicht und k\u00f6nnen sich in Vollzeit oder berufsbegleitend weiterbilden zur Pflegefachassistenz bzw. in das Bachelorstudium Gesundheits- und Krankenpflege einsteigen. Das sind gro\u00dfartige Karrierem\u00f6glichkeiten.<\/p>\n<p>Gesundheitslandesrat Karlheinz Kornh\u00e4usl w\u00fcrdigte in seiner Ansprache den Einsatz, die Leidenschaft und das Engagement der Absolventinnen und Absolventen: \u201eIhre Ausbildung war herausfordernd, doch Sie haben sie mit Mut, Fachwissen und mitf\u00fchlender Menschlichkeit gemeistert. Daf\u00fcr geb\u00fchrt Ihnen gro\u00dfer Respekt. Sie haben nicht nur medizinisches Wissen erworben, sondern auch die Kunst des Zuh\u00f6rens, des Vertrauensaufbaus und der Teamarbeit. Ihr Abschluss ist der Beginn einer beruflichen Laufbahn, in der Sie jeden Tag die Welt ein bisschen besser machen.\u201d<\/p>\n<p>Die frisch ausgebildeten Fachkr\u00e4fte \u00fcbernehmen k\u00fcnftig verantwortungsvolle Aufgaben in den steirischen Gesundheitseinrichtungen, von Unterst\u00fctzung bei Pflege, Mobilisation, Mahlzeiten, Dokumentation, Wundversorgung und Medikamentengabe bis hin zur \u00dcberwachung von Vitalwerten sowie der Durchf\u00fchrung von Untersuchungen.<\/p>\n<p>F\u00fcr alle, die sich f\u00fcr eine Ausbildung in der Pflege interessieren, stehen die Beratungsstellen f\u00fcr Gesundheitsausbildungen des Landes Steiermark am Karmeliterplatz 2, 8010 Graz, mit Informationen und Beratung zur Verf\u00fcgung. Weitere Details online unter <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/at\/wp-content\/uploads\/2026\/02\/pfeil-ext.gif\" alt=\"\"\/>\u00a0<a title=\"\u00d6ffnet ein neues Fenster: www.gesundheitsausbildungen.steiermark.at\" href=\"http:\/\/www.gesundheitsausbildungen.steiermark.at\/\" target=\"_blank\" rel=\"nofollow noopener\">www.gesundheitsausbildungen.steiermark.at<\/a>.<\/p>\n<p>Graz, am 30. M\u00e4rz 2026<\/p>\n","protected":false},"excerpt":{"rendered":"Graz (30. M\u00e4rz 2026).-\u00a0Das steirische Gesundheitssystem gewinnt neue Fachkr\u00e4fte. Bei der heutigen Abschlussfeier f\u00fcr Pflegeassistenz und Pflegefachassistenz der&hellip;\n","protected":false},"author":2,"featured_media":74297,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[28935,46,9214,42,183,9217,6204,9218,3742,9216,1140,9215,9206,28934,9211,5455,9209,9208,44,9212,269,58,9207,9213,9210,6353,116,9219],"class_list":{"0":"post-74296","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-graz","8":"tag-abschlussfeier","9":"tag-at","10":"tag-aussendung","11":"tag-austria","12":"tag-graz","13":"tag-kls","14":"tag-kommunikation","15":"tag-kommunikation-land-steiermark","16":"tag-land-steiermark","17":"tag-landeskommunikation","18":"tag-landespolitik","19":"tag-landespresse","20":"tag-landespressedienst","21":"tag-lr-kornhaeusl-pflege-ausbildung","22":"tag-mitteilung","23":"tag-newsletter","24":"tag-oea","25":"tag-oeffentlichkeitsarbeit","26":"tag-oesterreich","27":"tag-pa","28":"tag-politik","29":"tag-presse","30":"tag-pressearbeit","31":"tag-presseaussendung","32":"tag-pressedienst","33":"tag-pressemitteilung","34":"tag-steiermark","35":"tag-stmk"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/74296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=74296"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/74296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/74297"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=74296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=74296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=74296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}