{"id":85524,"date":"2026-04-05T15:31:10","date_gmt":"2026-04-05T15:31:10","guid":{"rendered":"https:\/\/www.europesays.com\/at\/85524\/"},"modified":"2026-04-05T15:31:10","modified_gmt":"2026-04-05T15:31:10","slug":"wahnsinn-in-linz-lask-feiert-kantersieg-ueber-die-wiener-austria","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/at\/85524\/","title":{"rendered":"Wahnsinn in Linz! LASK feiert Kantersieg \u00fcber die Wiener Austria"},"content":{"rendered":"<p>Der <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/fussball\/lask\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">LASK<\/a> feiert in der 25. Runde der ADMIRAL Bundesliga in der Meistergruppe einen 4:1-Kantersieg gegen die Wiener Austria.<\/p>\n<p>F\u00fcr die Linzer gibt es einen Traumstart zu bejubeln. Keba Cisse k\u00f6pft die Heimischen nach einer Usor-Flanke bei einem kurz ausgef\u00fchrten Eckball zur 1:0-F\u00fchrung (4.).<\/p>\n<p>Daraufhin folgen \u00e4u\u00dferst bittere Minuten f\u00fcr die Wiener. <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/tin-plavotic\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">Tin Plavotic<\/a> bekommt nach einem VAR-Check wegen Handspiels vor dem Strafraum eine glatte Rote Karte und die Linzer erhalten die Chance auf einen weiteren Treffer mit einem Freisto\u00df (11.).<\/p>\n<p>LASK nutzt die Feld\u00fcberlegenheit postwendend mit zwei Toren aus<\/p>\n<p>Genau diesen Freisto\u00df setzt <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/fussball\/kasper-joergensen\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">Kasper J\u00f6rgensen<\/a> zum 2:0 ins Netz (12.). Lediglich eine Minute danach schiebt <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/moses-usor\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">Moses Usor<\/a> sogar zur 3:0-F\u00fchrung ein.<\/p>\n<p>F\u00fcr die Wiener ist es ein Negativrekord. Erstmals kassiert die Austria nach 13 Minuten in einem Bundesliga-Spiel sagenhafte drei Gegentreffer. Doch es folgt, trotz der Unterzahl, eine rasche Reaktion. Taeseok Lee verk\u00fcrzt aus 18 Metern zum 1:3 (16.).<\/p>\n<p>Linzer bauen die F\u00fchrung noch vor der Pause wieder aus<\/p>\n<p>Noch vor dem Seitenwechsel sorgt der <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/fussball\/lask\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">LASK<\/a> aber wieder f\u00fcr einen Drei-Tore-Vorsprung. <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/fussball\/sasa-kalajdzic\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">Sasa Kalajdzic<\/a> nutzt eine Andrade-Flanke per Kopf zum 4:1 aus (32.).<\/p>\n<p>Auch nach dem Seitenwechsel kontrollieren die Gastgeber das Spielgeschehen. Kalajdzic scheitert zun\u00e4chst per Kopf an der Oberkante der Querlatte (52.), ehe <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/aleksandar-dragovic\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">Aleksandar Dragovic<\/a> auf der Linie einen Kalajdzic-Schuss an die Latte lenkt (57.).<\/p>\n<p>Daraufhin schonen die Linzer mit kontrollierten Angriffen ihre Kr\u00e4fte. Auf der Gegenseite verhindern die Wiener immerhin ein Debakel.<\/p>\n<p>Daher jubelt der <a href=\"https:\/\/www.laola1.at\/de\/daten\/news\/fussball\/lask\/\" class=\"tag\" rel=\"nofollow noopener\" target=\"_blank\">LASK<\/a> im dritten Spiel \u00fcber den ersten Sieg in der Meisterrunde. F\u00fcr die Austria ist es nach dem Erfolg in Hartberg die zweite Pleite nach der Punkteteilung.<\/p>\n","protected":false},"excerpt":{"rendered":"Der LASK feiert in der 25. Runde der ADMIRAL Bundesliga in der Meistergruppe einen 4:1-Kantersieg gegen die Wiener&hellip;\n","protected":false},"author":2,"featured_media":85525,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[1069,46,42,1509,964,15325,2356,184,32539,44,3590,32538],"class_list":{"0":"post-85524","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-linz","8":"tag-admiral-bundesliga","9":"tag-at","10":"tag-austria","11":"tag-fk-austria-wien","12":"tag-fussball","13":"tag-kasper-joergensen","14":"tag-lask","15":"tag-linz","16":"tag-moses-usor","17":"tag-oesterreich","18":"tag-sasa-kalajdzic","19":"tag-tin-plavotic"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@at\/116352823085905877","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/85524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/comments?post=85524"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/posts\/85524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media\/85525"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/media?parent=85524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/categories?post=85524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/at\/wp-json\/wp\/v2\/tags?post=85524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}