{"id":5259,"count":2,"description":"","link":"https:\/\/www.europesays.com\/australia\/tag\/bluetooth\/","name":"bluetooth","slug":"bluetooth","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/australia\/wp-json\/wp\/v2\/tags\/5259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/australia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/australia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/australia\/wp-json\/wp\/v2\/posts?tags=5259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}