{"id":100856,"date":"2026-05-08T21:16:13","date_gmt":"2026-05-08T21:16:13","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/100856\/"},"modified":"2026-05-08T21:16:13","modified_gmt":"2026-05-08T21:16:13","slug":"6h-de-spa-hadrien-david-et-akkodis-asp-en-pole-en-lmgt3","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/100856\/","title":{"rendered":"6H de Spa &#8211; Hadrien David et Akkodis-ASP en pole en LMGT3"},"content":{"rendered":"<p>Hadrien David a sign\u00e9 le meilleur temps de l&rsquo;Hyperpole des qualifications des 6 Heures de Spa en LMGT3, au volant de la Lexus RC F LMGT3 n\u00b078 &#8211; Akkodis-ASP, ce vendredi en Belgique.<\/p>\n<p>Le Fran\u00e7ais a domin\u00e9 la session d\u00e9cisive en 2&rsquo;16&Prime;612, 0&Prime;194 devant Zach Robichon (Aston Martin Vantage LMGT3 n\u00b027 &#8211; The Heart of Racing) et 0&Prime;212 devant Ben Tuck (Ford Mustang LMGT3 EVO n\u00b077 &#8211; Proton Competition). Quatri\u00e8me place pour la seconde Lexus n\u00b087 de Clemens Schmid, Giammarco Levorato compl\u00e9tant le top 5 avec la Ford n\u00b088 &#8211; Proton Competition.<\/p>\n<p>Suivent Simon Mann (Ferrari 296 LMGT3 EVO n\u00b021 &#8211; Vista AF Corse), Sean Gelael (BMW M4 LMGT3 EVO n\u00b032 &#8211; Team WRT), Rui Andrade (Mercedes-AMG LMGT3 EVO n\u00b061 &#8211; Iron Lynx), Timur Boguslavskiy (Porsche 911 LMGT3 R EVO n\u00b091 &#8211; Manthey DK Engineering) et Salih Yoluc (Corvette Z06 LMGT3.R n\u00b034 &#8211; Racing Team Turkey by TF).<\/p>\n<p>La premi\u00e8re partie des qualifications a \u00e9t\u00e9 domin\u00e9e par Petru Razvan Umbrarescu (Lexus RC G LMGT3 n\u00b087 &#8211; Akkodis-ASP), meilleur temps en 2&rsquo;17&Prime;225, plus de quatre dixi\u00e8mes devant la concurrence emmen\u00e9e \u00e0 cet instant par Stefano Gattuso (Ford Mustang LMGT3 EVO n\u00b088 &#8211; Proton Competition). Lexus est la seule marque \u00e0 placer ses deux voitures en Hyperpole.<\/p>\n<p>Les surprises de cette session demeurent l&rsquo;\u00e9limination des deux McLaren 720S LMGT3 EVO &#8211; Garage 59, <a href=\"https:\/\/www.endurance-info.com\/auto\/article\/120113-6h-de-spa-el3-cadillac-team-jota-se-signale-avant-les-qualifications\" rel=\"nofollow noopener\" target=\"_blank\">dominatrices ce matin en EL3<\/a>. Absence aussi en Hyperpole de la BMW M4 LMGT3 EVO n\u00b069 &#8211; Team WRT d&rsquo;Anthony McIntosh, vainqueur \u00e0 Imola le mois dernier dans la cat\u00e9gorie. Elimination \u00e9galement de la Porsche 911 LMGT3 R EVO n\u00b092 &#8211; The Bend Manthey, d\u00e9j\u00e0 en difficult\u00e9 avec un arr\u00eat en bord de piste en EL3 ce matin.<\/p>\n<p class=\"highlight\">Les chronos sont <a href=\"https:\/\/www.endurance-info.com\/sites\/default\/files\/2026-05\/Qualifs.pdf\" rel=\"nofollow noopener\" target=\"_blank\">ICI<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Hadrien David a sign\u00e9 le meilleur temps de l&rsquo;Hyperpole des qualifications des 6 Heures de Spa en LMGT3,&hellip;\n","protected":false},"author":2,"featured_media":100857,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[1057,1063,10,1047,1046,12,13,18,17,1056,1064,1058,1042,1044,1060,1045,1065,1050,1054,1049,1070,1053,1061,1055,1066,1043,1067,1052,1068,11,1059,1062,1048,1069,1051],"class_list":{"0":"post-100856","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"tag-24h-nurburgring-vln","9":"tag-24h-series","10":"tag-actualites","11":"tag-adac-gt-masters","12":"tag-asian-le-mans-series","13":"tag-be","14":"tag-be-fr","15":"tag-belgique","16":"tag-belgium","17":"tag-british-gt","18":"tag-club-des-pilotes-des-24h-du-mans","19":"tag-dtm","20":"tag-endurance-info","21":"tag-european-le-mans-series","22":"tag-ffsa-gt","23":"tag-fia-wec","24":"tag-green-racing","25":"tag-gt-open","26":"tag-gt-sports-club","27":"tag-gt-world-challenge-america","28":"tag-gt-world-challenge-asia","29":"tag-gt-world-challenge-europe","30":"tag-gulf12","31":"tag-imsa","32":"tag-intercontinental-gt-challenge","33":"tag-le-mans","34":"tag-le-mans-classic","35":"tag-ligier-european-series","36":"tag-michelin-le-mans-cup","37":"tag-news","38":"tag-porsche-carrera-cup-france","39":"tag-sport-paddle","40":"tag-super-gt","41":"tag-supercar","42":"tag-ultimate-cup-series"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/100856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=100856"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/100856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/100857"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=100856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=100856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=100856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}