{"id":101101,"date":"2026-05-09T04:40:21","date_gmt":"2026-05-09T04:40:21","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/101101\/"},"modified":"2026-05-09T04:40:21","modified_gmt":"2026-05-09T04:40:21","slug":"critique-du-film-cest-quoi-lamour-laure-calamy-et-vincent-macaigne-essaient-peniblement-dannuler-leur-mariage-religieux","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/101101\/","title":{"rendered":"Critique du film \u00ab\u00a0C\u2019est quoi l\u2019amour\u00a0?\u00a0\u00bb : Laure Calamy et Vincent Macaigne essaient p\u00e9niblement d\u2019annuler leur mariage religieux"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Prototype de la com\u00e9die sympa \u00e0 la fran\u00e7aise r\u00e9alis\u00e9e par Fabien Gorgeart (auteur du tr\u00e8s beau La Vraie Famille en 2021, d\u00e9j\u00e0 avec M\u00e9lanie Thierry et Lyes Salem), C\u2019est quoi l\u2019amour ? d\u00e9marre sur un concept original, puis tourne rapidement en rond, faute d\u2019id\u00e9es pour les rebondissements.<\/p>\n<p><a href=\"https:\/\/www.moustique.be\/cinema\/2026\/05\/07\/le-sexe-comme-la-vie-cest-une-aventure-francois-cluzet-a-la-conquete-du-plaisir-feminin-dans-une-comedie-qui-fait-du-bien-PWJBLMYZHRDPRPCL6NH7L62TSQ\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">\u201cLe sexe comme la vie, c&rsquo;est une aventure\u00a0\u00bb: Fran\u00e7ois Cluzet \u00e0 la conqu\u00eate du plaisir f\u00e9minin dans une com\u00e9die qui fait du bien<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00c0 charge pour Laure Calamy, en bonne vivante au caract\u00e8re bien tremp\u00e9 un peu d\u00e9pass\u00e9e par la situation, et Vincent Macaigne (\u00e9galement \u00e0 l\u2019affiche de La Poup\u00e9e), dans son registre traditionnel du tendre au c\u0153ur d\u2019or pas trop courageux, de rendre l\u2019ensemble plaisant, via des gaffes et malentendus dont sont victimes leurs partenaires ou leurs familles.<\/p>\n<p>Romantisme de cin\u00e9ma<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Si on ne s\u2019ennuie pas, il faut bien avouer que les rires ne sont pas plus souvent au rendez-vous que les effets de surprise. Tout est cousu de fil blanc, jusque dans le voyage en groupe \u00e0 Rome ou les d\u00e9veloppements totalement clich\u00e9s auxquels on n\u2019\u00e9chappe malheureusement pas. Quant \u00e0 la r\u00e9flexion sur l\u2019amour et la vie de couple, elle ne vole pas bien haut non plus, restant le plus souvent englu\u00e9e dans le romantisme version cin\u00e9matographique.<\/p>\n<p><a href=\"https:\/\/www.moustique.be\/cinema\/2026\/05\/07\/the-criminals-est-disponible-au-cinema-decouvrez-ce-film-haletant-de-david-mackenzie-qui-lie-lhistoire-dune-bombe-et-un-braquage-AHIWDL55PNDNJLDA5GSH3FNFCE\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">\u00ab\u00a0The Criminals\u00a0\u00bb est disponible au cin\u00e9ma: d\u00e9couvrez ce film haletant de David Mackenzie qui lie l&rsquo;histoire d&rsquo;une bombe et un braquage<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Tout cela reste donc mignon, gentiment souriant et devrait plut\u00f4t trouver son public un vendredi soir \u00e0 la t\u00e9l\u00e9vision qu\u2019au cin\u00e9ma.<\/p>\n","protected":false},"excerpt":{"rendered":"Prototype de la com\u00e9die sympa \u00e0 la fran\u00e7aise r\u00e9alis\u00e9e par Fabien Gorgeart (auteur du tr\u00e8s beau La Vraie&hellip;\n","protected":false},"author":2,"featured_media":98193,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[1168,12,13,18,17,133,2186,96,5521,95,106,151,15910,472,105,5118,13059],"class_list":{"0":"post-101101","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-films","8":"tag-amour","9":"tag-be","10":"tag-be-fr","11":"tag-belgique","12":"tag-belgium","13":"tag-cinema","14":"tag-comedie","15":"tag-divertissement","16":"tag-eglise","17":"tag-entertainment","18":"tag-films","19":"tag-france","20":"tag-laure-calamy","21":"tag-mariage","22":"tag-movies","23":"tag-religion","24":"tag-romantique"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116542781880481897","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/101101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=101101"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/101101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/98193"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=101101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=101101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=101101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}