{"id":102280,"date":"2026-05-10T09:47:09","date_gmt":"2026-05-10T09:47:09","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/102280\/"},"modified":"2026-05-10T09:47:09","modified_gmt":"2026-05-10T09:47:09","slug":"gaelle-garcia-diaz-a-enfin-eu-le-mariage-de-ses-reves-photos","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/102280\/","title":{"rendered":"Ga\u00eblle Garcia Diaz a (enfin) eu le mariage de ses r\u00eaves\u00a0! (photos)"},"content":{"rendered":"<p>Tr\u00e8s amoureuse de son mari, Ga\u00eblle Garcia Diaz\u2026 lui a \u00ab\u00a0re\u00a0\u00bb dit oui, ce samedi 9 mai 2026\u00a0! Re, parce qu\u2019elle \u00e9tait d\u00e9j\u00e0 mari\u00e9e avec lui, depuis cinq ans. \u00ab\u00a0On a eu un mariage Covid avec mon cher et tendre Daan, ce qui veut dire qu\u2019on n\u2019a pas eu droit malheureusement \u00e0 une c\u00e9r\u00e9monie, on n\u2019a pas pu faire de f\u00eate, on n\u2019a pas pu danser\u2026 un peu dommage\u00a0\u00bb, expliquait-elle dans une vid\u00e9o \u00ab\u00a0haul\u00a0\u00bb de sa future robe de mari\u00e9e. \u00ab\u00a0On a fait \u00e0 la maison communale, \u00e0 la mairie comme on dit en France, et c\u2019est vrai qu\u2019on a eu un petit go\u00fbt, on ne va pas se mentir, de trop peu \u00e0 l\u2019\u00e9poque, malgr\u00e9 le fait qu\u2019on ait quand m\u00eame eu un tr\u00e8s beau mariage, qu\u2019on \u00e9tait content, mais surtout on \u00e9tait tr\u00e8s peu. On \u00e9tait 40, c\u2019\u00e9tait pas le plus fun. Pour nos cinq ans, on s\u2019\u00e9tait dit alors avec Daan\u00a0: est-ce qu\u2019on ne ferait pas la f\u00eate de mariage qu\u2019on n\u2019a jamais eue\u00a0?\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Cinq ans de mariage, \u00e7a se f\u00eate\u00a0!\u00a0\u00bb, poursuit la Youtubeuse, entre temps devenue maman de deux petits gar\u00e7ons (Jake Dean et Joe-Lewis) avec Daan. \u00ab\u00a0Mais surtout, de pouvoir terminer finalement ce mariage qu\u2019on n\u2019a pas pu faire \u00e0 100\u00a0% comme on imaginait \u00e0 l\u2019\u00e9poque\u2026 On a l\u2019occasion aujourd\u2019hui de le faire, la chance aussi financi\u00e8rement de pouvoir s\u2019offrir ce petit remariage. Donc on s\u2019est dit let\u2019s go, on ne vit qu\u2019une fois\u00a0! Et de pouvoir \u00e9changer nos v\u0153ux, enfin\u00a0! Cinq ans apr\u00e8s s\u2019\u00eatre mari\u00e9s, c\u2019est quand m\u00eame un peu cocasse, je pense qu\u2019on va rire.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"Tr\u00e8s amoureuse de son mari, Ga\u00eblle Garcia Diaz\u2026 lui a \u00ab\u00a0re\u00a0\u00bb dit oui, ce samedi 9 mai 2026\u00a0!&hellip;\n","protected":false},"author":2,"featured_media":102281,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[12,13,18,17,129,128,96,9596,95,38097,3193,472,109,1225,12629],"class_list":{"0":"post-102280","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-celebrities","13":"tag-celebrity","14":"tag-divertissement","15":"tag-enfin","16":"tag-entertainment","17":"tag-gaelle","18":"tag-garcia","19":"tag-mariage","20":"tag-people","21":"tag-photos","22":"tag-reves"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116549651408558820","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/102280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=102280"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/102280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/102281"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=102280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=102280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=102280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}