{"id":102310,"date":"2026-05-10T10:13:24","date_gmt":"2026-05-10T10:13:24","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/102310\/"},"modified":"2026-05-10T10:13:24","modified_gmt":"2026-05-10T10:13:24","slug":"charles-leclerc-et-son-epouse-alexandra-saint-mleux-inaugurent-leur-yacht-baptise-le-sedici","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/102310\/","title":{"rendered":"Charles Leclerc et son \u00e9pouse, Alexandra Saint\u00a0Mleux, inaugurent leur yacht, baptis\u00e9 le Sedici"},"content":{"rendered":"<p>\n    Ce vendredi 8 mai, l\u2019entreprise Riva a d\u00e9voil\u00e9 une vid\u00e9o des \u00e9poux en train d\u2019inaugurer leur nouveau yacht. Charles Leclerc et Alexandra Saint\u00a0Mleux auraient d\u00e9pens\u00e9 entre 11 et 13 millions d\u2019euros pour acqu\u00e9rir l\u2019embarcation.<\/p>\n<p class=\"fig-paragraph\">La bouteille de champagne se brise contre la coque du bateau et c\u2019est officiel\u00a0: Charles Leclerc et\u00a0<a href=\"http:\/\/madame.lefigaro.fr\/style\/news\/dentelles-et-sac-bijou-le-marathon-mode-d-alexandra-saint-mleux-aux-derniers-grands-prix-de-formule-1-20251027\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\">Alexandra Saint\u00a0Mleux<\/a>\u00a0sont les heureux propri\u00e9taires du Sedici. Ce vendredi 8 mai, l\u2019entreprise Riva Yacht, c\u00e9l\u00e8bre constructeur italien de bateau de luxe, a d\u00e9voil\u00e9 une vid\u00e9o dans laquelle elle a compil\u00e9 des images de l\u2019inauguration du nouveau yacht du pilote de Formule 1 et de sa femme. Sur les extraits, les \u00e9poux ont d\u00e9couvert l\u2019immense bateau, toujours hors de l\u2019eau. Apr\u00e8s une c\u00e9r\u00e9monie officielle, pendant laquelle Charles Leclerc a notamment prononc\u00e9 un discours, Alexandra Saint\u00a0Mleux a, comme le veut la tradition, lanc\u00e9 une bouteille de champagne contre la coque de l\u2019embarcation, pour la baptiser. Des confettis ont alors vol\u00e9 dans les airs sous les applaudissements du public.<\/p>\n<p class=\"fig-paragraph\">Le yacht a ensuite \u00e9t\u00e9 mis \u00e0 l\u2019eau sous les yeux des nouveaux propri\u00e9taires. Ces derniers ont d\u2019ailleurs d\u00e9cid\u00e9 de lui donner le nom de Sedici, en r\u00e9f\u00e9rence au num\u00e9ro 16 du pilote mon\u00e9gasque. Le prix du bateau serait quant \u00e0 lui estim\u00e9 entre 11 et 13 millions d\u2019euros. Avec son confort haut de gamme, le Sedici mesure environ 20 m\u00e8tres de long et l\u2019int\u00e9rieur a \u00e9t\u00e9 pens\u00e9 par Minotti, c\u00e9l\u00e8bre maison italienne de mobilier qui \u00e9quipe notamment les yachts de luxe. Pour inaugurer ce nouveau bijou maritime, le couple \u00e9tait bien s\u00fbr accompagn\u00e9 de\u00a0<a href=\"http:\/\/madame.lefigaro.fr\/mariage\/petales-de-rose-bougies-et-collier-papa-veut-t-epouser-la-demande-en-mariage-ultra-romantique-de-charles-leclerc-a-alexandra-saint-mleux-20251103\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\">son fid\u00e8le compagnon, L\u00e9o<\/a>.<\/p>\n<p class=\"fig-body-link&#10;    \">\n            \u00c0 lire aussi<br \/>\n        <a class=\"fig-body-link__link\" href=\"http:\/\/madame.lefigaro.fr\/evasion\/en-photos-visite-de-la-vigie-la-tres-secrete-et-luxueuse-villa-ou-s-est-tenu-le-mariage-de-charles-leclerc-et-alexandra-saint-mleux-20260304\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n        En photos\u00a0: visite de La Vigie, la tr\u00e8s secr\u00e8te et luxueuse villa o\u00f9 s\u2019est tenu le mariage de Charles Leclerc et Alexandra Saint Mleux<\/a>\n<\/p>\n<p>                                                <a class=\"fig-a11y-skip\" href=\"#fig-a11y-skip-main-inarticle\" is=\"fig-a11y-skip\" data-trigger-mode=\"visible-once\"><br \/>\n    Passer la publicit\u00e9<br \/>\n<\/a>            <\/p>\n<p>                                                \u00abC\u2019est aussi ce que je suis en \u00e9tant sa femme\u00bb<\/p>\n<p class=\"fig-paragraph\">Cette vid\u00e9o intervient peu de temps apr\u00e8s la prise de parole virale d\u2019Alexandra Saint\u00a0Mleux. En effet, depuis qu\u2019elle est en couple,\u00a0<a href=\"http:\/\/madame.lefigaro.fr\/celebrites\/actu-people\/sourires-nerveux-et-tour-en-decapotable-le-long-de-la-cote-les-images-du-mariage-civil-de-charles-leclerc-et-alexandra-saint-mleux-20260303\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\">et mari\u00e9e depuis f\u00e9vrier dernier<\/a>, avec le c\u00e9l\u00e8bre pilote de F1, la jeune femme de 23 ans a commenc\u00e9 \u00e0 voir sa popularit\u00e9 grimper en fl\u00e8che. Mais \u00e0 cause de cette nouvelle c\u00e9l\u00e9brit\u00e9, elle re\u00e7oit r\u00e9guli\u00e8rement des critiques au sujet de son statut de \u00abfemme de\u00bb. Lors du\u00a0<a href=\"http:\/\/madame.lefigaro.fr\/celebrites\/actu-people\/l-apparition-de-charles-leclerc-et-de-son-epouse-alexandra-saint-mleux-plus-amoureux-que-jamais-au-grand-prix-de-miami-20260503\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\">Grand Prix de F1 de Miami<\/a>, d\u00e9but mai, les internautes s\u2019en \u00e9taient pris \u00e0 elle en affirmant qu\u2019elle n\u2019\u00e9tait \u00abrien\u00bb sans son \u00e9poux. Face \u00e0 ces commentaires,\u00a0<a href=\"http:\/\/madame.lefigaro.fr\/celebrites\/actu-people\/sans-mon-mari-je-suis-une-femme-comme-les-autres-alexandra-st-mleux-tout-juste-mariee-au-pilote-charles-leclerc-repond-a-ses-detracteurs-20260507\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"MADAME\" rel=\"nofollow noopener\" target=\"_blank\">Alexandra Saint\u00a0Mleux a d\u00e9cid\u00e9 de prendre la parole<\/a>, assumant enti\u00e8rement la position qu\u2019elle a aujourd\u2019hui.<\/p>\n<p class=\"fig-paragraph\">\u00abSans mon mari, je suis une fille normale, avec des hobbies normaux, des centres d\u2019int\u00e9r\u00eat normaux et des passions normales, qui essaie juste d\u2019\u00eatre une bonne personne\u00bb, a-t-elle d\u00e9clar\u00e9 selon le m\u00e9dia\u00a0<a href=\"https:\/\/www.instagram.com\/p\/DX93QDXiGwg\/?utm_source=ig_embed\" target=\"_blank\" rel=\"nofollow noopener\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\">Vantix Magazine<\/a> . \u00abC\u2019est aussi ce que je suis en \u00e9tant sa femme, et il n\u2019y a rien de mal \u00e0 \u00e7a. Nous ne sommes pas tous destin\u00e9s \u00e0 devenir chanteur, docteur, acteur ou athl\u00e8te, et \u00e7a ne retire en rien la valeur d\u2019une personne. Qui on est en tant que personne, comment on traite les autres et ce qu\u2019on choisit de faire de son temps libre, d\u00e9finit en revanche cette valeur. \u00c0 m\u00e9diter\u00a0!\u00bb Un message fort qui, on l\u2019esp\u00e8re, calmera les critiques.<\/p>\n<p>    <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Ce vendredi 8 mai, l\u2019entreprise Riva a d\u00e9voil\u00e9 une vid\u00e9o des \u00e9poux en train d\u2019inaugurer leur nouveau yacht.&hellip;\n","protected":false},"author":2,"featured_media":102311,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[12,13,18,17,129,128,1083,96,95,472,109],"class_list":{"0":"post-102310","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-celebrities","13":"tag-celebrity","14":"tag-couple","15":"tag-divertissement","16":"tag-entertainment","17":"tag-mariage","18":"tag-people"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116549753702584295","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/102310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=102310"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/102310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/102311"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=102310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=102310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=102310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}