{"id":103701,"date":"2026-05-11T16:35:16","date_gmt":"2026-05-11T16:35:16","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/103701\/"},"modified":"2026-05-11T16:35:16","modified_gmt":"2026-05-11T16:35:16","slug":"cetait-il-ny-a-pas-longtemps-diego-est-la-lio-submergee-par-lemotion-en-evoquant-son-fils-qui-sest-suicide-il-y-a-un-an-video","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/103701\/","title":{"rendered":"\u00ab\u00a0C&rsquo;\u00e9tait il n&rsquo;y a pas longtemps\u2026 Diego est l\u00e0\u00a0\u00bb\u00a0: Lio submerg\u00e9e par l&rsquo;\u00e9motion en \u00e9voquant son fils, qui s&rsquo;est suicid\u00e9 il y a un an (VIDEO)"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Une journ\u00e9e difficile aujourd&rsquo;hui pour les mamans belges, orphelines de leur enfant\u00a0\u00bb, peut-on notamment lire en commentaires sur les r\u00e9seaux.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Lio, invit\u00e9e de \u00ab\u00a0C \u00e0 Vous\u00a0\u00bb le 9\u00a0mai, a \u00e9mu le public en \u00e9voquant la m\u00e9moire de son fils Diego<a href=\"https:\/\/www.dhnet.be\/lifestyle\/people\/2025\/03\/05\/mort-du-fils-de-lio-la-chanteuse-reagit-au-deces-de-diego-qui-sest-immole-VQNL2YZAO5APRA6K3NH6UQB5ZE\/\" target=\"_self\" rel=\"nofollow noopener\">, d\u00e9c\u00e9d\u00e9 en mars\u00a02025<\/a>. Le jeune homme avait mis fin \u00e0 ses jours en s&rsquo;immolant par le feu, \u00e0 seulement 21 ans.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">La c\u00e9l\u00e8bre interpr\u00e8te de Banana Split dans les ann\u00e9es 80, \u00e9tait pr\u00e9sente pour parler de son<a href=\"https:\/\/www.dhnet.be\/medias\/musique\/2025\/11\/21\/lio-rend-hommage-a-son-fils-diego-decede-il-y-a-quelques-mois-dans-son-nouvel-album-sorti-ce-vendredi-4MZW3LS2HNHBFJ2WHZPAKQF5QM\/\" target=\"_self\" rel=\"nofollow noopener\"> nouvel album \u00ab\u00a0Geoid Party in the Sky\u00a0\u00bb <\/a>qui rend hommage \u00e0 son fils disparu pendant son enregistrement. Et la Belge a laiss\u00e9 transpara\u00eetre sa douleur face \u00e0 son absence, qui a \u00e9t\u00e9 une source d&rsquo;inspiration pour cet opus. L&rsquo;interpr\u00e9tation de son dernier morceau en direct, Amoureuse en solo, a accentu\u00e9 l&rsquo;\u00e9motion sur le plateau. Lio a exprim\u00e9 sa gratitude envers ses fans qui ont financ\u00e9 l&rsquo;album et a tenu \u00e0 souligner qu&rsquo;<a href=\"https:\/\/www.dhnet.be\/medias\/television\/2025\/10\/15\/un-jour-je-dormais-avec-mes-enfants-et-il-est-venu-me-violer-jetais-enceinte-de-sept-mois-lio-au-coeur-dun-docu-choc-dedie-a-son-fils-decede-RUNAOGG2LVH6VOJOMZAUO3PC6E\/\" target=\"_self\" rel=\"nofollow noopener\">elle re\u00e7oit \u00e9norm\u00e9ment d&rsquo;amour malgr\u00e9 les difficult\u00e9s.<\/a> \u00ab\u00a0Geoid est l&rsquo;anagramme de Diego\u00a0\u00bb, explique la chanteuse belge de 63 ans. \u00ab\u00a0Et c&rsquo;est aussi la terre en forme de patate quand elle n&rsquo;a pas la gravit\u00e9\u2026 il adorait l&rsquo;espace et il est parti -faire la party- in the sky j&rsquo;esp\u00e8re.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"\u00ab\u00a0Une journ\u00e9e difficile aujourd&rsquo;hui pour les mamans belges, orphelines de leur enfant\u00a0\u00bb, peut-on notamment lire en commentaires sur&hellip;\n","protected":false},"author":2,"featured_media":103702,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[2821,16569,3046,3047,3048,1381,12,13,2822,2823,1488,1526,18,17,43,1749,2825,2826,2827,2828,9802,3049,96,95,9803,2832,326,1080,482,3051,9804,9805,9806,3053,9807,1362,9808,9809,894,21137,2171,3054,1541,3055,3056,2845,3057,906,369,9810,2861,1082,1549,412],"class_list":{"0":"post-103701","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-divertissement","8":"tag-vkalut","9":"tag-16569","10":"tag-antwerp","11":"tag-antwerp-fc","12":"tag-antwerpen","13":"tag-anvers","14":"tag-be","15":"tag-be-fr","16":"tag-beker","17":"tag-beker-van-belgie","18":"tag-belgian","19":"tag-belgie","20":"tag-belgique","21":"tag-belgium","22":"tag-brussels","23":"tag-club","24":"tag-coupe","25":"tag-coupe-de-belgique","26":"tag-croky","27":"tag-cup","28":"tag-de-kakkers","29":"tag-de-ploeg-van-t-stad","30":"tag-divertissement","31":"tag-entertainment","32":"tag-fc-malinois","33":"tag-final","34":"tag-finale","35":"tag-foot","36":"tag-football","37":"tag-great","38":"tag-koninklijke-voetbalclub-mechelen","39":"tag-kv-mechelen","40":"tag-kvm","41":"tag-lantwerp","42":"tag-les-sang-et-or","43":"tag-malines","44":"tag-malinois","45":"tag-malinwa","46":"tag-match","47":"tag-mechelen","48":"tag-old","49":"tag-rafc","50":"tag-red","51":"tag-reds","52":"tag-roodwit","53":"tag-royal","54":"tag-royal-antwerp-football","55":"tag-soccer","56":"tag-sport","57":"tag-the-yellow-reds","58":"tag-vincent-kalut","59":"tag-voetbal","60":"tag-wedstrijd","61":"tag-yellow"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/103701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=103701"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/103701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/103702"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=103701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=103701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=103701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}