{"id":104696,"date":"2026-05-12T13:32:15","date_gmt":"2026-05-12T13:32:15","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/104696\/"},"modified":"2026-05-12T13:32:15","modified_gmt":"2026-05-12T13:32:15","slug":"je-me-suis-bien-trompe-antoine-maries-au-premier-regard-fait-une-decouverte-inattendue-sur-melanie-leur-histoire-chavire","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/104696\/","title":{"rendered":"\u00ab\u00a0Je me suis bien tromp\u00e9\u00a0\u00bb : Antoine (Mari\u00e9s au premier regard) fait une d\u00e9couverte inattendue sur M\u00e9lanie, leur histoire chavire"},"content":{"rendered":"<p class=\"articleContent-meta\">\n        Aujourd&rsquo;hui \u00e0 14:38 &#8211; par             <a class=\"articleContent-metaAuthorsLink\" href=\"https:\/\/www.programme.tv\/auteur\/jessica-gajderowicz\/\" rel=\"nofollow noopener\" target=\"_blank\">Jessica Gajderowicz<\/a><\/p>\n<p>                        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/05\/tl-melanie-candidates-de-maries-au-premier-regard-nous-raconte-sa-phobie-pour-les-avions.jpg\" alt=\"Player Video\" class=\"player-applyRatio poster exclude-seedtag\"\/><\/p>\n<p>Dans l\u2019\u00e9pisode 13 partie 1 de Mari\u00e9s au premier regard d\u00e9j\u00e0 disponible sur M6+, l\u2019ambiance est tendue entre Antoine et M\u00e9lanie. Mais une activit\u00e9 \u00e0 deux a tout chang\u00e9 du c\u00f4t\u00e9 du jeune homme. En effet, il a vu son \u00e9pouse sous un nouvel angle.<\/p>\n<p>Pour la premi\u00e8re fois, Mari\u00e9s au premier regard a propos\u00e9 une exp\u00e9rience totalement in\u00e9dite. M\u00e9lanie et Lucile, deux s\u0153urs, ont souhait\u00e9 se marier le m\u00eame jour. Une requ\u00eate accept\u00e9e par leurs pr\u00e9tendants. D\u00e8s les d\u00e9buts de l\u2019exp\u00e9rience, <a href=\"https:\/\/www.programme.tv\/news\/emissions-tv\/267389-melanie-maries-au-premier-regard-partage-ses-doutes-apres-avoir-rencontre-son-futur-mari-j-espere-qu-il-ne-sera-pas-focus-sur-ma-soeur\/\" rel=\"nofollow noopener\" target=\"_blank\">M\u00e9lanie redoutait que son futur mari n\u2019ait d\u2019yeux que pour sa s\u0153ur. <\/a>Et contrairement \u00e0 Lucile et Alex qui vivent une histoire torride,<a href=\"https:\/\/www.programme.tv\/news\/emissions-tv\/267687-il-ny-a-pas-eu-letincelle-antoine-maries-au-premier-regard-avoue-aux-cameras-ne-pas-etre-attire-par-melanie\/\" rel=\"nofollow noopener\" target=\"_blank\"> les choses sont plus compliqu\u00e9es pour l\u2019autre paire.<\/a> En effet, les \u00e9changes sont beaucoup moins spontan\u00e9s et ils n\u2019arrivent pas \u00e0 briser la glace.<\/p>\n<p>Mari\u00e9s au premier regard : Antoine agr\u00e9ablement surpris par M\u00e9lanie<\/p>\n<p>Dans l\u2019\u00e9pisode treize de Mari\u00e9s au premier regard, M\u00e9lanie est toujours d\u00e9\u00e7ue de l\u2019attitude d\u2019Antoine. Alors qu\u2019elle \u00e9tait partie prendre son petit-d\u00e9jeuner avec Alex et Lucile pour ne pas manger seule, <a href=\"https:\/\/www.programme.tv\/news\/emissions-tv\/267705-je-me-sens-seule-melanie-maries-au-premier-regard-totalement-rejetee-par-antoine-elle-decouche-de-son-appartement\/\" rel=\"nofollow noopener\" target=\"_blank\">elle a d\u00e9couvert que son mari avait mang\u00e9 sans elle. <\/a>\u00ab\u00a0\u00c7a m\u2019a touch\u00e9e parce que j\u2019aime bien partager ce genre de moments m\u00eame si c\u2019est des moments simples. On est dans une exp\u00e9rience incroyable\u00a0\u00bb, a-t-elle rappel\u00e9. La candidate songe \u00e0 lui en parler apr\u00e8s leur activit\u00e9 surf. Et justement, Antoine est plut\u00f4t dubitatif \u00e0 ce sujet puisqu\u2019il confie face cam\u00e9ra : \u00ab\u00a0M\u00e9lanie a souvent peur pour beaucoup de choses, elle est souvent stress\u00e9e en plus elle n\u2019est pas sportive. D\u00e9j\u00e0 elle a du mal \u00e0 tenir le surf\u00a0\u00bb. Pire encore, il enl\u00e8ve son alliance de peur qu\u2019elle tombe en mer. Mais M\u00e9lanie ne compte pas laisser ses angoisses prendre le dessus.Et bingo, elle a bel et bien r\u00e9ussi \u00e0 se donner \u00e0 c\u0153ur sur la planche. \u00ab\u00a0Je me suis bien tromp\u00e9. Elle y va de bonne volont\u00e9 \u00e7a m\u2019a rassur\u00e9 aussi parce que c\u2019est hyper positif\u00a0\u00bb, s\u2019est r\u00e9joui Antoine \u00e0 la fois content et surpris.<\/p>\n<p>                                Mari\u00e9s au premier regard : Antoine et M\u00e9lanie s\u2019expliquent<\/p>\n<p>M\u00eame s\u2019ils ont pass\u00e9 un beau moment, Antoine a senti que son \u00e9pouse n\u2019allait pas bien. M\u00e9lanie lui r\u00e9v\u00e8le alors pourquoi ce petit-d\u00e9jeuner pris sans elle l\u2019a touch\u00e9e. \u00ab\u00a0J\u2019ai d\u00e9j\u00e0 \u00e9t\u00e9 rejet\u00e9e avant dans mes relations des fois je mangeais seule le seul\u00a0\u00bb, explique-t-elle. Surpris, son compagnon ne pensait pas que c\u2019\u00e9tait aussi profond. Voyant qu\u2019elle a peur de revivre la m\u00eame chose, il tente de la rassurer. \u00ab\u00a0Il faut que tu partes de tes pens\u00e9es de tes ex, maintenant c\u2019est nous c\u2019est notre histoire\u00a0\u00bb, lui lance Antoine. Avant d\u2019ajouter : \u00ab\u00a0c\u2019est bien que tu m\u2019en parles et qu\u2019on se comprenne mieux\u00a0\u00bb. De l\u00e0, le couple devient pour la premi\u00e8re fois tactile. Un couac qui pourrait relancer leur lune de miel sur de bons rails.<\/p>\n<p>Article \u00e9crit en collaboration avec 6medias.<\/p>\n<p>Rejoignez-nous sur Google !<\/p>\n<p class=\"articleContent-pushTagline\">Abonnez-vous \u00e0 <a href=\"https:\/\/profile.google.com\/cp\/CgsvZy8xMjExMWxuMQ\" rel=\"nofollow noopener\" target=\"_blank\">T\u00e9l\u00e9 2 semaines sur Google<\/a> pour ne manquer aucune info !<\/p>\n","protected":false},"excerpt":{"rendered":"Aujourd&rsquo;hui \u00e0 14:38 &#8211; par Jessica Gajderowicz Dans l\u2019\u00e9pisode 13 partie 1 de Mari\u00e9s au premier regard d\u00e9j\u00e0&hellip;\n","protected":false},"author":2,"featured_media":104697,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[99],"tags":[3799,12,13,18,17,12355,3490,1083,96,95,1084,472,1085,15563,3442,19857,112,6253],"class_list":{"0":"post-104696","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-television","8":"tag-avion","9":"tag-be","10":"tag-be-fr","11":"tag-belgique","12":"tag-belgium","13":"tag-candidate","14":"tag-confidences","15":"tag-couple","16":"tag-divertissement","17":"tag-entertainment","18":"tag-m6","19":"tag-mariage","20":"tag-maries-au-premier-regard","21":"tag-mariu00c9s-au-premier-regard","22":"tag-mariu00e9s-au-premier-regard","23":"tag-phobie","24":"tag-television","25":"tag-tensions"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116561861001639416","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/104696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=104696"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/104696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/104697"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=104696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=104696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=104696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}