{"id":11370,"date":"2026-02-18T23:02:13","date_gmt":"2026-02-18T23:02:13","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/11370\/"},"modified":"2026-02-18T23:02:13","modified_gmt":"2026-02-18T23:02:13","slug":"le-retour-du-fameux-poulet-frites-compote-du-dimanche-comment-la-laiterie-a-linkebeek-a-relance-la-tradition-estaminet","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/11370\/","title":{"rendered":"Le retour du fameux poulet-frites-compote du dimanche\u00a0: comment la Laiterie \u00e0 Linkebeek a relanc\u00e9 la tradition \u00ab\u00a0estaminet\u00a0\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"w-full lazyload lazyload--opacity object-contain\" style=\"aspect-ratio:133 \/ 100;opacity:1\" alt=\"Jadis, plac\u00e9e devant l'entr\u00e9e, elle a trouv\u00e9 sa place sur la terrasse arri\u00e8re\" width=\"768\" height=\"576\" fetchpriority=\"auto\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/1770894307_282_S5VKD3X55FFF3BW6V4SEHXNP7I.png\"  data- data-optimumx=\"1\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/AXXJVXG7ZVBK3IY4JSEX7CBXEQ.jpg\" width=\"768\" height=\"576\" alt=\"Jadis, plac\u00e9e devant l'entr\u00e9e, elle a trouv\u00e9 sa place sur la terrasse arri\u00e8re\" class=\"absolute inset-0 w-full\"\/>Jadis, plac\u00e9e devant l&rsquo;entr\u00e9e, elle a trouv\u00e9 sa place sur la terrasse arri\u00e8re \u00a9DR<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Quand nous avons rachet\u00e9 en 2018, nous avons voulu revenir aux origines en \u00e9liminant le n\u00e9on orange et la peinture rose. Retour au blanc et brun. \u00c0 l&rsquo;int\u00e9rieur, nous avons tenu au combo estaminet restaurant. Estaminet avec comptoir, cuisine ouverte, ambiance bistrot et restaurant avec verri\u00e8re v\u00e9randa (sans oublier la terrasse tr\u00e8s pris\u00e9e en \u00e9t\u00e9).\u00a0\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"w-full lazyload lazyload--opacity object-contain\" style=\"aspect-ratio:143 \/ 100;opacity:1\" alt=\"Une ambiance chaleureuse et familiale\" width=\"768\" height=\"539\" fetchpriority=\"auto\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/1770894307_282_S5VKD3X55FFF3BW6V4SEHXNP7I.png\"  data- data-optimumx=\"1\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/QRSYTROHHNADXM26F4PRVAQTFA.jpg\" width=\"768\" height=\"539\" alt=\"Une ambiance chaleureuse et familiale\" class=\"absolute inset-0 w-full\"\/>Une ambiance chaleureuse et familiale \u00a9DR<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Depuis sept ans (d\u00e9j\u00e0\u2026), l&rsquo;accent a \u00e9t\u00e9 clairement mis sur trois aspects : l&rsquo;accueil, les familles (le gros plus est l&rsquo;espace enfants dont l&rsquo;am\u00e9nagement sonne comme une bulle d&rsquo;oxyg\u00e8ne pour les parents\u2026) et la qualit\u00e9 d&rsquo;une cuisine roborative comme on dit. En gros, on en a pour son argent avec des plats copieux qui font du bien.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Nous avons toujours pr\u00e9f\u00e9r\u00e9 mieux que pas assez, sourit Julien. Notre chef a toujours \u00e9t\u00e9 g\u00e9n\u00e9reux avec des plats authentiques plut\u00f4t traditionnels (gibier en saison, croquettes de crevettes, filet de bar, rognons de veau, pain de viande, carbonnades flamandes,\u2026). Nous tenons aussi \u00e0 proposer un plat du jour qui fait recette. \u00ab\u00a0<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Il est vrai que son prix (16 euros) d\u00e9tonne dans un milieu de l&rsquo;Horeca qui a parfois tendance \u00e0 gonfler. Laddition: seize euros + un verre de vin + un caf\u00e9 = 25 euros. Imbattable dans la capitale.<\/p>\n<p class=\"ap-StoryQuote-text\">Addition l\u00e9g\u00e8re: plat du jour + un verre de vin + un caf\u00e9 = 25 euros<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Quand vous d\u00e9barquez incognito \u00e0 la Laiterie, vous \u00eates surpris d&rsquo;arriver dans une r\u00e9union de copains. Tout le monde (ou presque) se conna\u00eet. C&rsquo;est \u00e7a l&rsquo;esprit estaminet comme Bruxelles savait le cultiver jadis.<\/p>\n<p>Le retour du poulet frites compote familial du dimanche!<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Ambiance entretenue avec le retour (meme s&rsquo;il est \u00e0 l&rsquo;affiche depuis 2018) du fameux poulet-frites-compote du dimanche midi. Une institution familiale qui avait quasiment disparu de nos \u00e9tablissements. Le revoil\u00e0. Et il fait le plein pour 22 euros.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Reste un des points noirs \u00e0 Bruxelles : le parking. Jadis, le supermarch\u00e9 Delhaize (en face du restaurant) permettait une offre large mais des barri\u00e8res ont \u00e9t\u00e9 install\u00e9es.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Au-del\u00e0 de notre parking clients que nous g\u00e9rons comme des voituriers, il y a de la place dans les rues adjacentes (c&rsquo;est vrai\u2026) ou \u00e0 quelques dizaines de m\u00e8tres chez un magasin de meubles en soir\u00e9e.\u00a0\u00bb<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Le tout est gratuit. Ce qui \u00e0 Bruxelles reste une exception non n\u00e9gligeable<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Petit point historique : la Laiterie a toujours \u00e9t\u00e9 une affaire de famille. Lorsque les Van Gucht ont d\u00e9cid\u00e9 de se s\u00e9parer de l&rsquo;endroit, la famille Gold\u00e9 s&rsquo;est rapidement mis sur le coup.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Apr\u00e8s avoir tenu Le Petit Golf \u00e0 Watermael-Boitsfort au Drohme o\u00f9 j&rsquo;\u00e9tais comme un poisson dans l&rsquo;eau, je cherchais un nouveau point de chute. Comment ne pas tomber amoureux de l&rsquo;endroit ?\u00a0\u00bb<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">On ne peut pas lui donner tort\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"Jadis, plac\u00e9e devant l&rsquo;entr\u00e9e, elle a trouv\u00e9 sa place sur la terrasse arri\u00e8re \u00a9DR \u00ab\u00a0Quand nous avons rachet\u00e9&hellip;\n","protected":false},"author":2,"featured_media":11371,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12,13,18,17,391,28,7445,3765,2143],"class_list":{"0":"post-11370","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-belgique","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-brabant-wallon","13":"tag-bruxelles-villes","14":"tag-linkebeek","15":"tag-uccle","16":"tag-watermael-boitsfort"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/11370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=11370"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/11370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/11371"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=11370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=11370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=11370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}