{"id":11538,"date":"2026-02-19T02:40:11","date_gmt":"2026-02-19T02:40:11","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/11538\/"},"modified":"2026-02-19T02:40:11","modified_gmt":"2026-02-19T02:40:11","slug":"le-grand-prix-de-formule-1-organise-un-an-sur-deux-a-spa-francorchamps-un-electrochoc-pour-la-region-de-stavelot-et-malmedy","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/11538\/","title":{"rendered":"Le Grand Prix de Formule 1 organis\u00e9 un an sur deux \u00e0 Spa-Francorchamps\u00a0: \u00ab\u00a0Un \u00e9lectrochoc pour la r\u00e9gion\u00a0\u00bb de Stavelot et Malmedy"},"content":{"rendered":"<p>Pr\u00e8s de 2 millions de pertes de recettes que Stavelot avait d\u00e9j\u00e0 anticip\u00e9es<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Un fameux manque \u00e0 gagner, donc. Mais l&rsquo;information avait \u00e9t\u00e9 anticip\u00e9e. \u00ab\u00a0D\u00e9j\u00e0 l&rsquo;ann\u00e9e pass\u00e9e, des articles avaient annonc\u00e9 que le Grand Prix risquait de ne pas \u00eatre organis\u00e9 en 2028 et 2030. J&rsquo;ai tenu compte de ces param\u00e8tres et on a commenc\u00e9 \u00e0 provisionner. On a aussi pris des mesures de mani\u00e8re \u00e0 pallier l&rsquo;absence de deux comp\u00e9titions, en sachant que si l&rsquo;\u00e9preuve venait \u00e0 \u00eatre finalement organis\u00e9e ce ne serait que du boni.\u00a0\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"w-full lazyload lazyload--opacity object-contain\" style=\"aspect-ratio:150 \/ 100;opacity:1\" alt=\"Interview du samedi : Fabien Legros bourgmestre de Stavelot\" width=\"768\" height=\"511\" fetchpriority=\"auto\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/1771412889_836_S5VKD3X55FFF3BW6V4SEHXNP7I.png\"  data- data-optimumx=\"1\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/7ZT3GT4IKNH3BA35RNBPYCDQ5Q.jpg\" width=\"768\" height=\"511\" alt=\"Interview du samedi : Fabien Legros bourgmestre de Stavelot\" class=\"absolute inset-0 w-full\"\/>Le bourgmestre de Stavelot, Fabien Legros, avait anticip\u00e9 la non-organisation du Grand Prix. \u00a9EDA<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Mais en attendant cette hypoth\u00e9tique bonne nouvelle, la Commune devra composer sans les rentr\u00e9es li\u00e9es aux panneaux publicitaires, aux entr\u00e9es de camping, \u00e0 la billetterie\u2026 Et cette alternance pourrait bien se prolonger au-del\u00e0 de 2032. \u00ab\u00a0C&rsquo;est certain qu&rsquo;on ne peut plus d\u00e9penser de la m\u00eame mani\u00e8re, poursuit le mayeur. Les ann\u00e9es o\u00f9 le Grand Prix est organis\u00e9, on devra mettre une partie de recettes de c\u00f4t\u00e9 afin de financer les ann\u00e9es sans course.\u00a0\u00bb<\/p>\n<p>Des finances communales qui seront encore plus mises \u00e0 mal<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Et pour ne rien arranger, les finances communales sont mises sous pression p<a href=\"https:\/\/www.lavenir.net\/lavenir-vous-repond\/2025\/10\/17\/je-serai-exclu-du-chomage-en-2026-comment-savoir-si-jaurai-droit-a-une-aide-du-cpas-T4RCZ2BUIRDYZK4LCL4LWFHIJA\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">ar les mesures prises aux autres niveaux de pouvoir<\/a>. \u00ab\u00a0C&rsquo;est vrai qu&rsquo;on n&rsquo;est pas rassur\u00e9 par tout ce qu&rsquo;on entend. On est aussi fort impact\u00e9s par la cotisation de responsabilisation (NDLR : une d\u00e9pense impos\u00e9e par le f\u00e9d\u00e9ral pour le paiement des pensions des fonctionnaires locaux).\u00a0\u00bb<\/p>\n<p>Le bourgmestre de Stavelot ne veut pas toucher \u00e0 la fiscalit\u00e9 ni \u00e0 l&#8217;emploi<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Et comme le bourgmestre ne veut pas toucher \u00e0 la fiscalit\u00e9, \u00ab\u00a0qui est d\u00e9j\u00e0 \u00e9lev\u00e9e \u00e0 Stavelot\u00a0\u00bb, pr\u00e9server l&#8217;emploi et continuer \u00e0 assurer un maximum de services, c&rsquo;est du c\u00f4t\u00e9 des projets qu&rsquo;il faudra faire des \u00e9conomies. \u00ab\u00a0Certains d&rsquo;entre eux risquent de ne pas \u00eatre pr\u00e9sent\u00e9s, parce que pas finan\u00e7ables.\u00a0\u00bb La <a href=\"https:\/\/www.lavenir.net\/regions\/verviers\/stavelot\/2025\/09\/26\/voici-a-quoi-va-ressembler-la-future-salle-culturelle-de-stavelot-le-debut-des-travaux-est-prevu-en-automne-2026-photos-3HWY7O6J7BBNFBXSDOG43MAK3A\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">salle culturelle<\/a> et <a href=\"https:\/\/www.lavenir.net\/regions\/verviers\/stavelot\/2024\/03\/29\/le-hall-sportif-des-bressaix-a-stavelot-va-etre-agrandi-6ZFLRQULLNGUPLEKYP6BPLH6VQ\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">le hall des sports, <\/a>notamment, risquent de se retrouver en sursis.<\/p>\n<p class=\"ap-StoryQuote-text\">\u00ab\u00a0Il y a aura peut-\u00eatre un retournement de situation. \u00c7a me para\u00eet tr\u00e8s mal embarqu\u00e9 pour 2028, mais je veux rester optimiste pour 2030.\u00a0\u00bb<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Mais rien ne sert de mettre la charrue avant les b\u0153ufs. \u00ab\u00a0Il y a encore des informations dont on ne dispose pas. On parle de nouvelles diminutions de moyens accord\u00e9s par les autres niveaux de pouvoir. On d\u00e9cidera de ce qu&rsquo;on fera, ou pas, une fois qu&rsquo;on aura tous les \u00e9l\u00e9ments.\u00a0\u00bb<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Et puis, on n&rsquo;est pas \u00e0 l&rsquo;abri d&rsquo;une bonne nouvelle. \u00ab\u00a0Peut-\u00eatre que d&rsquo;autres activit\u00e9s pourront compenser en partie les pertes li\u00e9es \u00e0 l&rsquo;absence de Grand Prix. Et il y aura peut-\u00eatre un retournement de situation. \u00c7a me para\u00eet tr\u00e8s mal embarqu\u00e9 pour 2028, mais je veux rester optimiste pour 2030.\u00a0\u00bb<\/p>\n<p>\u00c0 Malmedy, l&rsquo;absence de Grand Prix aura aussi des cons\u00e9quences<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Du c\u00f4t\u00e9 des voisins <a href=\"https:\/\/www.lavenir.net\/regions\/verviers\/malmedy\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">malm\u00e9diens<\/a>, la non-organisation du Grand Prix aura moins d&rsquo;impact sur les finances communales, mais quand m\u00eame. \u00ab\u00a0Cet \u00e9v\u00e9nement repr\u00e9sente minimum 700 000 \u20ac de recettes\u00a0\u00bb, d\u00e9taille l&rsquo;\u00e9chevin des Finances Jacques Remy-Paquay.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Ici aussi, il faudra voir comment g\u00e9rer cette perte. \u00ab\u00a0On devra regarder du c\u00f4t\u00e9 de nos d\u00e9penses et de nos investissements afin d&rsquo;absorber le choc sans acc\u00e9l\u00e9rer la fiscalit\u00e9 pour les Malm\u00e9diens.\u00a0\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"w-full lazyload lazyload--opacity object-contain\" style=\"aspect-ratio:150 \/ 100;opacity:1\" alt=\"La perte du Grand Prix, c'est loin d'\u00eatre une bonne nouvelle pour les finances malm\u00e9diennes.\" width=\"768\" height=\"512\" fetchpriority=\"auto\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/1771412889_836_S5VKD3X55FFF3BW6V4SEHXNP7I.png\"  data- data-optimumx=\"1\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/02\/KH6LIWDMAVHXNLOZCCL25HDHVQ.jpg\" width=\"768\" height=\"512\" alt=\"La perte du Grand Prix, c'est loin d'\u00eatre une bonne nouvelle pour les finances malm\u00e9diennes.\" class=\"absolute inset-0 w-full\"\/>La perte du Grand Prix, c&rsquo;est loin d&rsquo;\u00eatre une bonne nouvelle pour les finances malm\u00e9diennes. \u00a9 \u00c9dA LABEYE PhilippeUne d\u00e9cision qui impactera bien plus que les finances communales de Malmedy et Stavelot<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Et, outre la Commune, de nombreux acteurs \u00e9conomiques de la r\u00e9gion vont \u00eatre impact\u00e9s. \u00ab\u00a0Pendant les Grand Prix, les g\u00eetes et les h\u00f4tels sont remplis, le chiffre d&rsquo;affaires de l&rsquo;Horeca explose, les commerces connaissent un afflux massif de clients\u2026\u00a0\u00bb Le secteur associatif, souvent pr\u00e9sent lors du Grand Prix, sera \u00e9galement impact\u00e9.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Bref, \u00ab\u00a0c&rsquo;est un \u00e9lectrochoc pour la r\u00e9gion. L&rsquo;\u00e9conomie locale est tr\u00e8s d\u00e9pendante du Grand Prix.\u00a0\u00bb Mais comme le mayeur stavelotain, Jacques Remy-Paquay se veut positif. \u00ab\u00a0C&rsquo;est aussi une opportunit\u00e9 de voir dans quelle mesure on peut \u00eatre moins d\u00e9pendant du circuit. M\u00eame si je n&rsquo;y crois pas trop, on peut toujours esp\u00e9rer que le Grand Prix soit organis\u00e9 plus qu&rsquo;un an sur deux. Et dans ce cas-l\u00e0, ce sera du bonus.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"Pr\u00e8s de 2 millions de pertes de recettes que Stavelot avait d\u00e9j\u00e0 anticip\u00e9es Un fameux manque \u00e0 gagner,&hellip;\n","protected":false},"author":2,"featured_media":11539,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[2867,12,13,18,17,987,784,84,7617],"class_list":{"0":"post-11538","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sports","8":"tag-24h-de-spa-francorchamps","9":"tag-be","10":"tag-be-fr","11":"tag-belgique","12":"tag-belgium","13":"tag-malmedy","14":"tag-spa","15":"tag-sports","16":"tag-stavelot"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/11538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=11538"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/11538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/11539"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=11538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=11538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=11538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}