{"id":15430,"date":"2026-02-22T08:43:07","date_gmt":"2026-02-22T08:43:07","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/15430\/"},"modified":"2026-02-22T08:43:07","modified_gmt":"2026-02-22T08:43:07","slug":"verre-plus-leger-cubis-bouchons-synthetiques-quel-futur-pour-les-bouteilles-de-vin-le-truc-genial-cest-la-canette-assure-eric-boschman","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/15430\/","title":{"rendered":"Verre plus l\u00e9ger, cubis, bouchons synth\u00e9tiques\u2026 Quel futur pour les bouteilles de vin\u00a0? \u00ab\u00a0Le truc g\u00e9nial, c&rsquo;est la canette\u00a0\u00bb, assure Eric Boschman"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Pour le sommelier belge Eric Boschman, l&rsquo;enjeu est clair. \u00ab\u00a0La vraie difficult\u00e9, c&rsquo;est de diminuer la charge carbone du vin, et le secteur le plus polluant, c&rsquo;est la bouteille\u00a0\u00bb, r\u00e9sume-t-il. Et sur le plan gustatif ? Il se veut rassurant. \u00ab\u00a0Au niveau du go\u00fbt, \u00e7a ne change rien. Quant \u00e0 la conservation, les premiers retours sont encourageants. Ces nouveaux flacons constituent surtout une avanc\u00e9e pour les vignerons, davantage qu&rsquo;une r\u00e9volution pour le consommateur\u00a0\u00bb, compl\u00e8te-t-il.<\/p>\n<p><a href=\"https:\/\/www.dhnet.be\/conso\/consommation\/2025\/12\/28\/la-question-conso-prix-alternatives-service-eric-boschman-nous-livre-tous-ses-secrets-sur-le-champagne-oubliez-les-coupes-et-les-flutes-GFS2ORYHXZCG7BGTYG5DT4FXGY\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">La Question Conso : prix, alternatives, service, Eric Boschman nous livre tous ses secrets sur le Champagne, \u00ab\u00a0oubliez les coupes et les fl\u00fbtes !\u00a0\u00bb<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">En fait, toute la fili\u00e8re cherche \u00e0 r\u00e9duire son impact : capsules, transport, bouchons, tout fait l&rsquo;objet d&rsquo;\u00e9tudes et d&rsquo;innovations. Pour les bouchons, Eric Boschman reste tr\u00e8s attach\u00e9 au li\u00e8ge naturel. \u00ab\u00a0Le li\u00e8ge, ce sont des arbres qui absorbent du carbone et se r\u00e9g\u00e9n\u00e8rent. C&rsquo;est ce qu&rsquo;il y a de mieux. Les bouchons synth\u00e9tiques ou en verre, eux, affichent un bilan carbone moins favorable.\u00a0\u00bb<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">D&rsquo;autres pistes existent. Les bouteilles en plastique PET ont \u00e9t\u00e9 test\u00e9es : l\u00e9g\u00e8res, mais \u00ab\u00a0z\u00e9ro\u00a0\u00bb en mati\u00e8re de conservation, selon le sommelier. En revanche, il d\u00e9fend une option plus iconoclaste. \u00ab\u00a0Vous voulez un bon titre ? Le truc id\u00e9al, c&rsquo;est la canette\u00a0\u00bb, rigole-t-il, avant de d\u00e9fendre plus s\u00e9rieusement son point de vue. \u00ab\u00a0L&rsquo;aluminium est recyclable \u00e0 100 %, refroidit tr\u00e8s vite et n&rsquo;alt\u00e8re pas le go\u00fbt, assure-t-il. J&rsquo;ai fait des d\u00e9gustations \u00e0 l&rsquo;aveugle : on ne voit pas de diff\u00e9rence. J&rsquo;ai m\u00eame vu des vignerons qui tiraient la t\u00eate apr\u00e8s n&rsquo;y avoir vu que de feu ! Pratique, l\u00e9g\u00e8re et adapt\u00e9e \u00e0 une consommation individuelle ou nomade \u2013 pour un pique-nique, par exemple -, la canette pourrait gagner du terrain, m\u00eame si les mentalit\u00e9s doivent encore \u00e9voluer.\u00a0\u00bb<\/p>\n<p><a href=\"https:\/\/www.dhnet.be\/conso\/consommation\/2025\/12\/21\/eric-boschman-se-prete-au-jeu-du-grand-test-des-marques-et-donne-son-avis-sur-les-champagnes-premier-prix-celui-ci-plaira-a-enormement-de-monde-XTCKOJF2YJG6BHMIBUHBZNKBGE\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">Eric Boschman se pr\u00eate au jeu du grand test des marques et donne son avis sur les champagnes premier prix : \u00ab\u00a0Celui-ci plaira \u00e0 \u00e9norm\u00e9ment de monde !\u00a0\u00bb<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Les cubis (Bag-in-Box, dans le jargon) progressent aussi. \u00ab\u00a0On trouve d\u00e9sormais de tr\u00e8s bons vins en 3 ou 5 litres\u00a0\u00bb, observe-t-il, m\u00eame si l&rsquo;image reste moins prestigieuse. Capsules \u00e0 vis ou demi-bouteilles compl\u00e8tent l&rsquo;offre, sans bouleverser l&rsquo;\u00e9quilibre du march\u00e9. \u00ab\u00a0Il vaut mieux une canette qu&rsquo;une demi-bouteille, au niveau de la conservation\u00a0\u00bb, pr\u00e9cise-t-il enfin.<\/p>\n<p><a href=\"https:\/\/www.dhnet.be\/conso\/consommation\/2025\/12\/31\/des-bulles-wallonnes-pour-feter-le-passage-a-lan-neuf-voici-la-selection-100-belge-deric-boschman-cest-tres-reconfortant-presque-contemplatif-UMHDV2W5QNF2JDBECPJE7XSOOQ\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">Des bulles wallonnes pour f\u00eater le passage \u00e0 l&rsquo;an neuf ? Voici la s\u00e9lection 100 % belge d&rsquo;Eric Boschman : \u00ab\u00a0C&rsquo;est tr\u00e8s r\u00e9confortant, presque contemplatif\u00a0\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Pour le sommelier belge Eric Boschman, l&rsquo;enjeu est clair. \u00ab\u00a0La vraie difficult\u00e9, c&rsquo;est de diminuer la charge carbone&hellip;\n","protected":false},"author":2,"featured_media":15431,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[12,13,18,17,38,5047,37,36],"class_list":{"0":"post-15430","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economie","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-business","13":"tag-conso","14":"tag-economie","15":"tag-economy"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/15430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=15430"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/15430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/15431"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=15430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=15430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=15430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}