{"id":24361,"date":"2026-03-01T20:30:13","date_gmt":"2026-03-01T20:30:13","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/24361\/"},"modified":"2026-03-01T20:30:13","modified_gmt":"2026-03-01T20:30:13","slug":"notre-prise-en-main-de-la-tablette-la-plus-fine-du-monde-frandroid","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/24361\/","title":{"rendered":"notre prise en main de la tablette la plus fine du monde \u2014 Frandroid"},"content":{"rendered":"<p>La Honor MagicPad 4 est la tablette la plus fine du monde, encore plus que l\u2019iPad Pro qui excellait pourtant d\u00e9j\u00e0 en ce domaine. Et ce n\u2019est pas pour autant qu\u2019elle sacrifie sa configuration. Un processeur Snapdragon encore jamais vu dans une tablette, une \u00e9norme batterie, un \u00e9cran Oled au bon format pour le multim\u00e9dia, rien que la fiche technique me donnait envie de la prendre rapidement en main.\u00a0<\/p>\n<p class=\"shortcode-container see-more\">\n    Pour aller plus loin<br \/><a href=\"https:\/\/www.frandroid.com\/guide-dachat\/guide-tablettes\/320702_guide-dachat-tablette-choisir-noel\" rel=\"nofollow noopener\" target=\"_blank\">Les meilleures tablettes tactiles en 2026, du premier prix au haut de gamme<\/a>\n            <\/p>\n<p>C\u2019est chose faite, je l\u2019ai depuis une dizaine de jours et j\u2019ai d\u00e9j\u00e0 pu bien avancer sur mes tests. Voici donc mon premier ressenti sur cette tablette Android qui pousse la concurrence pour se faire une place aux c\u00f4t\u00e9s des plus grands, mais \u00e0 un prix bien plus int\u00e9ressant.<\/p>\n<p>&#13;<\/p>\n<p>Fiche technique<\/p>\n<p>        Mod\u00e8le<br \/>\n                <a href=\"https:\/\/www.frandroid.com\/produits\/tablettes-tactiles\/honor\/2975519-honor-magicpad-4\" rel=\"nofollow noopener\" target=\"_blank\">Honor MagicPad 4<\/a><\/p>\n<p>            Dimensions<\/p>\n<p>                                    273,4 mm x 178,8 mm                            <\/p>\n<p>            Taille de l\u2019\u00e9cran<\/p>\n<p>                                    12,3 pouces                            <\/p>\n<p>            D\u00e9finition<\/p>\n<p>                                    3000 x 1920 pixels                            <\/p>\n<p>            Densit\u00e9 de pixels<\/p>\n<p>                                    290 ppp                            <\/p>\n<p>            Technologie de l\u2019\u00e9cran<\/p>\n<p>                                    OLED                            <\/p>\n<p>            Mod\u00e8le du processeur<\/p>\n<p>                                    Snapdragon 8 Gen 5                            <\/p>\n<p>            M\u00e9moire vive (RAM)<\/p>\n<p>                                    12, 16 Go                            <\/p>\n<p>            M\u00e9moire interne<\/p>\n<p>                                    256, 512 Go                            <\/p>\n<p>            Appareil photo (dorsal)<\/p>\n<p>                                    13 Mp                            <\/p>\n<p>            Appareil photo (frontal)<\/p>\n<p>                                    9 Mp                            <\/p>\n<p>            Wifi<\/p>\n<p>                                    Wi-Fi 7 (be)                            <\/p>\n<p>            Bluetooth<\/p>\n<p>                                    6.0                            <\/p>\n<p>            NFC<\/p>\n<p>                                    Non                            <\/p>\n<p>            \u00c9tanche<\/p>\n<p>                                    Inconnu                            <\/p>\n<p>            Poids<\/p>\n<p>                                    450 grammes                            <\/p>\n<p>            Couleurs<\/p>\n<p>                                    Blanc, Gris                            <\/p>\n<p>                                <a class=\"button fr-button fr-button--pink fr-button--fullwidth has-text-centered\" href=\"https:\/\/www.frandroid.com\/produits\/tablettes-tactiles\/honor\/2975519-honor-magicpad-4\" rel=\"nofollow noopener\" target=\"_blank\">Fiche produit<\/a><\/p>\n<p>&#13;<\/p>\n<p>Design : Une prouesse d\u2019ing\u00e9nierie \u00e0 4,8 mm<\/p>\n<p>Je pense que je n\u2019oublierai pas mon premier contact avec la Honor MagicPad 4. C\u2019est b\u00eate, on parle d\u2019une tablette, mais quelle finesse !<\/p>\n<p>Honor a r\u00e9ussi l\u2019exploit de r\u00e9duire l\u2019\u00e9paisseur \u00e0 seulement 4,8 mm. Pour situer le contexte, c\u2019est plus fin que l\u2019iPad Pro 13 (5,1 mm) et l\u2019iPad Air 13 (5,6 mm). Cette qu\u00eate de la minceur ne se fait pas au d\u00e9triment de la l\u00e9g\u00e8ret\u00e9, puisque l\u2019appareil p\u00e8se environ 450 grammes.<\/p>\n<p>En main, elle flotte, c\u2019est une feuille, mais elle n\u2019inspire pas pour autant de crainte quant \u00e0 sa solidit\u00e9. Pour cela, on peut compter sur un ch\u00e2ssis en m\u00e9tal unibody qui offre une excellente finition. Deux coloris sont disponibles : Gris et Blanc. Classique.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/honor-magicpad-4-2.jpg\" class=\"article-content__figure\" rel=\"nofollow noopener\"><img fetchpriority=\"high\" loading=\"eager\" decoding=\"async\" width=\"1200\" height=\"904\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/honor-magicpad-4-2-1200x904.jpg\" alt=\"\" class=\"wp-image-2989453 wp-image\"  \/><\/a><\/p>\n<p>La prise en main est sublim\u00e9e par des bordures ultra-fines de moins de 4 mm qui offrent un ratio \u00e9cran\/corps de 93 %. L\u2019\u00e9cran Oled est vraiment magnifi\u00e9 ainsi.\u00a0<\/p>\n<p>Malgr\u00e9 sa finesse extr\u00eame, la Magic Pad 4 conserve un syst\u00e8me \u00e0 huit haut-parleurs qui nous avait d\u00e9j\u00e0 plu sur la Magic Pad 2.\u00a0<\/p>\n<p>&#13;<\/p>\n<p>\u00c9cran : l\u2019OLED qui d\u00e9fie le soleil<\/p>\n<p>L\u2019affichage est l\u2019un des gros points forts de cette tablette. Honor abandonne la technologie LCD de la MagicPad 3 pour une dalle OLED de 12,3 pouces. La d\u00e9finition 3K de 3000 x 1920 pixels assure une densit\u00e9 de 290 PPI. La dalle est au format 16:10 environ. C\u2019est totalement diff\u00e9rent d\u2019un iPad Pro au format 4:3. Si Honor nous raconte une histoire de productivit\u00e9 avec cette tablette, on ne m\u2019\u00f4tera pas de l\u2019esprit qu\u2019elle est tout aussi bien taill\u00e9e pour une exp\u00e9rience multim\u00e9dia. Oled 16:10, c\u2019est un super combo pour les films et s\u00e9ries.<\/p>\n<p>\t\t\t\t\t\t<a href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/magicpad4-sdr-vives-chaude.png\" itemprop=\"url\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t<img decoding=\"async\" class=\"wp-image\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/magicpad4-sdr-vives-chaude.png\"  width=\"460\" height=\"372\" loading=\"lazy\" data-original-width=\"460\" data-original-height=\"372\" itemprop=\"http:\/\/schema.org\/image\" title=\"magicpad4 sdr vives chaude\" alt=\"magicpad4 sdr vives chaude\" style=\"width: 460px; height: 372px;\"\/><br \/>\n\t\t\t\t\t\t<\/a><\/p>\n<p>\t\t\t\t\t\t<a href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/magicpad4-hdr-vives-chaude.png\" itemprop=\"url\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t<img decoding=\"async\" class=\"wp-image\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/magicpad4-hdr-vives-chaude.png\"  width=\"460\" height=\"372\" loading=\"lazy\" data-original-width=\"460\" data-original-height=\"372\" itemprop=\"http:\/\/schema.org\/image\" title=\"magicpad4 hdr vives chaude\" alt=\"magicpad4 hdr vives chaude\" style=\"width: 460px; height: 372px;\"\/><br \/>\n\t\t\t\t\t\t<\/a><\/p>\n<p>Et puis, on peut aussi jouer avec dans de bonnes conditions gr\u00e2ce \u00e0 fluidit\u00e9 assur\u00e9e par un taux de rafra\u00eechissement adaptatif \u00e0 5 paliers grimpant jusqu\u2019\u00e0 165 Hz, surpassant les 120 Hz des iPad Pro. Mais c\u2019est surtout la luminosit\u00e9 qui m\u2019a impressionn\u00e9e : un pic de 2400 nits annonc\u00e9. Bien mieux que la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente et encore mieux en vrai ! Sous notre sonde, la tablette est mont\u00e9e jusqu\u2019\u00e0 3000 nits en HDR. En SDR, c\u2019est plus modeste avec 830 nits. Mais le r\u00e9sultat est tout de m\u00eame bon pour une tablette.\u00a0<\/p>\n<p>C\u00f4t\u00e9 colorim\u00e9trie, c\u2019est pas mal avec un DeltaE qui d\u00e9passe \u00e0 peine les valeurs cibles en SDR et HDR. Les tons chair et l\u2019\u00e9chelle de gris, voil\u00e0 ce qui d\u00e9borde un peu. La temp\u00e9rature est tr\u00e8s bonne avec 6341K, on approche vraiment des 6500K de la lumi\u00e8re du jour. Le blanc est donc vraiment blanc. Et pour la profondeur des noirs, on est sur de l\u2019Oled, alors elle est infinie.<\/p>\n<p>Concernant l\u2019\u00e9tendue des nuances de couleurs, on est parfait sur l\u2019espace sRGB, mais on ne comble pas le DCI-P3, seulement \u00e0 90%.<\/p>\n<p>Au global on a une tr\u00e8s bonne exp\u00e9rience avec cet \u00e9cran. Pas vraiment de point noir et surtout une tr\u00e8s tr\u00e8s bonne luminosit\u00e9, comme sur le Magic 8 Pro d\u2019ailleurs. \u00c0 l\u2019utilisation, je n\u2019ai jamais remarqu\u00e9 de souci et puis c\u2019est un terrible compagnon pour le divertissement. GeForce Now, Netflix, YouTube, tout y passe depuis que je l\u2019ai entre les mains.<\/p>\n<p>Et pour prot\u00e9ger les yeux, on peut compter la panoplie de protections oculaires de Honor :<\/p>\n<p>Gradation PWM de 5280 Hz pour \u00e9liminer le scintillement.<\/p>\n<p>Affichage d\u00e9focalis\u00e9 par IA pour r\u00e9duire la fatigue visuelle.<\/p>\n<p>Affichage circadien augmentant la m\u00e9latonine de 20 %.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111313-com-android-settings-settingsoasiseyecomfortsettingsac.jpg\" class=\"article-content__figure\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"768\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111313-com-android-settings-settingsoasiseyecomfortsettingsac-1200x768.jpg\" alt=\"\" class=\"wp-image-2995239 wp-image\"  \/><\/a><\/p>\n<p>&#13;<\/p>\n<p>Performances : le premier souffle du Snapdragon 8 Gen 5<\/p>\n<p>La MagicPad 4 inaugure la plateforme Snapdragon 8 Gen 5 de Qualcomm. Grav\u00e9e en 3 nm , cette puce octo-core monte jusqu\u2019\u00e0 3,8 GHz. C\u2019est la petite soeur du Snapdragon 8 Elite Gen 5 install\u00e9 notamment dans le Magic 8 Pro.<\/p>\n<p>Selon ma compilation de benchmarks, la MagicPad 4 obtient un score normalis\u00e9 de 59 991. Elle se place au coude \u00e0 coude avec le Samsung Galaxy Tab S11 Ultra (59 863) et la Redmagic Astra (59 881). Elle reste toutefois l\u00e9g\u00e8rement derri\u00e8re la OnePlus Pad 3 (62 566). Point commun entre ces trois tablettes, toutes utilisent un Snapdragon 8 Elite, la cr\u00e8me des SoC de 2025. Aussi, Qualcomm nous donne l\u2019occasion de retrouver les tr\u00e8s bonnes performances de ce SoC tout en y ajoutant quelques fioritures sur la partie r\u00e9seau notamment.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/image-69.png\" class=\"article-content__figure\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"577\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/image-69-1200x577.png\" alt=\"\" class=\"wp-image-2995151 wp-image\"  \/><\/a>Moyennes normalis\u00e9es de diff\u00e9rents benchmarks.<\/p>\n<p>C\u00f4t\u00e9 m\u00e9moire, on retrouve deux configurations : 12 Go ou 16 Go de RAM. Mon mod\u00e8le de test est la moins bien \u00e9quip\u00e9e des deux. Et pourtant, \u00e0 aucun moment je ne me suis senti limit\u00e9. La MagicPad 4 tourne comme une horloge. M\u00eame en jeu, elle assure sur mes sessions de Genshin Impact bien que j\u2019ai pouss\u00e9 toutes les options graphiques \u00e0 fond. Le 60 fps est tenu.<\/p>\n<p>Et mon test de <a href=\"https:\/\/www.frandroid.com\/produits-android\/smartphone\/2853559_votre-smartphone-rame-subitement-en-jeu-on-vous-explique-le-throttling-et-pourquoi-ce-nest-pas-toujours-une-mauvaise-nouvelle\" rel=\"nofollow noopener\" target=\"_blank\">throttling<\/a> vient confirmer mes bonnes impressions. La tablette d\u2019Honor en est totalement d\u00e9pourvue. Le processeur tourne \u00e0 pleine cadence sur une dur\u00e9e prolong\u00e9e, sans jamais faillir, preuve d\u2019une tr\u00e8s bonne optimisation du syst\u00e8me de refroidissement.<\/p>\n<p>On pourrait donc craindre un grand d\u00e9gagement de chaleur sur la coque. Il n\u2019en est rien non plus. \u00c0 l\u2019aide d\u2019une sonde thermique, j\u2019ai relev\u00e9 31\u00b0C au point le plus chaud du ch\u00e2ssis apr\u00e8s une heure de stress test.<\/p>\n<p>&#13;<\/p>\n<p>Logiciel : MagicOS 10 et le pont vers Apple<\/p>\n<p>La tablette tourne sous MagicOS 10 (bas\u00e9 sur Android 16). Honor a particuli\u00e8rement travaill\u00e9 la productivit\u00e9 avec un Mode PC capable de g\u00e9rer jusqu\u2019\u00e0 20 fen\u00eatres flottantes simultan\u00e9ment. J\u2019ai pu en profiter durant mon vol vers le MWC 2026. Avec le clavier additionnel, c\u2019est une tablette compacte qui permet vraiment de tout faire en mobilit\u00e9, comme un vrai PC.\u00a0<\/p>\n<p>\t\t\t\t\t\t<a href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111319-com-hihonor-eyesense-defocusactivity.jpg\" itemprop=\"url\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t<img decoding=\"async\" class=\"wp-image\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111319-com-hihonor-eyesense-defocusactivity.jpg\"  width=\"460\" height=\"294\" loading=\"lazy\" data-original-width=\"460\" data-original-height=\"294\" itemprop=\"http:\/\/schema.org\/image\" title=\"Screenshot_20260225_111319_com_hihonor_eyesense_DefocusActivity\" alt=\"Screenshot_20260225_111319_com_hihonor_eyesense_DefocusActivity\" style=\"width: 460px; height: 294px;\"\/><br \/>\n\t\t\t\t\t\t<\/a><\/p>\n<p>\t\t\t\t\t\t<a href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111351-com-hihonor-assistant-yoyoassistantstartactivity.jpg\" itemprop=\"url\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t<img decoding=\"async\" class=\"wp-image\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/screenshot-20260225-111351-com-hihonor-assistant-yoyoassistantstartactivity.jpg\"  width=\"460\" height=\"294\" loading=\"lazy\" data-original-width=\"460\" data-original-height=\"294\" itemprop=\"http:\/\/schema.org\/image\" title=\"Screenshot_20260225_111351_com_hihonor_assistant_YoYoAssistantStartActivity\" alt=\"Screenshot_20260225_111351_com_hihonor_assistant_YoYoAssistantStartActivity\" style=\"width: 460px; height: 294px;\"\/><br \/>\n\t\t\t\t\t\t<\/a><\/p>\n<p>L\u2019intelligence artificielle est omnipr\u00e9sente via l\u2019Al Meeting Agent qui permet<\/p>\n<p>La transcription audio en temps r\u00e9el.<\/p>\n<p>La r\u00e9daction automatique de comptes-rendus de r\u00e9union.<\/p>\n<p>La r\u00e9duction de bruit par empreinte vocale (Al Voiceprint).<\/p>\n<p>Des fonctions que j\u2019ai aper\u00e7ues, mais pas encore analys\u00e9es.<\/p>\n<p>Mais la v\u00e9ritable surprise vient de l\u2019interop\u00e9rabilit\u00e9 avec l\u2019\u00e9cosyst\u00e8me Apple. La MagicPad 4 peut servir d\u2019\u00e9cran \u00e9tendu sans fil pour un Mac, reconna\u00eetre enti\u00e8rement des AirPods et supporte nativement l\u2019\u00e9dition de documents Keynote, Pages et Numbers. Elle permet m\u00eame la sauvegarde directe sur iCloud, brisant ainsi les barri\u00e8res habituelles entre Android et les produits Apple.<\/p>\n<p>Tout un pan que j\u2019aurais bien aim\u00e9 tester, mais qui n\u2019est pas encore disponible. Pour l\u2019instant, \u00e7a m\u2019a juste \u00e9t\u00e9 pr\u00e9sent\u00e9 en amont. Utilisateur de Mac, iPhone et Airpods, j\u2019ai h\u00e2te de voir si \u00e7a tient la route parce que si c\u2019est le cas et que \u00e7a arrive aussi sur les smartphones Honor, \u00e7a faciliterait grandement ma bascule vers Android.<\/p>\n<p>&#13;<\/p>\n<p>Photo : le minimum syndical<\/p>\n<p>Comme souvent sur les tablettes de ce format, la partie photographique reste secondaire. On trouve un capteur arri\u00e8re de 13 M\u00e9gapixels (f\/2.0) avec autofocus. \u00c0 l\u2019avant, la cam\u00e9ra de 9 M\u00e9gapixels (f\/2.2) est optimis\u00e9e pour la visioconf\u00e9rence. Les clich\u00e9s sont corrects sous une bonne lumi\u00e8re, mais bien moins exploitables d\u00e8s que la luminosit\u00e9 baisse. C\u2019est suffisant pour scanner des documents via l\u2019IA int\u00e9gr\u00e9e, mais n\u2019esp\u00e9rez pas remplacer votre smartphone.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/honor-magicpad-4-5.jpg\" class=\"article-content__figure\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"904\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/honor-magicpad-4-5-1200x904.jpg\" alt=\"\" class=\"wp-image-2989461 wp-image\"  \/><\/a><\/p>\n<p>&#13;<\/p>\n<p>Audio \u00e0 8 HP<\/p>\n<p>Malgr\u00e9 sa finesse, la MagicPad 4 embarque huit haut-parleurs. Le rendu sonore est certifi\u00e9 IMAX Enhanced et DTS X:Ultra. La spatialisation audio IA d\u2019Honor offre une sc\u00e8ne sonore large, id\u00e9ale pour le visionnage de films. Les basses manquent forc\u00e9ment de profondeur \u00e0 cause du volume r\u00e9duit de la caisse de r\u00e9sonance, mais la clart\u00e9 des m\u00e9diums et des aigus est agr\u00e9ablement surprenante.<\/p>\n<p>&#13;<\/p>\n<p>R\u00e9seau et Communication : l\u2019arriv\u00e9e du Bluetooth 6.0<\/p>\n<p>La connectivit\u00e9 embarque ce qui se fait de mieux. On a donc du Wi-Fi 7, mais aussi du Bluetooth 6.0 qui fait son apparition sur ce mod\u00e8le. Pour le d\u00e9bit r\u00e9seau, j\u2019ai t\u00e9l\u00e9charg\u00e9 une saison enti\u00e8re de T\u00e9h\u00e9ran en \u00e0 peine quelques minutes, limite trop rapide. Le port USB-C est \u00e0 la norme 3.2 Gen1, permettant des transferts rapides et une sortie vid\u00e9o efficace.<\/p>\n<p>&#13;<\/p>\n<p>Autonomie : le sacrifice de la finesse ?<\/p>\n<p>On ne perd pas 1 mm d\u2019\u00e9paisseur sans le payer \u00e0 un moment ou \u00e0 un autre. Pour atteindre 4,8 mm d\u2019\u00e9paisseur, Honor a d\u00fb r\u00e9duire la capacit\u00e9 de la batterie \u00e0 10 100 mAh. \u00c0 titre de comparaison, la MagicPad 3, plus \u00e9paisse, embarquait 12 450 mAh.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/images.frandroid.com\/wp-content\/uploads\/2026\/02\/honor-magicpad-4-4.jpg\" class=\"article-content__figure\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"903\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/honor-magicpad-4-4-1200x903.jpg\" alt=\"\" class=\"wp-image-2989459 wp-image\"  \/><\/a><\/p>\n<p>Heureusement, le passage \u00e0 l\u2019Oled, l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique du Snapdragon 8 Gen 5 et les optimisations de MagicOS 10 permettent de tenir une journ\u00e9e de travail sans probl\u00e8me. Sur PCMark, on tient un peu plus de 8h. La lecture d\u2019un film de 2h30 n\u2019entame que de 11% la batterie, ce qui est dans la bonne moyenne. Surtout, la consommation en veille est quasi nulle. Une bonne nouvelle parce que je n\u2019ai pas le m\u00eame r\u00e9sultat avec une OnePlus Pad 3 par exemple.<\/p>\n<p>La charge rapide filaire de 66W permet de regagner rapidement des pourcentages, m\u00eame si l\u2019on aurait aim\u00e9 une puissance sup\u00e9rieure pour compenser la baisse de capacit\u00e9 brute.<\/p>\n<p>&#13;<\/p>\n<p>Prix et disponibilit\u00e9<\/p>\n<p>La MagicPad 4 est lanc\u00e9e ce 1er mars. Elle se d\u00e9cline en deux versions : <\/p>\n<p>MagicPad 4 12+256 Go \u00e0 699 euros<\/p>\n<p>MagicPad 4 16+512 Go \u00e0 799 euros<\/p>\n<p>&#13;<\/p>\n<p>Verdict<\/p>\n<p>Vous l\u2019aurez compris, mon bilan provisoire est tr\u00e8s positif. J\u2019aime vraiment utiliser cette tablette qui ne fait pas mal aux bras gr\u00e2ce \u00e0 son poids plume pour la diagonale qu\u2019elle offre. Le format est parfait \u00e0 mon sens et elle remplit son office sur tous les terrains. Enfin, presque. Oui, la photo est le parent pauvre comme toujours sur les tablettes. Mais pour le reste, c\u2019est carton plein. Je dois encore affiner mes tests, mais l\u2019ensemble est plus qu\u2019encourageant. Surtout, avoir une tablette aussi fine entre les mains est absolument grisant.<\/p>\n<p>    <a href=\"https:\/\/www.frandroid.com\/produits\/tablettes-tactiles\/honor\/2975519-honor-magicpad-4\" class=\"product-resume__prices-title__product-name has-text-weight-bold\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n    Honor MagicPad 4    <\/a><br \/>\n        au meilleur prix<\/p>\n<p class=\"has-text-weight-semibold has-text-centered has-text-body-lightest\">Il n\u2019y a pas d\u2019offres pour le moment, d\u00e9couvrez<\/p>\n","protected":false},"excerpt":{"rendered":"La Honor MagicPad 4 est la tablette la plus fine du monde, encore plus que l\u2019iPad Pro qui&hellip;\n","protected":false},"author":2,"featured_media":24362,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[12,13,18,17,13550,73,71,75,72,76,74],"class_list":{"0":"post-24361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sciences-et-technologies","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-honor-magicpad-4","13":"tag-science","14":"tag-science-and-technology","15":"tag-sciences","16":"tag-sciences-et-technologies","17":"tag-technologies","18":"tag-technology"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/24361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=24361"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/24361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/24362"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=24361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=24361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=24361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}