{"id":30369,"date":"2026-03-06T15:26:19","date_gmt":"2026-03-06T15:26:19","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/30369\/"},"modified":"2026-03-06T15:26:19","modified_gmt":"2026-03-06T15:26:19","slug":"eva-mendes-et-ryan-gosling-saffichent-ensemble-pour-la-premiere-fois-depuis-plus-de-10-ans","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/30369\/","title":{"rendered":"Eva Mendes et Ryan Gosling s\u2019affichent ensemble pour la premi\u00e8re fois depuis plus de 10\u00a0ans"},"content":{"rendered":"<p>        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/e97b84b_upload-1-g5mtft2ako0q-capture-d-ecran-2026-03-06-104024.png\"  width=\"728\" height=\"409\" alt=\"Voir Ryan Gsoling et Eva Mendes au m\u00eame endroit est particuli\u00e8rement rare, malgr\u00e9 leur union de longue date.\"\/>  <\/p>\n<p>Capture d\u2019\u00e9cran X<\/p>\n<p>Voir Ryan Gsoling et Eva Mendes au m\u00eame endroit est particuli\u00e8rement rare, malgr\u00e9 leur union de longue date.<\/p>\n<p class=\"asset asset-text\">C\u2019est l\u2019un des couples les plus glamours \u00e0 Hollywood, mais aussi l\u2019un des plus secrets. En solo, par contre, <a href=\"https:\/\/www.huffingtonpost.fr\/culture\/article\/ce-journaliste-americain-en-galere-a-du-interviewer-ryan-gosling-en-plein-milieu-du-desert_261101.html\" rel=\"nofollow noopener\" target=\"_blank\">Ryan Gosling est partout<\/a> \u00e0 l\u2019occasion de la sortie du film Projet Derni\u00e8re Chance, attendu le 18\u00a0mars prochain en France.<\/p>\n<p class=\"asset asset-text\">Tourn\u00e9e d\u2019interviews, <a href=\"https:\/\/www.huffingtonpost.fr\/international\/video\/ne-laissez-pas-obama-jouer-la-carte-iranienne-pour-se-faire-reelire-avertissait-trump-en-2012_260994.html\" rel=\"nofollow noopener\" target=\"_blank\">Saturday Night Live<\/a> et autres late-shows, l\u2019acteur canadien assure la promotion de son nouveau projet de science-fiction. Ce jeudi 5\u00a0mars, il s\u2019est donc assis sur le canap\u00e9 de Jimmy Fallon pour en parler. Un imp\u00e9ratif professionnel qui n\u2019a pas emp\u00each\u00e9 la star de vouloir c\u00e9l\u00e9brer comme il se doit l\u2019anniversaire de <a href=\"https:\/\/www.huffingtonpost.fr\/people\/article\/ryan-gosling-en-tournee-promo-pour-the-fall-guy-fait-discretement-la-promo-d-eva-mendes_233332.html\" rel=\"nofollow noopener\" target=\"_blank\">sa femme Eva Mendes<\/a>, n\u00e9e un 5\u00a0mars.<\/p>\n<p class=\"asset asset-text\">En tant qu\u2019invit\u00e9 du Tonight Show, <a href=\"https:\/\/www.huffingtonpost.fr\/culture\/article\/star-wars-starfighter-ou-waterworld-2-cette-photo-promo-de-ryan-gosling-a-de-quoi-nous-faire-douter_254989.html\" rel=\"nofollow noopener\" target=\"_blank\">Ryan Gosling<\/a> s\u2019est permis un petit \u00e9cart pour c\u00e9l\u00e9brer celle qu\u2019il a rencontr\u00e9 en 2011, lors du tournage de The Place Beyond The Pines et avec qui il a eu deux enfants.<\/p>\n<p class=\"asset asset-text\">En plateau, Ryan Gosling a d\u2019abord demand\u00e9 au public de lui souhaiter un joyeux anniversaire, sachant qu\u2019elle se trouvait quelque part dans les coulisses. Eva Mendes, l\u00e9g\u00e8rement g\u00ean\u00e9e mais toujours souriante, a alors \u00e9t\u00e9 invit\u00e9e \u00e0 rejoindre le plateau o\u00f9 elle a retrouv\u00e9 son compagnon. \u00ab\u00a0Vous risquez de me retrouver demain dans l\u2019Hudson (River)\u00a0\u00bb, a gliss\u00e9 le com\u00e9dien, bien conscient du naturel discret de celle qui partage sa vie.<\/p>\n<p> La lecture de ce contenu est susceptible d\u2019entra\u00eener un d\u00e9p\u00f4t de cookies de la part de l\u2019op\u00e9rateur tiers qui l\u2019h\u00e9berge. Compte-tenu des choix que vous avez exprim\u00e9s en mati\u00e8re de d\u00e9p\u00f4t de cookies, nous avons bloqu\u00e9 l\u2019affichage de ce contenu. Si vous souhaitez y acc\u00e9der, vous devez accepter la cat\u00e9gorie de cookies \u201cContenus tiers\u201d en cliquant sur le bouton ci-dessous. <\/p>\n<p> Lire la Vid\u00e9o        <\/p>\n<p class=\"asset asset-text\">Il l\u2019a alors introduite au public pr\u00e9sent ce soir-l\u00e0, qui avait la particularit\u00e9 d\u2019\u00eatre uniquement compos\u00e9 d\u2019enseignants. Un clin d\u2019\u0153il au m\u00e9tier du personnage de Ryan Gosling dans Projet Derni\u00e8re Chance. Pour ses premiers mots, Eva Mendes a souhait\u00e9 saluer le travail des enseignants. Pendant ce temps, <a href=\"https:\/\/www.huffingtonpost.fr\/medias\/article\/menace-par-donald-trump-jimmy-fallon-lui-repond-avec-une-fausse-pluie-de-compliments_255011.html\" rel=\"nofollow noopener\" target=\"_blank\">Jimmy Fallon<\/a> tirait le plus possible son micro pour qu\u2019elle soit audible.<\/p>\n<p class=\"asset asset-text\">\u00ab\u00a0Vous allez couper tout \u00e7a, n\u2019est-ce pas\u00a0?\u00a0\u00bb, a-t-elle d\u2019ailleurs lanc\u00e9. La r\u00e9ponse de Jimmy Fallon\u00a0? \u00ab\u00a0Non\u00a0\u00bb. Il faut dire que le c\u00e9l\u00e8bre animateur \u00e9tait bien conscient de tenir une s\u00e9quence rare puisque Ryan Gosling et Eva Mendes n\u2019avaient pas \u00e9t\u00e9 vus ensemble, publiquement, depuis plus de dix ans.<\/p>\n<p>    \u00ab\u00a0Happy Birthday\u00a0Eva Mendes\u00a0\u00bb    <\/p>\n<p class=\"asset asset-text\">\u00ab\u00a0C\u2019est votre anniversaire\u00a0!\u00a0\u00bb, lui a alors rappel\u00e9 Jimmy Fallon, r\u00e9v\u00e9lant la surprise pr\u00e9par\u00e9e par Ryan Gosling. Car la fanfare du lyc\u00e9e North Bergen, dans le New Jersey, est apparue dans le dos de l\u2019actrice avec une banderole \u00ab\u00a0Joyeux anniversaire Eva\u00a0\u00bb.<\/p>\n<p class=\"asset asset-text\">Aussi hilare que g\u00ean\u00e9e, Eva Mendes a savour\u00e9 ce moment musical avant d\u2019apprendre que tout avait \u00e9t\u00e9 organis\u00e9 par Ryan Gosling. \u00ab\u00a0C\u2019est gr\u00e2ce \u00e0 lui\u00a0\u00bb, a m\u00eame gliss\u00e9 Jimmy Fallon. Eva Mendes s\u2019est donc tourn\u00e9e vers lui pour l\u2019embrasser tendrement sur la joue mais en toute discr\u00e9tion. Un moment particuli\u00e8rement rare puisqu\u2019en dehors des avant-premi\u00e8res du film de Derek Cianfrance en 2012 et 2013, le couple s\u2019est toujours abstenu de toute apparition publique officielle.<\/p>\n<p>         <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/03\/caf0e2f_upload-1-ertemdael38p-afp-20240820-151470439-v4-highres-theplacebeyondthepinespremiere2012to.jpeg\"  width=\"728\" height=\"517\" alt=\"Eva Mendes and Ryan Gosling lors de la pr\u00e9sentation du film \u00ab\u00a0The Place Beyond The Pines\u00a0\u00bb au Toronto International Film Festival en septembre 2012.\"\/>  <\/p>\n<p>SONIA RECCHIA \/ Getty Images via AFP<\/p>\n<p>Eva Mendes and Ryan Gosling lors de la pr\u00e9sentation du film \u00ab\u00a0The Place Beyond The Pines\u00a0\u00bb au Toronto International Film Festival en septembre 2012.<\/p>\n<p class=\"asset asset-text\">Il aura d\u2019ailleurs fallu attendre 2022\u00a0pour qu\u2019Eva Mendes commence \u00e0 parler publiquement de Ryan Gosling en le pr\u00e9sentant comme son mari. Elle avait alors confirm\u00e9 qu\u2019ils s\u2019\u00e9taient mari\u00e9s dans le plus grand secret, sans rien r\u00e9v\u00e9ler de plus. Et \u00e0 chaque fois que l\u2019actrice est interrog\u00e9e sur sa vie priv\u00e9e, elle rappelle poliment qu\u2019elle n\u2019est pas \u00e0 l\u2019aise avec ce sujet, qu\u2019elle veut conserver une part de myst\u00e8re et ne souhaite donc pas exposer sa vie priv\u00e9e avec son mari et <a href=\"https:\/\/www.huffingtonpost.fr\/life\/article\/eva-mendes-n-aurait-pas-pu-elever-des-enfants-avant-d-avoir-40-ans_233424.html\" rel=\"nofollow noopener\" target=\"_blank\">leurs deux filles Esmeralda et Amada<\/a>, respectivement n\u00e9es en 2014 et 2016. Ryan Gosling a visiblement fait une toute petite entorse \u00e0 cette r\u00e8gle \u00e0 l\u2019occasion de son 52e anniversaire.<\/p>\n","protected":false},"excerpt":{"rendered":"Capture d\u2019\u00e9cran X Voir Ryan Gsoling et Eva Mendes au m\u00eame endroit est particuli\u00e8rement rare, malgr\u00e9 leur union&hellip;\n","protected":false},"author":2,"featured_media":30370,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[12,13,18,17,129,128,133,419,96,95,16185,14702,109,16184],"class_list":{"0":"post-30369","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-celebrities","13":"tag-celebrity","14":"tag-cinema","15":"tag-culture","16":"tag-divertissement","17":"tag-entertainment","18":"tag-eva-mendes","19":"tag-jimmy-fallon","20":"tag-people","21":"tag-ryan-gosling"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116182934142375472","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/30369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=30369"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/30369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/30370"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=30369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=30369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=30369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}